{"id":341825,"date":"2025-05-20T16:10:44","date_gmt":"2025-05-20T14:10:44","guid":{"rendered":"https:\/\/dutchhealthstore.com\/product\/serum-spray\/"},"modified":"2025-10-10T09:51:10","modified_gmt":"2025-10-10T07:51:10","slug":"serum-spray","status":"publish","type":"product","link":"https:\/\/dutchhealthstore.com\/nl\/product\/serum-spray\/","title":{"rendered":"Serum Spray"},"content":{"rendered":"<p class=\"\" data-start=\"258\" data-end=\"507\">Als styling must-have verzacht het pluizig haar, definieert het krullen en golven, temt het springerig haar en biedt het bescherming tegen hitte &#8211; en dat alles zonder vettige resten of stijfheid achter te laten. De gewichtloze formule trekt gemakkelijk in het haar voor een natuurlijke, zachte finish.<\/p>\n<p class=\"\" data-start=\"509\" data-end=\"680\">Als hoofdhuidbehandeling brengt <strong data-start=\"531\" data-end=\"546\">Serum Spray<\/strong> krachtige plantaardige voedingsstoffen rechtstreeks naar de wortels om de hoofdhuid nieuwe energie te geven en een gezondere, sterkere haargroei te ondersteunen.<\/p>\n<p class=\"\" data-start=\"682\" data-end=\"764\">Perfect voor alle haartypes, texturen en condities, inclusief gekleurd haar.<\/p>\n<p class=\"\" data-start=\"766\" data-end=\"820\">Vrij van siliconen en quaternaire ammoniumverbindingen.<\/p>\n<p data-start=\"766\" data-end=\"820\"><strong>Inhoud: 120 ml  <\/strong><\/p>\n<h3 data-start=\"766\" data-end=\"820\">Hoe te gebruiken<\/h3>\n<p>Spray op handdoekdroog haar en verdeel gelijkmatig om pluizen te verminderen, textuur glad te maken, je natuurlijke style te verzachten en te verbeteren. Of je nu een f\u00f6hn, een f\u00f6hn met een ronde borstel of aan de lucht droogt, het product verbetert alle kapsels door natuurlijke definitie toe te voegen, kroes te temmen, te verzachten en de glans te herstellen.<\/p>\n<h2 data-start=\"766\" data-end=\"820\"><strong>Natuurlijke \/ biologische Ingredi\u00ebnten <\/strong><\/h2>\n<div class=\"product-ingredient-wrapper\">\n<p>*Alo\u00eb Vera Bladsap, Water, \u2020Marula Zaad Olie, Hennepzaad Olie, *Camelina Zaad Olie, *Baobab Olie, *Tahitiaanse Tamanu Zaad Olie, *Argan Kernel Olie, *Lijfvrucht Olie, *Doorn Olie, *Oregano Extract, *Calendula Extract, *Chamille Extract, *Thyme-extract, *Neembladextract, *Bhringraj-extract, \u00a7Xanthaangom, *Guar Gom, Kaliumsorbaat, \u2020Sinaasappelschilolie Uitgedrukt, \u2020Lavendelextract, \u2020Rosemary Leaf Oil, \u2020Litsea Cubeba Fruit Oil, \u2020Ylang Ylang Flower Oil.<\/p>\n<\/div>\n<div class=\"product-ingredient-info\">\n<p>*GECERTIFICEERD BIOLOGISCH<\/p>\n<p>\u2020BIOLOGISCH<\/p>\n<p>\u00a7 NON-GMO PLANTAARDIG<\/p>\n<\/div>\n<div class=\"product-ingredient-bottom-wrapper\">\n<p>\u00a7 NIET-GMO PLANTAARDIG<\/p>\n<p>Geen dierproeven<\/p>\n<p>Gemaakt in de VS<\/p>\n<p>We vermelden niet de verdeling van de natuurlijke essenti\u00eble oliebestanddelen zoals vermeld op productdozen of flessen op onze website. Deze lijst met mogelijke allergenen staat op productdozen of -flessen omdat deze alleen verplicht is voor verkoop in de Europese Unie. Ter informatie: dit zijn bestanddelen van natuurlijke essenti\u00eble oli\u00ebn op onze productdozen. Het zijn geen synthetische isolaten die aan de formules zijn toegevoegd, ze zitten al in de essenti\u00eble oli\u00ebn die in de producten zitten. De EU vereist dat deze bestanddelen apart worden vermeld op productverpakkingen, wat verwarrend kan zijn.<\/p>\n\n\t<section class=\"section\" id=\"section_1756811589\">\n\t\t<div class=\"section-bg fill\" >\n\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"1920\" height=\"1080\" src=\"https:\/\/dutchhealthstore.com\/wp-content\/uploads\/2020\/10\/01-achtergrond-schaduw.jpg\" class=\"bg attachment-original size-original\" alt=\"\" \/>\t\t\t\t\t\t<div class=\"section-bg-overlay absolute fill\"><\/div>\n\t\t\t\n\t<div class=\"is-border\"\n\t\tstyle=\"border-color:rgba(202, 202, 202, 0.87);border-width:1px 1px 1px 1;\">\n\t<\/div>\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_193713573\">\n\t\t<a class=\"\" href=\"https:\/\/dutchhealthstore.com\/nl\/product-category\/merken\/josh-rosebrook-nl\/\" >\t\t\t\t\t\t<div class=\"img-inner image-cover dark\" style=\"padding-top:13%;\">\n\t\t\t<img decoding=\"async\" width=\"996\" height=\"133\" src=\"https:\/\/dutchhealthstore.com\/wp-content\/uploads\/2020\/09\/banner-template-brand-blockinnate.jpg\" class=\"attachment-original size-original\" alt=\"josh-rosebrook-brand-block-banner\" srcset=\"https:\/\/dutchhealthstore.com\/wp-content\/uploads\/2020\/09\/banner-template-brand-blockinnate.jpg 996w, https:\/\/dutchhealthstore.com\/wp-content\/uploads\/2020\/09\/banner-template-brand-blockinnate-800x107.jpg 800w, https:\/\/dutchhealthstore.com\/wp-content\/uploads\/2020\/09\/banner-template-brand-blockinnate-768x103.jpg 768w, https:\/\/dutchhealthstore.com\/wp-content\/uploads\/2020\/09\/banner-template-brand-blockinnate-530x71.jpg 530w, https:\/\/dutchhealthstore.com\/wp-content\/uploads\/2020\/09\/banner-template-brand-blockinnate-64x9.jpg 64w\" sizes=\"(max-width: 996px) 100vw, 996px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/a>\t\t\n<style>\n#image_193713573 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\n\t<div id=\"text-3757903175\" class=\"text hidden\">\n\t\t\n\n<h2 class=\"thin-font\">Meer over het merk<\/h2>\n\t\t\t<\/div>\n\t\n<div class=\"row\"  id=\"row-1889784288\">\n\n\n\t<div id=\"col-705353609\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\t<div id=\"gap-1725581185\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-1725581185 {\n  padding-top: 30px;\n}\n<\/style>\n\t<\/div>\n\t\n\n\n\t\t<div class=\"tabbed-content tabsbrandblock\">\n\t\t\t\n\t\t\t<ul class=\"nav nav-line nav-vertical nav-normal nav-size-small nav-left\" role=\"tablist\"><li id=\"tab-over-jos\" class=\"tab active has-icon\" role=\"presentation\"><a href=\"#tab_over-jos\" role=\"tab\" aria-selected=\"true\" aria-controls=\"tab_over-jos\"><span>Over Jos<\/span><\/a><\/li>\n<li id=\"tab-ingredi\u00ebnten\" class=\"tab has-icon\" role=\"presentation\"><a href=\"#tab_ingredi\u00ebnten\" tabindex=\"-1\" role=\"tab\" aria-selected=\"false\" aria-controls=\"tab_ingredi\u00ebnten\"><span>Ingredi\u00ebnten<\/span><\/a><\/li>\n<li id=\"tab-milieu-impact\" class=\"tab has-icon\" role=\"presentation\"><a href=\"#tab_milieu-impact\" tabindex=\"-1\" role=\"tab\" aria-selected=\"false\" aria-controls=\"tab_milieu-impact\"><span>Milieu-impact<\/span><\/a><\/li>\n<li id=\"tab-het-verschil-tussen-een-hydraterende-en-hydraterende-huid\" class=\"tab has-icon\" role=\"presentation\"><a href=\"#tab_het-verschil-tussen-een-hydraterende-en-hydraterende-huid\" tabindex=\"-1\" role=\"tab\" aria-selected=\"false\" aria-controls=\"tab_het-verschil-tussen-een-hydraterende-en-hydraterende-huid\"><span>Het verschil tussen een hydraterende en hydraterende huid<\/span><\/a><\/li>\n<li id=\"tab-weg-met-de-ontsteking,-omhoog-met-de-informatie\" class=\"tab has-icon\" role=\"presentation\"><a href=\"#tab_weg-met-de-ontsteking,-omhoog-met-de-informatie\" tabindex=\"-1\" role=\"tab\" aria-selected=\"false\" aria-controls=\"tab_weg-met-de-ontsteking,-omhoog-met-de-informatie\"><span>Weg met de ontsteking, omhoog met de informatie<\/span><\/a><\/li>\n<li id=\"tab-faq\" class=\"tab has-icon\" role=\"presentation\"><a href=\"#tab_faq\" tabindex=\"-1\" role=\"tab\" aria-selected=\"false\" aria-controls=\"tab_faq\"><span>FAQ<\/span><\/a><\/li><\/ul><div class=\"tab-panels\"><div id=\"tab_over-jos\" class=\"panel active entry-content\" role=\"tabpanel\" aria-labelledby=\"tab-over-jos\">\n\n<div class=\"row\"  id=\"row-645434310\">\n\n\n\t<div id=\"col-654468212\" class=\"col medium-8 small-12 large-8\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n<h3 class=\"thin-font\"><span style=\"color: #333333;\">Over Josh Rosebrook<\/span><\/h3>\n<p>\"Echte schoonheid is een manier van leven, een manier om van jezelf te houden''. Ik opende mijn eerste salon in Portland, Oregon, toen ik 10 jaar oud was. Ik vond een antieke kappersstoel in onze kelder en was al snel bezig met het stylen en fixeren van het haar van alle kinderen in de buurt. Het kwam als vanzelf in me op; ik wist instinctief hoe ik hun haar moest knippen en stylen om ze de look te geven die ze wilden.<\/p>\n<p><a href=\"\/?p=99416\"><strong>Lees verder<\/strong><\/a><\/p>\n<p> <\/p>\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-1282057374\" class=\"col medium-4 small-12 large-4\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_2032921060\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner image-cover dark\" style=\"padding-top:80%;\">\n\t\t\t<img decoding=\"async\" width=\"534\" height=\"800\" src=\"https:\/\/dutchhealthstore.com\/wp-content\/uploads\/2020\/09\/Josh-3-534x800.jpg\" class=\"attachment-large size-large\" alt=\"Josh Rosebrook Ingredients\" srcset=\"https:\/\/dutchhealthstore.com\/wp-content\/uploads\/2020\/09\/Josh-3-534x800.jpg 534w, https:\/\/dutchhealthstore.com\/wp-content\/uploads\/2020\/09\/Josh-3-scaled-510x764.jpg 510w, https:\/\/dutchhealthstore.com\/wp-content\/uploads\/2020\/09\/Josh-3-267x400.jpg 267w, https:\/\/dutchhealthstore.com\/wp-content\/uploads\/2020\/09\/Josh-3-768x1151.jpg 768w, https:\/\/dutchhealthstore.com\/wp-content\/uploads\/2020\/09\/Josh-3-1025x1536.jpg 1025w, https:\/\/dutchhealthstore.com\/wp-content\/uploads\/2020\/09\/Josh-3-1367x2048.jpg 1367w, https:\/\/dutchhealthstore.com\/wp-content\/uploads\/2020\/09\/Josh-3-scaled.jpg 1709w\" sizes=\"(max-width: 534px) 100vw, 534px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_2032921060 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\n<style>\n#row-645434310 > .col > .col-inner {\n  padding: 19px 0px 0px 0px;\n}\n<\/style>\n<\/div>\n\n<\/div>\n<div id=\"tab_ingredi\u00ebnten\" class=\"panel entry-content\" role=\"tabpanel\" aria-labelledby=\"tab-ingredi\u00ebnten\">\n\n<div class=\"row\"  id=\"row-148877540\">\n\n\n\t<div id=\"col-771803397\" class=\"col medium-8 small-12 large-8\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n<h3 class=\"thin-font\"><span style=\"color: #333333;\">Ingredi\u00ebnten<\/span><\/h3>\n<p>We doen er alles aan om de hoogste kwaliteit, gecertificeerde biologische, biologische en in het wild vervaardigde ingredi\u00ebnten te vinden die beschikbaar zijn. We hebben sterke, langdurige relaties opgebouwd met onze leveranciers om ervoor te zorgen dat onze Ingredi\u00ebnten voldoen aan onze compromisloze normen, ethiek en duurzaamheid.<\/p>\n<p><a class=\"thin-font\" href=\"\/?p=133876\"><strong>Lees verder<\/strong><\/a><\/p>\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-678555531\" class=\"col medium-4 small-12 large-4\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_1587609696\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner image-cover dark\" style=\"padding-top:80%;\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1020\" height=\"579\" src=\"https:\/\/dutchhealthstore.com\/wp-content\/uploads\/2020\/03\/Josh-Rosebrook-Synergie.jpg\" class=\"attachment-large size-large\" alt=\"Josh Rosebrook - Synergie\" srcset=\"https:\/\/dutchhealthstore.com\/wp-content\/uploads\/2020\/03\/Josh-Rosebrook-Synergie.jpg 1268w, https:\/\/dutchhealthstore.com\/wp-content\/uploads\/2020\/03\/Josh-Rosebrook-Synergie-510x290.jpg 510w, https:\/\/dutchhealthstore.com\/wp-content\/uploads\/2020\/03\/Josh-Rosebrook-Synergie-704x400.jpg 704w, https:\/\/dutchhealthstore.com\/wp-content\/uploads\/2020\/03\/Josh-Rosebrook-Synergie-768x436.jpg 768w\" sizes=\"(max-width: 1020px) 100vw, 1020px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_1587609696 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\n<style>\n#row-148877540 > .col > .col-inner {\n  padding: 19px 0px 0px 0px;\n}\n<\/style>\n<\/div>\n\n<\/div>\n<div id=\"tab_milieu-impact\" class=\"panel entry-content\" role=\"tabpanel\" aria-labelledby=\"tab-milieu-impact\">\n\n<div class=\"row\"  id=\"row-1421441081\">\n\n\n\t<div id=\"col-1422036051\" class=\"col medium-8 small-12 large-8\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n<h3 class=\"thin-font\">Milieu-impact<\/h3>\n<p>Een kernonderdeel van onze missie als een bewust natuurlijke schoonheidsbedrijf is onze impact op het milieu. We zijn altijd op zoek naar manieren om onze ecologische voetafdruk te verkleinen, ons milieu te beschermen en te gedijen als de meest ecologisch duurzame onderneming die mogelijk is.<\/p>\n<p><a class=\"thin-font\" href=\"\/?product_cat=josh-rosebrook-nl\"><strong>Lees verder<\/strong><\/a><\/p>\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-641988926\" class=\"col medium-4 small-12 large-4\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_646709372\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner image-cover dark\" style=\"padding-top:80%;\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"827\" height=\"800\" src=\"https:\/\/dutchhealthstore.com\/wp-content\/uploads\/2020\/03\/Josh-Rosewood-Packaging-1-827x800.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/dutchhealthstore.com\/wp-content\/uploads\/2020\/03\/Josh-Rosewood-Packaging-1-827x800.jpg 827w, https:\/\/dutchhealthstore.com\/wp-content\/uploads\/2020\/03\/Josh-Rosewood-Packaging-1-510x493.jpg 510w, https:\/\/dutchhealthstore.com\/wp-content\/uploads\/2020\/03\/Josh-Rosewood-Packaging-1-413x400.jpg 413w, https:\/\/dutchhealthstore.com\/wp-content\/uploads\/2020\/03\/Josh-Rosewood-Packaging-1-768x743.jpg 768w, https:\/\/dutchhealthstore.com\/wp-content\/uploads\/2020\/03\/Josh-Rosewood-Packaging-1-32x32.jpg 32w, https:\/\/dutchhealthstore.com\/wp-content\/uploads\/2020\/03\/Josh-Rosewood-Packaging-1.jpg 1200w\" sizes=\"(max-width: 827px) 100vw, 827px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_646709372 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\n<style>\n#row-1421441081 > .col > .col-inner {\n  padding: 19px 0px 0px 0px;\n}\n<\/style>\n<\/div>\n\n<\/div>\n<div id=\"tab_het-verschil-tussen-een-hydraterende-en-hydraterende-huid\" class=\"panel entry-content\" role=\"tabpanel\" aria-labelledby=\"tab-het-verschil-tussen-een-hydraterende-en-hydraterende-huid\">\n\n<div class=\"row\"  id=\"row-909910702\">\n\n\n\t<div id=\"col-442699338\" class=\"col medium-8 small-12 large-8\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n<h3 class=\"thin-font\">Het verschil tussen een hydraterende en hydraterende huid<\/h3>\n<p>Helaas is er geen enkele cr\u00e8me of serum die alles zal doen wat nodig is voor een optimale gezondheid van uw huid. Je beste huid krijg je niet door \u00e9\u00e9n 'wonder'-product een paar maanden te gebruiken. Zo werkt het gewoon niet. Iemand die zich inzet om de achteruitgang en veroudering van de huid te vertragen, zal voortdurend investeren in producten voor een eenvoudige routine <i>en<\/i> de tijd die nodig is om het vitale orgaan te onderhouden en te behandelen. Dit vereist het regelmatig uitvoeren van individuele stappen, elke dag, elke week, jarenlang.<\/p>\n<p><a class=\"thin-font\" href=\"\/?p=100170\"> <strong>Lees verder<\/strong><\/a><\/p>\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-1692001132\" class=\"col medium-4 small-12 large-4\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_696441182\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner image-cover dark\" style=\"padding-top:80%;\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"480\" height=\"480\" src=\"https:\/\/dutchhealthstore.com\/wp-content\/uploads\/2020\/05\/Hydrating-Accelerator.jpg\" class=\"attachment-large size-large\" alt=\"Hydrating Accelerator\" srcset=\"https:\/\/dutchhealthstore.com\/wp-content\/uploads\/2020\/05\/Hydrating-Accelerator.jpg 480w, https:\/\/dutchhealthstore.com\/wp-content\/uploads\/2020\/05\/Hydrating-Accelerator-100x100.jpg 100w, https:\/\/dutchhealthstore.com\/wp-content\/uploads\/2020\/05\/Hydrating-Accelerator-400x400.jpg 400w, https:\/\/dutchhealthstore.com\/wp-content\/uploads\/2020\/05\/Hydrating-Accelerator-280x280.jpg 280w, https:\/\/dutchhealthstore.com\/wp-content\/uploads\/2020\/05\/Hydrating-Accelerator-150x150.jpg 150w, https:\/\/dutchhealthstore.com\/wp-content\/uploads\/2020\/05\/Hydrating-Accelerator-32x32.jpg 32w\" sizes=\"(max-width: 480px) 100vw, 480px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_696441182 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\n<style>\n#row-909910702 > .col > .col-inner {\n  padding: 19px 0px 0px 0px;\n}\n<\/style>\n<\/div>\n\n<\/div>\n<div id=\"tab_weg-met-de-ontsteking,-omhoog-met-de-informatie\" class=\"panel entry-content\" role=\"tabpanel\" aria-labelledby=\"tab-weg-met-de-ontsteking,-omhoog-met-de-informatie\">\n\n<div class=\"row\"  id=\"row-292306245\">\n\n\n\t<div id=\"col-1106292457\" class=\"col medium-8 small-12 large-8\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n<h3 class=\"thin-font\">Weg met de ontsteking, omhoog met de informatie<\/h3>\n<p>In deze post gaan we in op ontstekingsvermindering en de kruiden die werden gekozen op basis van hun op bewijs gebaseerde actuele voordelen. Dus wat is een ontsteking? Nou, het is multifactorieel en gecompliceerd (hey, wat niet als het om ons lichaam gaat!). Hier volgt een eenvoudige benadering om verschillende soorten ontstekingen te herkennen, hoewel we ons op de huid zullen richten omdat dat onze expertise is.<\/p>\n<p><a class=\"thin-font\" href=\"\/?p=134084\"><strong>Lees verder<\/strong><\/a><\/p>\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-665724159\" class=\"col medium-4 small-12 large-4\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_82152394\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner image-cover dark\" style=\"padding-top:80%;\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1020\" height=\"596\" src=\"https:\/\/dutchhealthstore.com\/wp-content\/uploads\/2020\/09\/josh-rosebrook-dutch-health-store-1369x800.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/dutchhealthstore.com\/wp-content\/uploads\/2020\/09\/josh-rosebrook-dutch-health-store-1369x800.jpg 1369w, https:\/\/dutchhealthstore.com\/wp-content\/uploads\/2020\/09\/josh-rosebrook-dutch-health-store-510x298.jpg 510w, https:\/\/dutchhealthstore.com\/wp-content\/uploads\/2020\/09\/josh-rosebrook-dutch-health-store-684x400.jpg 684w, https:\/\/dutchhealthstore.com\/wp-content\/uploads\/2020\/09\/josh-rosebrook-dutch-health-store-768x449.jpg 768w, https:\/\/dutchhealthstore.com\/wp-content\/uploads\/2020\/09\/josh-rosebrook-dutch-health-store-1536x898.jpg 1536w, https:\/\/dutchhealthstore.com\/wp-content\/uploads\/2020\/09\/josh-rosebrook-dutch-health-store-2048x1197.jpg 2048w\" sizes=\"(max-width: 1020px) 100vw, 1020px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_82152394 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\n<style>\n#row-292306245 > .col > .col-inner {\n  padding: 19px 0px 0px 0px;\n}\n<\/style>\n<\/div>\n\n<\/div>\n<div id=\"tab_faq\" class=\"panel entry-content\" role=\"tabpanel\" aria-labelledby=\"tab-faq\">\n\n<div class=\"row\"  id=\"row-1831999742\">\n\n\n\t<div id=\"col-1928371268\" class=\"col medium-8 small-12 large-8\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n<h3 class=\"thin-font\"><span style=\"color: #333333;\">FAQ<\/span><\/h3>\n<div class=\"accordion\">\n\n\t<div id=\"accordion-3413895662\" class=\"accordion-item\">\n\t\t<a id=\"accordion-3413895662-label\" class=\"accordion-title plain\" href=\"#accordion-item-zijn-de-producten-van-josh-rosebrook-wreedheidvrij-en-veganistisch?\" aria-expanded=\"false\" aria-controls=\"accordion-3413895662-content\">\n\t\t\t<button class=\"toggle\" aria-label=\"Toggle\"><i class=\"icon-angle-down\" aria-hidden=\"true\"><\/i><\/button>\n\t\t\t<span>Zijn de producten van Josh Rosebrook wreedheidvrij en veganistisch?<\/span>\n\t\t<\/a>\n\t\t<div id=\"accordion-3413895662-content\" class=\"accordion-inner\" aria-labelledby=\"accordion-3413895662-label\">\n\t\t\t\n\n<p>Ja, alle producten van Josh Rosebrook zijn cruelty-free en veganistisch.<\/p>\n\n\t\t<\/div>\n\t<\/div>\n\t\n\t<div id=\"accordion-2117686797\" class=\"accordion-item\">\n\t\t<a id=\"accordion-2117686797-label\" class=\"accordion-title plain\" href=\"#accordion-item-voor-welke-huidtypes-zijn-de-producten-van-josh-rosebrook-geschikt?\" aria-expanded=\"false\" aria-controls=\"accordion-2117686797-content\">\n\t\t\t<button class=\"toggle\" aria-label=\"Toggle\"><i class=\"icon-angle-down\" aria-hidden=\"true\"><\/i><\/button>\n\t\t\t<span>Voor welke huidtypes zijn de producten van Josh Rosebrook geschikt?<\/span>\n\t\t<\/a>\n\t\t<div id=\"accordion-2117686797-content\" class=\"accordion-inner\" aria-labelledby=\"accordion-2117686797-label\">\n\t\t\t\n\n<p>Josh Rosebrook biedt producten voor verschillende huidtypes, waaronder de gevoelige, droge, vette en gecombineerde huid. Door hun focus op zachte, voedende ingredi\u00ebnten zijn ze geschikt voor veel mensen.<\/p>\n\n\t\t<\/div>\n\t<\/div>\n\t\n\t<div id=\"accordion-2416267459\" class=\"accordion-item\">\n\t\t<a id=\"accordion-2416267459-label\" class=\"accordion-title plain\" href=\"#accordion-item-bevatten-de-producten-van-josh-rosebrook-essenti\u00eble-oli\u00ebn?\" aria-expanded=\"false\" aria-controls=\"accordion-2416267459-content\">\n\t\t\t<button class=\"toggle\" aria-label=\"Toggle\"><i class=\"icon-angle-down\" aria-hidden=\"true\"><\/i><\/button>\n\t\t\t<span>Bevatten de producten van Josh Rosebrook essenti\u00eble oli\u00ebn?<\/span>\n\t\t<\/a>\n\t\t<div id=\"accordion-2416267459-content\" class=\"accordion-inner\" aria-labelledby=\"accordion-2416267459-label\">\n\t\t\t\n\n<p>Hoewel sommige Josh Rosebrook producten essenti\u00eble oli\u00ebn bevatten, worden deze zorgvuldig geselecteerd en in lage concentraties gebruikt om het risico op irritatie te minimaliseren. Het merk biedt ook geurvrije opties.<\/p>\n\n\t\t<\/div>\n\t<\/div>\n\t\n\t<div id=\"accordion-2624389042\" class=\"accordion-item\">\n\t\t<a id=\"accordion-2624389042-label\" class=\"accordion-title plain\" href=\"#accordion-item-wat-is-de-aanbevolen-huidverzorgingsroutine-met-josh-rosebrook-producten?\" aria-expanded=\"false\" aria-controls=\"accordion-2624389042-content\">\n\t\t\t<button class=\"toggle\" aria-label=\"Toggle\"><i class=\"icon-angle-down\" aria-hidden=\"true\"><\/i><\/button>\n\t\t\t<span>Wat is de aanbevolen huidverzorgingsroutine met Josh Rosebrook producten?<\/span>\n\t\t<\/a>\n\t\t<div id=\"accordion-2624389042-content\" class=\"accordion-inner\" aria-labelledby=\"accordion-2624389042-label\">\n\t\t\t\n\n<p>Een basisroutine van Josh Rosebrook bestaat meestal uit het reinigen, tonifi\u00ebren, hydrateren en beschermen van de huid. De specifieke producten die worden gebruikt, zijn afhankelijk van je huidtype en huidproblemen.<\/p>\n\n\t\t<\/div>\n\t<\/div>\n\t\n\n<\/div>\n\t<div id=\"gap-25650005\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-25650005 {\n  padding-top: 20px;\n}\n<\/style>\n\t<\/div>\n\t\n\n<p>Klik hieronder om contact met ons op te nemen voor verdere vragen:<\/p>\n<a href=\"https:\/\/dutchhealthstore.com\/contact-us\/\" class=\"button white\" >\n\t\t<span>Neem contact met ons op<\/span>\n\t<\/a>\n\n\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-780410701\" class=\"col medium-4 small-12 large-4\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_1021316430\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner image-cover dark\" style=\"padding-top:80%;\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"526\" height=\"526\" src=\"https:\/\/dutchhealthstore.com\/wp-content\/uploads\/2024\/05\/josh-rosebrook-discover-hydration-kit-1.jpg\" class=\"attachment-large size-large\" alt=\"josh-rosebrook-discover-hydration-kit-1\" srcset=\"https:\/\/dutchhealthstore.com\/wp-content\/uploads\/2024\/05\/josh-rosebrook-discover-hydration-kit-1.jpg 526w, https:\/\/dutchhealthstore.com\/wp-content\/uploads\/2024\/05\/josh-rosebrook-discover-hydration-kit-1-247x247.jpg 247w, https:\/\/dutchhealthstore.com\/wp-content\/uploads\/2024\/05\/josh-rosebrook-discover-hydration-kit-1-100x100.jpg 100w, https:\/\/dutchhealthstore.com\/wp-content\/uploads\/2024\/05\/josh-rosebrook-discover-hydration-kit-1-64x64.jpg 64w, https:\/\/dutchhealthstore.com\/wp-content\/uploads\/2024\/05\/josh-rosebrook-discover-hydration-kit-1-400x400.jpg 400w, https:\/\/dutchhealthstore.com\/wp-content\/uploads\/2024\/05\/josh-rosebrook-discover-hydration-kit-1-280x280.jpg 280w, https:\/\/dutchhealthstore.com\/wp-content\/uploads\/2024\/05\/josh-rosebrook-discover-hydration-kit-1-510x510.jpg 510w\" sizes=\"(max-width: 526px) 100vw, 526px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_1021316430 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\n<style>\n#row-1831999742 > .col > .col-inner {\n  padding: 19px 0px 0px 0px;\n}\n<\/style>\n<\/div>\n\n<\/div><\/div><\/div>\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n<\/div>\n\n\t\t<\/div>\n\n\t\t\n<style>\n#section_1756811589 {\n  padding-top: 30px;\n  padding-bottom: 30px;\n}\n#section_1756811589 .section-bg-overlay {\n  background-color: rgba(255, 255, 255, 0.86);\n}\n<\/style>\n\t<\/section>\n\t\n\n\t<section class=\"section\" id=\"section_1859624629\">\n\t\t<div class=\"section-bg fill\" >\n\t\t\t\t\t\t\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n\n\t<div id=\"gap-612152373\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-612152373 {\n  padding-top: 30px;\n}\n<\/style>\n\t<\/div>\n\t\n\n<h2 class=\"thin-font\">Blog Berichten<\/h2>\n\n  \n    <div class=\"row large-columns-4 medium-columns-1 small-columns-1 slider row-slider slider-nav-reveal slider-nav-push\"  data-flickity-options='{&quot;imagesLoaded&quot;: true, &quot;groupCells&quot;: &quot;100%&quot;, &quot;dragThreshold&quot; : 5, &quot;cellAlign&quot;: &quot;left&quot;,&quot;wrapAround&quot;: true,&quot;prevNextButtons&quot;: true,&quot;percentPosition&quot;: true,&quot;pageDots&quot;: false, &quot;rightToLeft&quot;: false, &quot;autoPlay&quot; : false}' >\n\n  <div class=\"col post-item\" >\n\t\t\t<div class=\"col-inner\">\n\t\t\t\t<div class=\"box box-normal box-text-bottom box-blog-post has-hover\">\n            \t\t\t\t\t<div class=\"box-image\" >\n  \t\t\t\t\t\t<div class=\"image-cover\" style=\"padding-top:32.25%;\">\n\t\t\t\t\t\t\t<a href=\"https:\/\/dutchhealthstore.com\/nl\/kun-je-beschadigd-haar-echt-herstellen-de-waarheid-over-gezond-haar\/\" class=\"plain\" aria-label=\"Kun je beschadigd haar echt herstellen? De waarheid over gezond haar\">\n\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"268\" src=\"https:\/\/dutchhealthstore.com\/wp-content\/uploads\/2026\/07\/joshbanner-800x268.jpg\" class=\"attachment-medium size-medium wp-post-image\" alt=\"\" srcset=\"https:\/\/dutchhealthstore.com\/wp-content\/uploads\/2026\/07\/joshbanner-800x268.jpg 800w, https:\/\/dutchhealthstore.com\/wp-content\/uploads\/2026\/07\/joshbanner-768x257.jpg 768w, https:\/\/dutchhealthstore.com\/wp-content\/uploads\/2026\/07\/joshbanner-149x50.jpg 149w, https:\/\/dutchhealthstore.com\/wp-content\/uploads\/2026\/07\/joshbanner-530x178.jpg 530w, https:\/\/dutchhealthstore.com\/wp-content\/uploads\/2026\/07\/joshbanner-64x21.jpg 64w, https:\/\/dutchhealthstore.com\/wp-content\/uploads\/2026\/07\/joshbanner.jpg 1390w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t<\/a>\n  \t\t\t\t\t\t\t  \t\t\t\t\t\t\t  \t\t\t\t\t\t<\/div>\n  \t\t\t\t\t\t  \t\t\t\t\t<\/div>\n          \t\t\t\t\t<div class=\"box-text text-center\" >\n\t\t\t\t\t<div class=\"box-text-inner blog-post-inner\">\n\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<h5 class=\"post-title is-large \">\n\t\t\t\t\t\t<a href=\"https:\/\/dutchhealthstore.com\/nl\/kun-je-beschadigd-haar-echt-herstellen-de-waarheid-over-gezond-haar\/\" class=\"plain\">Kun je beschadigd haar echt herstellen? De waarheid over gezond haar<\/a>\n\t\t\t\t\t<\/h5>\n\t\t\t\t\t\t\t\t\t\t<div class=\"is-divider\"><\/div>\n\t\t\t\t\t\t\t\t\t\t<p class=\"from_the_blog_excerpt \">\n\t\t\t\t\t\tWe hebben de beloftes allemaal wel eens gezien. Producten die beweren beschadigd haar van de [...]\t\t\t\t\t<\/p>\n\t\t\t\t\t                    \n\t\t\t\t\t\n\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"badge absolute top post-date badge-square\">\n\t\t\t\t\t\t\t<div class=\"badge-inner\">\n\t\t\t\t\t\t\t\t<span class=\"post-date-day\">03<\/span><br>\n\t\t\t\t\t\t\t\t<span class=\"post-date-month is-xsmall\">jul<\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div><div class=\"col post-item\" >\n\t\t\t<div class=\"col-inner\">\n\t\t\t\t<div class=\"box box-normal box-text-bottom box-blog-post has-hover\">\n            \t\t\t\t\t<div class=\"box-image\" >\n  \t\t\t\t\t\t<div class=\"image-cover\" style=\"padding-top:32.25%;\">\n\t\t\t\t\t\t\t<a href=\"https:\/\/dutchhealthstore.com\/nl\/snakt-je-haar-naar-proteinen-of-vocht\/\" class=\"plain\" aria-label=\"Snakt je haar naar prote\u00efnen of vocht?\">\n\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"268\" src=\"https:\/\/dutchhealthstore.com\/wp-content\/uploads\/2025\/05\/josh-header-2-800x268.jpg\" class=\"attachment-medium size-medium wp-post-image\" alt=\"\" srcset=\"https:\/\/dutchhealthstore.com\/wp-content\/uploads\/2025\/05\/josh-header-2-800x268.jpg 800w, https:\/\/dutchhealthstore.com\/wp-content\/uploads\/2025\/05\/josh-header-2-768x257.jpg 768w, https:\/\/dutchhealthstore.com\/wp-content\/uploads\/2025\/05\/josh-header-2-149x50.jpg 149w, https:\/\/dutchhealthstore.com\/wp-content\/uploads\/2025\/05\/josh-header-2-530x178.jpg 530w, https:\/\/dutchhealthstore.com\/wp-content\/uploads\/2025\/05\/josh-header-2-64x21.jpg 64w, https:\/\/dutchhealthstore.com\/wp-content\/uploads\/2025\/05\/josh-header-2.jpg 1390w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t<\/a>\n  \t\t\t\t\t\t\t  \t\t\t\t\t\t\t  \t\t\t\t\t\t<\/div>\n  \t\t\t\t\t\t  \t\t\t\t\t<\/div>\n          \t\t\t\t\t<div class=\"box-text text-center\" >\n\t\t\t\t\t<div class=\"box-text-inner blog-post-inner\">\n\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<h5 class=\"post-title is-large \">\n\t\t\t\t\t\t<a href=\"https:\/\/dutchhealthstore.com\/nl\/snakt-je-haar-naar-proteinen-of-vocht\/\" class=\"plain\">Snakt je haar naar prote\u00efnen of vocht?<\/a>\n\t\t\t\t\t<\/h5>\n\t\t\t\t\t\t\t\t\t\t<div class=\"is-divider\"><\/div>\n\t\t\t\t\t\t\t\t\t\t<p class=\"from_the_blog_excerpt \">\n\t\t\t\t\t\tHaar voelt vaak onvoorspelbaar aan. De ene maand glanst en glanst het, de volgende maand [...]\t\t\t\t\t<\/p>\n\t\t\t\t\t                    \n\t\t\t\t\t\n\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"badge absolute top post-date badge-square\">\n\t\t\t\t\t\t\t<div class=\"badge-inner\">\n\t\t\t\t\t\t\t\t<span class=\"post-date-day\">22<\/span><br>\n\t\t\t\t\t\t\t\t<span class=\"post-date-month is-xsmall\">mei<\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div><div class=\"col post-item\" >\n\t\t\t<div class=\"col-inner\">\n\t\t\t\t<div class=\"box box-normal box-text-bottom box-blog-post has-hover\">\n            \t\t\t\t\t<div class=\"box-image\" >\n  \t\t\t\t\t\t<div class=\"image-cover\" style=\"padding-top:32.25%;\">\n\t\t\t\t\t\t\t<a href=\"https:\/\/dutchhealthstore.com\/nl\/josh-rosebrooks-hair-care-is-eindelijk-terug-bij-dutch-health-store\/\" class=\"plain\" aria-label=\"Josh Rosebrook&#8217;s Hair Care is eindelijk terug bij Dutch Health Store!\">\n\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"268\" src=\"https:\/\/dutchhealthstore.com\/wp-content\/uploads\/2025\/05\/headerjosh-800x268.jpg\" class=\"attachment-medium size-medium wp-post-image\" alt=\"\" srcset=\"https:\/\/dutchhealthstore.com\/wp-content\/uploads\/2025\/05\/headerjosh-800x268.jpg 800w, https:\/\/dutchhealthstore.com\/wp-content\/uploads\/2025\/05\/headerjosh-768x257.jpg 768w, https:\/\/dutchhealthstore.com\/wp-content\/uploads\/2025\/05\/headerjosh-149x50.jpg 149w, https:\/\/dutchhealthstore.com\/wp-content\/uploads\/2025\/05\/headerjosh-530x178.jpg 530w, https:\/\/dutchhealthstore.com\/wp-content\/uploads\/2025\/05\/headerjosh-64x21.jpg 64w, https:\/\/dutchhealthstore.com\/wp-content\/uploads\/2025\/05\/headerjosh.jpg 1390w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t<\/a>\n  \t\t\t\t\t\t\t  \t\t\t\t\t\t\t  \t\t\t\t\t\t<\/div>\n  \t\t\t\t\t\t  \t\t\t\t\t<\/div>\n          \t\t\t\t\t<div class=\"box-text text-center\" >\n\t\t\t\t\t<div class=\"box-text-inner blog-post-inner\">\n\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<h5 class=\"post-title is-large \">\n\t\t\t\t\t\t<a href=\"https:\/\/dutchhealthstore.com\/nl\/josh-rosebrooks-hair-care-is-eindelijk-terug-bij-dutch-health-store\/\" class=\"plain\">Josh Rosebrook&#8217;s Hair Care is eindelijk terug bij Dutch Health Store!<\/a>\n\t\t\t\t\t<\/h5>\n\t\t\t\t\t\t\t\t\t\t<div class=\"is-divider\"><\/div>\n\t\t\t\t\t\t\t\t\t\t<p class=\"from_the_blog_excerpt \">\n\t\t\t\t\t\tBijna anderhalf jaar lang moest ons team keer op keer dezelfde teleurstellende zin uitspreken: \u201cSorry, [...]\t\t\t\t\t<\/p>\n\t\t\t\t\t                    \n\t\t\t\t\t\n\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"badge absolute top post-date badge-square\">\n\t\t\t\t\t\t\t<div class=\"badge-inner\">\n\t\t\t\t\t\t\t\t<span class=\"post-date-day\">22<\/span><br>\n\t\t\t\t\t\t\t\t<span class=\"post-date-month is-xsmall\">mei<\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div><div class=\"col post-item\" >\n\t\t\t<div class=\"col-inner\">\n\t\t\t\t<div class=\"box box-normal box-text-bottom box-blog-post has-hover\">\n            \t\t\t\t\t<div class=\"box-image\" >\n  \t\t\t\t\t\t<div class=\"image-cover\" style=\"padding-top:32.25%;\">\n\t\t\t\t\t\t\t<a href=\"https:\/\/dutchhealthstore.com\/nl\/verheldert-vitamine-c-de-huid\/\" class=\"plain\" aria-label=\"Verheldert vitamine C de huid?\">\n\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"268\" src=\"https:\/\/dutchhealthstore.com\/wp-content\/uploads\/2024\/11\/vitaminC-skin-800x268.jpg\" class=\"attachment-medium size-medium wp-post-image\" alt=\"\" srcset=\"https:\/\/dutchhealthstore.com\/wp-content\/uploads\/2024\/11\/vitaminC-skin-800x268.jpg 800w, https:\/\/dutchhealthstore.com\/wp-content\/uploads\/2024\/11\/vitaminC-skin-768x257.jpg 768w, https:\/\/dutchhealthstore.com\/wp-content\/uploads\/2024\/11\/vitaminC-skin-149x50.jpg 149w, https:\/\/dutchhealthstore.com\/wp-content\/uploads\/2024\/11\/vitaminC-skin-530x178.jpg 530w, https:\/\/dutchhealthstore.com\/wp-content\/uploads\/2024\/11\/vitaminC-skin-64x21.jpg 64w, https:\/\/dutchhealthstore.com\/wp-content\/uploads\/2024\/11\/vitaminC-skin.jpg 1390w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t<\/a>\n  \t\t\t\t\t\t\t  \t\t\t\t\t\t\t  \t\t\t\t\t\t<\/div>\n  \t\t\t\t\t\t  \t\t\t\t\t<\/div>\n          \t\t\t\t\t<div class=\"box-text text-center\" >\n\t\t\t\t\t<div class=\"box-text-inner blog-post-inner\">\n\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<h5 class=\"post-title is-large \">\n\t\t\t\t\t\t<a href=\"https:\/\/dutchhealthstore.com\/nl\/verheldert-vitamine-c-de-huid\/\" class=\"plain\">Verheldert vitamine C de huid?<\/a>\n\t\t\t\t\t<\/h5>\n\t\t\t\t\t\t\t\t\t\t<div class=\"is-divider\"><\/div>\n\t\t\t\t\t\t\t\t\t\t<p class=\"from_the_blog_excerpt \">\n\t\t\t\t\t\tVitamine C is essentieel voor een gezonde huid. Het is de meest overvloedige antioxidant in [...]\t\t\t\t\t<\/p>\n\t\t\t\t\t                    \n\t\t\t\t\t\n\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"badge absolute top post-date badge-square\">\n\t\t\t\t\t\t\t<div class=\"badge-inner\">\n\t\t\t\t\t\t\t\t<span class=\"post-date-day\">12<\/span><br>\n\t\t\t\t\t\t\t\t<span class=\"post-date-month is-xsmall\">nov<\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div><div class=\"col post-item\" >\n\t\t\t<div class=\"col-inner\">\n\t\t\t\t<div class=\"box box-normal box-text-bottom box-blog-post has-hover\">\n            \t\t\t\t\t<div class=\"box-image\" >\n  \t\t\t\t\t\t<div class=\"image-cover\" style=\"padding-top:32.25%;\">\n\t\t\t\t\t\t\t<a href=\"https:\/\/dutchhealthstore.com\/nl\/de-kracht-van-voedende-reinigingsproducten\/\" class=\"plain\" aria-label=\"De kracht van voedende reinigingsproducten\">\n\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"268\" src=\"https:\/\/dutchhealthstore.com\/wp-content\/uploads\/2024\/11\/blog-cleansers-800x268.jpg\" class=\"attachment-medium size-medium wp-post-image\" alt=\"\" srcset=\"https:\/\/dutchhealthstore.com\/wp-content\/uploads\/2024\/11\/blog-cleansers-800x268.jpg 800w, https:\/\/dutchhealthstore.com\/wp-content\/uploads\/2024\/11\/blog-cleansers-768x257.jpg 768w, https:\/\/dutchhealthstore.com\/wp-content\/uploads\/2024\/11\/blog-cleansers-149x50.jpg 149w, https:\/\/dutchhealthstore.com\/wp-content\/uploads\/2024\/11\/blog-cleansers-530x178.jpg 530w, https:\/\/dutchhealthstore.com\/wp-content\/uploads\/2024\/11\/blog-cleansers-64x21.jpg 64w, https:\/\/dutchhealthstore.com\/wp-content\/uploads\/2024\/11\/blog-cleansers.jpg 1390w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t<\/a>\n  \t\t\t\t\t\t\t  \t\t\t\t\t\t\t  \t\t\t\t\t\t<\/div>\n  \t\t\t\t\t\t  \t\t\t\t\t<\/div>\n          \t\t\t\t\t<div class=\"box-text text-center\" >\n\t\t\t\t\t<div class=\"box-text-inner blog-post-inner\">\n\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<h5 class=\"post-title is-large \">\n\t\t\t\t\t\t<a href=\"https:\/\/dutchhealthstore.com\/nl\/de-kracht-van-voedende-reinigingsproducten\/\" class=\"plain\">De kracht van voedende reinigingsproducten<\/a>\n\t\t\t\t\t<\/h5>\n\t\t\t\t\t\t\t\t\t\t<div class=\"is-divider\"><\/div>\n\t\t\t\t\t\t\t\t\t\t<p class=\"from_the_blog_excerpt \">\n\t\t\t\t\t\tReinigen is de basis van elke effectieve huidverzorgingsroutine. Een goede cleanser verwijdert vuil, olie en [...]\t\t\t\t\t<\/p>\n\t\t\t\t\t                    \n\t\t\t\t\t\n\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"badge absolute top post-date badge-square\">\n\t\t\t\t\t\t\t<div class=\"badge-inner\">\n\t\t\t\t\t\t\t\t<span class=\"post-date-day\">07<\/span><br>\n\t\t\t\t\t\t\t\t<span class=\"post-date-month is-xsmall\">nov<\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div><div class=\"col post-item\" >\n\t\t\t<div class=\"col-inner\">\n\t\t\t\t<div class=\"box box-normal box-text-bottom box-blog-post has-hover\">\n            \t\t\t\t\t<div class=\"box-image\" >\n  \t\t\t\t\t\t<div class=\"image-cover\" style=\"padding-top:32.25%;\">\n\t\t\t\t\t\t\t<a href=\"https:\/\/dutchhealthstore.com\/nl\/omarm-de-zeven-stappen-van-huidverzorging-voor-een-stralende-gezonde-huid\/\" class=\"plain\" aria-label=\"Omarm de zeven stappen van huidverzorging voor een stralende, gezonde huid\">\n\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"268\" src=\"https:\/\/dutchhealthstore.com\/wp-content\/uploads\/2023\/11\/joshrosebrook-2-800x268.jpg\" class=\"attachment-medium size-medium wp-post-image\" alt=\"\" srcset=\"https:\/\/dutchhealthstore.com\/wp-content\/uploads\/2023\/11\/joshrosebrook-2-800x268.jpg 800w, https:\/\/dutchhealthstore.com\/wp-content\/uploads\/2023\/11\/joshrosebrook-2-768x257.jpg 768w, https:\/\/dutchhealthstore.com\/wp-content\/uploads\/2023\/11\/joshrosebrook-2-510x171.jpg 510w, https:\/\/dutchhealthstore.com\/wp-content\/uploads\/2023\/11\/joshrosebrook-2-64x21.jpg 64w, https:\/\/dutchhealthstore.com\/wp-content\/uploads\/2023\/11\/joshrosebrook-2.jpg 1390w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t<\/a>\n  \t\t\t\t\t\t\t  \t\t\t\t\t\t\t  \t\t\t\t\t\t<\/div>\n  \t\t\t\t\t\t  \t\t\t\t\t<\/div>\n          \t\t\t\t\t<div class=\"box-text text-center\" >\n\t\t\t\t\t<div class=\"box-text-inner blog-post-inner\">\n\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<h5 class=\"post-title is-large \">\n\t\t\t\t\t\t<a href=\"https:\/\/dutchhealthstore.com\/nl\/omarm-de-zeven-stappen-van-huidverzorging-voor-een-stralende-gezonde-huid\/\" class=\"plain\">Omarm de zeven stappen van huidverzorging voor een stralende, gezonde huid<\/a>\n\t\t\t\t\t<\/h5>\n\t\t\t\t\t\t\t\t\t\t<div class=\"is-divider\"><\/div>\n\t\t\t\t\t\t\t\t\t\t<p class=\"from_the_blog_excerpt \">\n\t\t\t\t\t\tGa mee op een transformerende reis met ons bij Dutch Health Store, als we ons [...]\t\t\t\t\t<\/p>\n\t\t\t\t\t                    \n\t\t\t\t\t\n\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"badge absolute top post-date badge-square\">\n\t\t\t\t\t\t\t<div class=\"badge-inner\">\n\t\t\t\t\t\t\t\t<span class=\"post-date-day\">23<\/span><br>\n\t\t\t\t\t\t\t\t<span class=\"post-date-month is-xsmall\">nov<\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div><div class=\"col post-item\" >\n\t\t\t<div class=\"col-inner\">\n\t\t\t\t<div class=\"box box-normal box-text-bottom box-blog-post has-hover\">\n            \t\t\t\t\t<div class=\"box-image\" >\n  \t\t\t\t\t\t<div class=\"image-cover\" style=\"padding-top:32.25%;\">\n\t\t\t\t\t\t\t<a href=\"https:\/\/dutchhealthstore.com\/nl\/ontdek-de-magie-van-biovergistingen-voor-een-gezonde-huid\/\" class=\"plain\" aria-label=\"Ontdek de magie van biovergistingen voor een gezonde huid\">\n\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"268\" src=\"https:\/\/dutchhealthstore.com\/wp-content\/uploads\/2023\/06\/josh-rosebrook-header-800x268.jpg\" class=\"attachment-medium size-medium wp-post-image\" alt=\"josh rosebrook\" srcset=\"https:\/\/dutchhealthstore.com\/wp-content\/uploads\/2023\/06\/josh-rosebrook-header-800x268.jpg 800w, https:\/\/dutchhealthstore.com\/wp-content\/uploads\/2023\/06\/josh-rosebrook-header-768x257.jpg 768w, https:\/\/dutchhealthstore.com\/wp-content\/uploads\/2023\/06\/josh-rosebrook-header-510x171.jpg 510w, https:\/\/dutchhealthstore.com\/wp-content\/uploads\/2023\/06\/josh-rosebrook-header-64x21.jpg 64w, https:\/\/dutchhealthstore.com\/wp-content\/uploads\/2023\/06\/josh-rosebrook-header.jpg 1390w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t<\/a>\n  \t\t\t\t\t\t\t  \t\t\t\t\t\t\t  \t\t\t\t\t\t<\/div>\n  \t\t\t\t\t\t  \t\t\t\t\t<\/div>\n          \t\t\t\t\t<div class=\"box-text text-center\" >\n\t\t\t\t\t<div class=\"box-text-inner blog-post-inner\">\n\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<h5 class=\"post-title is-large \">\n\t\t\t\t\t\t<a href=\"https:\/\/dutchhealthstore.com\/nl\/ontdek-de-magie-van-biovergistingen-voor-een-gezonde-huid\/\" class=\"plain\">Ontdek de magie van biovergistingen voor een gezonde huid<\/a>\n\t\t\t\t\t<\/h5>\n\t\t\t\t\t\t\t\t\t\t<div class=\"is-divider\"><\/div>\n\t\t\t\t\t\t\t\t\t\t<p class=\"from_the_blog_excerpt \">\n\t\t\t\t\t\tOnze fascinatie voor biofermentatie zit diep en sluit naadloos aan bij onze toewijding aan huidverzorging [...]\t\t\t\t\t<\/p>\n\t\t\t\t\t                    \n\t\t\t\t\t\n\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"badge absolute top post-date badge-square\">\n\t\t\t\t\t\t\t<div class=\"badge-inner\">\n\t\t\t\t\t\t\t\t<span class=\"post-date-day\">22<\/span><br>\n\t\t\t\t\t\t\t\t<span class=\"post-date-month is-xsmall\">jun<\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div><div class=\"col post-item\" >\n\t\t\t<div class=\"col-inner\">\n\t\t\t\t<div class=\"box box-normal box-text-bottom box-blog-post has-hover\">\n            \t\t\t\t\t<div class=\"box-image\" >\n  \t\t\t\t\t\t<div class=\"image-cover\" style=\"padding-top:32.25%;\">\n\t\t\t\t\t\t\t<a href=\"https:\/\/dutchhealthstore.com\/nl\/de-waarheid-over-essentiele-olien-in-huidverzorging\/\" class=\"plain\" aria-label=\"De waarheid over essenti\u00eble oli\u00ebn in huidverzorging\">\n\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"268\" src=\"https:\/\/dutchhealthstore.com\/wp-content\/uploads\/2022\/05\/header-joshrosebrfook-800x268.jpg\" class=\"attachment-medium size-medium wp-post-image\" alt=\"\" srcset=\"https:\/\/dutchhealthstore.com\/wp-content\/uploads\/2022\/05\/header-joshrosebrfook-800x268.jpg 800w, https:\/\/dutchhealthstore.com\/wp-content\/uploads\/2022\/05\/header-joshrosebrfook-510x171.jpg 510w, https:\/\/dutchhealthstore.com\/wp-content\/uploads\/2022\/05\/header-joshrosebrfook-64x21.jpg 64w, https:\/\/dutchhealthstore.com\/wp-content\/uploads\/2022\/05\/header-joshrosebrfook-768x257.jpg 768w, https:\/\/dutchhealthstore.com\/wp-content\/uploads\/2022\/05\/header-joshrosebrfook.jpg 1390w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t<\/a>\n  \t\t\t\t\t\t\t  \t\t\t\t\t\t\t  \t\t\t\t\t\t<\/div>\n  \t\t\t\t\t\t  \t\t\t\t\t<\/div>\n          \t\t\t\t\t<div class=\"box-text text-center\" >\n\t\t\t\t\t<div class=\"box-text-inner blog-post-inner\">\n\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<h5 class=\"post-title is-large \">\n\t\t\t\t\t\t<a href=\"https:\/\/dutchhealthstore.com\/nl\/de-waarheid-over-essentiele-olien-in-huidverzorging\/\" class=\"plain\">De waarheid over essenti\u00eble oli\u00ebn in huidverzorging<\/a>\n\t\t\t\t\t<\/h5>\n\t\t\t\t\t\t\t\t\t\t<div class=\"is-divider\"><\/div>\n\t\t\t\t\t\t\t\t\t\t<p class=\"from_the_blog_excerpt \">\n\t\t\t\t\t\tVan alles wat delicaat, zuiver en waardevol is in deze wereld, wordt uiteindelijk misbruik gemaakt. [...]\t\t\t\t\t<\/p>\n\t\t\t\t\t                    \n\t\t\t\t\t\n\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"badge absolute top post-date badge-square\">\n\t\t\t\t\t\t\t<div class=\"badge-inner\">\n\t\t\t\t\t\t\t\t<span class=\"post-date-day\">20<\/span><br>\n\t\t\t\t\t\t\t\t<span class=\"post-date-month is-xsmall\">mei<\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div><\/div>\n\n\n\t\t<\/div>\n\n\t\t\n<style>\n#section_1859624629 {\n  padding-top: 30px;\n  padding-bottom: 30px;\n}\n<\/style>\n\t<\/section>\n\t\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p><strong data-start=\"127\" data-end=\"142\">Serum Spray<\/strong> is een revolutionair haarserum dat werkt als een lichtgewicht stylingbehandeling en een voedende tonic voor de hoofdhuid.<\/p>\n","protected":false},"featured_media":341472,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[1029,8570,5601,1006,510,8600],"product_tag":[6156,4018,9602,3799],"class_list":["post-341825","product","type-product","status-publish","has-post-thumbnail","product_cat-categorieen","product_cat-hair-nl","product_cat-josh-rosebrook-nl","product_cat-merken","product_cat-shop-winkel","product_cat-styling","product_tag-face-care-nl","product_tag-haar","product_tag-hydrating-nl","product_tag-serum-nl","pa_brand-josh-rosebrook-nl","pa_gtin-810872030094-nl","pa_haircare-productype-styling-hair-nl","pa_size-120-ml-nl","first","outofstock","taxable","shipping-taxable","purchasable","product-type-simple"],"bundled_by":[],"bundle_stock_status":"outofstock","bundle_stock_quantity":0,"bundle_virtual":false,"bundle_layout":"","bundle_add_to_cart_form_location":"","bundle_editable_in_cart":false,"bundle_sold_individually_context":"","bundle_item_grouping":"","bundle_min_size":"","bundle_max_size":"","bundle_price":[],"bundled_items":[],"bundle_sell_ids":[],"group_of_quantity":0,"min_quantity":0,"max_quantity":"","exclude_order_quantity_value_rules":"no","exclude_category_quantity_rules":"no","combine_variations":"no","yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.1 (Yoast SEO v28.1) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Serum Spray - Josh Rosebrook<\/title>\n<meta name=\"description\" content=\"Serum Spray is een revolutionair haarserum dat werkt als een lichtgewicht stylingbehandeling en een voedende tonic voor de hoofdhuid.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dutchhealthstore.com\/nl\/product\/serum-spray\/\" \/>\n<meta property=\"og:locale\" content=\"nl_NL\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Serum Spray - Dutch Health Store\" \/>\n<meta property=\"og:description\" content=\"Serum Spray is een revolutionair haarserum dat werkt als een lichtgewicht stylingbehandeling en een voedende tonic voor de hoofdhuid.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dutchhealthstore.com\/nl\/product\/serum-spray\/\" \/>\n<meta property=\"og:site_name\" content=\"Dutch Health Store\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.instagram.com\/dutchhealthstore\/\" \/>\n<meta property=\"article:modified_time\" content=\"2025-10-10T07:51:10+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dutchhealthstore.com\/wp-content\/uploads\/2025\/05\/josh-rosebrook-serum-spray.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"530\" \/>\n\t<meta property=\"og:image:height\" content=\"530\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Prijs\" \/>\n\t<meta name=\"twitter:data1\" content=\"&euro;22,00\" \/>\n\t<meta name=\"twitter:label2\" content=\"Beschikbaarheid\" \/>\n\t<meta name=\"twitter:data2\" content=\"Uitverkocht\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/dutchhealthstore.com\\\/nl\\\/product\\\/serum-spray\\\/\",\"url\":\"https:\\\/\\\/dutchhealthstore.com\\\/nl\\\/product\\\/serum-spray\\\/\",\"name\":\"Serum Spray - Josh Rosebrook\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dutchhealthstore.com\\\/nl\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/dutchhealthstore.com\\\/nl\\\/product\\\/serum-spray\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/dutchhealthstore.com\\\/nl\\\/product\\\/serum-spray\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dutchhealthstore.com\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/josh-rosebrook-serum-spray.jpg\",\"datePublished\":\"2025-05-20T14:10:44+00:00\",\"dateModified\":\"2025-10-10T07:51:10+00:00\",\"description\":\"Serum Spray is een revolutionair haarserum dat werkt als een lichtgewicht stylingbehandeling en een voedende tonic voor de hoofdhuid.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/dutchhealthstore.com\\\/nl\\\/product\\\/serum-spray\\\/#breadcrumb\"},\"inLanguage\":\"nl-NL\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/dutchhealthstore.com\\\/nl\\\/product\\\/serum-spray\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"nl-NL\",\"@id\":\"https:\\\/\\\/dutchhealthstore.com\\\/nl\\\/product\\\/serum-spray\\\/#primaryimage\",\"url\":\"https:\\\/\\\/dutchhealthstore.com\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/josh-rosebrook-serum-spray.jpg\",\"contentUrl\":\"https:\\\/\\\/dutchhealthstore.com\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/josh-rosebrook-serum-spray.jpg\",\"width\":530,\"height\":530,\"caption\":\"josh-rosebrook-serum-spray\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/dutchhealthstore.com\\\/nl\\\/product\\\/serum-spray\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/dutchhealthstore.com\\\/nl\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/dutchhealthstore.com\\\/nl\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Serum Spray\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/dutchhealthstore.com\\\/nl\\\/#website\",\"url\":\"https:\\\/\\\/dutchhealthstore.com\\\/nl\\\/\",\"name\":\"Dutch Health Store\",\"description\":\"Enhance Your Beauty with Organic &amp; Natural Skincare\",\"publisher\":{\"@id\":\"https:\\\/\\\/dutchhealthstore.com\\\/nl\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/dutchhealthstore.com\\\/nl\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"nl-NL\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/dutchhealthstore.com\\\/nl\\\/#organization\",\"name\":\"Dutch Health Store\",\"url\":\"https:\\\/\\\/dutchhealthstore.com\\\/nl\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"nl-NL\",\"@id\":\"https:\\\/\\\/dutchhealthstore.com\\\/nl\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/dutchhealthstore.com\\\/wp-content\\\/uploads\\\/2020\\\/08\\\/logo-dutchhealthstore-jpg-e1599484957574.jpg\",\"contentUrl\":\"https:\\\/\\\/dutchhealthstore.com\\\/wp-content\\\/uploads\\\/2020\\\/08\\\/logo-dutchhealthstore-jpg-e1599484957574.jpg\",\"width\":400,\"height\":62,\"caption\":\"Dutch Health Store\"},\"image\":{\"@id\":\"https:\\\/\\\/dutchhealthstore.com\\\/nl\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.instagram.com\\\/dutchhealthstore\\\/\",\"https:\\\/\\\/www.facebook.com\\\/dutchhealthstore\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Serum Spray - Josh Rosebrook","description":"Serum Spray is een revolutionair haarserum dat werkt als een lichtgewicht stylingbehandeling en een voedende tonic voor de hoofdhuid.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dutchhealthstore.com\/nl\/product\/serum-spray\/","og_locale":"nl_NL","og_type":"article","og_title":"Serum Spray - Dutch Health Store","og_description":"Serum Spray is een revolutionair haarserum dat werkt als een lichtgewicht stylingbehandeling en een voedende tonic voor de hoofdhuid.","og_url":"https:\/\/dutchhealthstore.com\/nl\/product\/serum-spray\/","og_site_name":"Dutch Health Store","article_publisher":"https:\/\/www.instagram.com\/dutchhealthstore\/","article_modified_time":"2025-10-10T07:51:10+00:00","og_image":[{"width":530,"height":530,"url":"https:\/\/dutchhealthstore.com\/wp-content\/uploads\/2025\/05\/josh-rosebrook-serum-spray.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Prijs":"&euro;22,00","Beschikbaarheid":"Uitverkocht"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/dutchhealthstore.com\/nl\/product\/serum-spray\/","url":"https:\/\/dutchhealthstore.com\/nl\/product\/serum-spray\/","name":"Serum Spray - Josh Rosebrook","isPartOf":{"@id":"https:\/\/dutchhealthstore.com\/nl\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dutchhealthstore.com\/nl\/product\/serum-spray\/#primaryimage"},"image":{"@id":"https:\/\/dutchhealthstore.com\/nl\/product\/serum-spray\/#primaryimage"},"thumbnailUrl":"https:\/\/dutchhealthstore.com\/wp-content\/uploads\/2025\/05\/josh-rosebrook-serum-spray.jpg","datePublished":"2025-05-20T14:10:44+00:00","dateModified":"2025-10-10T07:51:10+00:00","description":"Serum Spray is een revolutionair haarserum dat werkt als een lichtgewicht stylingbehandeling en een voedende tonic voor de hoofdhuid.","breadcrumb":{"@id":"https:\/\/dutchhealthstore.com\/nl\/product\/serum-spray\/#breadcrumb"},"inLanguage":"nl-NL","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dutchhealthstore.com\/nl\/product\/serum-spray\/"]}]},{"@type":"ImageObject","inLanguage":"nl-NL","@id":"https:\/\/dutchhealthstore.com\/nl\/product\/serum-spray\/#primaryimage","url":"https:\/\/dutchhealthstore.com\/wp-content\/uploads\/2025\/05\/josh-rosebrook-serum-spray.jpg","contentUrl":"https:\/\/dutchhealthstore.com\/wp-content\/uploads\/2025\/05\/josh-rosebrook-serum-spray.jpg","width":530,"height":530,"caption":"josh-rosebrook-serum-spray"},{"@type":"BreadcrumbList","@id":"https:\/\/dutchhealthstore.com\/nl\/product\/serum-spray\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/dutchhealthstore.com\/nl\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/dutchhealthstore.com\/nl\/shop\/"},{"@type":"ListItem","position":3,"name":"Serum Spray"}]},{"@type":"WebSite","@id":"https:\/\/dutchhealthstore.com\/nl\/#website","url":"https:\/\/dutchhealthstore.com\/nl\/","name":"Dutch Health Store","description":"Enhance Your Beauty with Organic &amp; Natural Skincare","publisher":{"@id":"https:\/\/dutchhealthstore.com\/nl\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dutchhealthstore.com\/nl\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"nl-NL"},{"@type":"Organization","@id":"https:\/\/dutchhealthstore.com\/nl\/#organization","name":"Dutch Health Store","url":"https:\/\/dutchhealthstore.com\/nl\/","logo":{"@type":"ImageObject","inLanguage":"nl-NL","@id":"https:\/\/dutchhealthstore.com\/nl\/#\/schema\/logo\/image\/","url":"https:\/\/dutchhealthstore.com\/wp-content\/uploads\/2020\/08\/logo-dutchhealthstore-jpg-e1599484957574.jpg","contentUrl":"https:\/\/dutchhealthstore.com\/wp-content\/uploads\/2020\/08\/logo-dutchhealthstore-jpg-e1599484957574.jpg","width":400,"height":62,"caption":"Dutch Health Store"},"image":{"@id":"https:\/\/dutchhealthstore.com\/nl\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.instagram.com\/dutchhealthstore\/","https:\/\/www.facebook.com\/dutchhealthstore"]}]}},"_links":{"self":[{"href":"https:\/\/dutchhealthstore.com\/nl\/wp-json\/wp\/v2\/product\/341825","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dutchhealthstore.com\/nl\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/dutchhealthstore.com\/nl\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/dutchhealthstore.com\/nl\/wp-json\/wp\/v2\/comments?post=341825"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dutchhealthstore.com\/nl\/wp-json\/wp\/v2\/media\/341472"}],"wp:attachment":[{"href":"https:\/\/dutchhealthstore.com\/nl\/wp-json\/wp\/v2\/media?parent=341825"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/dutchhealthstore.com\/nl\/wp-json\/wp\/v2\/product_brand?post=341825"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/dutchhealthstore.com\/nl\/wp-json\/wp\/v2\/product_cat?post=341825"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/dutchhealthstore.com\/nl\/wp-json\/wp\/v2\/product_tag?post=341825"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}