{"id":226408,"date":"2022-12-02T08:45:31","date_gmt":"2022-12-02T08:45:31","guid":{"rendered":"https:\/\/dutchhealthstore.com\/?p=226408"},"modified":"2022-12-02T07:56:28","modified_gmt":"2022-12-02T07:56:28","slug":"recipe-gnocchi-met-pesto","status":"publish","type":"post","link":"https:\/\/dutchhealthstore.com\/nl\/recipe-gnocchi-met-pesto\/","title":{"rendered":"(Recipe) Gnocchi with spicy cheese &#038; pesto"},"content":{"rendered":"\n\n\t<section class=\"section\" id=\"section_915945346\">\n\t\t<div class=\"section-bg fill\" >\n\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"768\" height=\"1152\" src=\"https:\/\/dutchhealthstore.com\/wp-content\/uploads\/2022\/12\/gnocchi-met-pesto-gezond-weekmenu-768x1152.jpg.webp\" class=\"bg attachment-original size-original\" alt=\"\" \/>\t\t\t\t\t\t<div class=\"section-bg-overlay absolute fill\"><\/div>\n\t\t\t\n\t<div class=\"is-border\"\n\t\tstyle=\"border-color:rgb(235, 235, 235);border-width:0px 0px 0px 0px;\">\n\t<\/div>\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n\n<div class=\"row row-large align-center\"  id=\"row-646417023\">\n\n\n\t<div id=\"col-1336116327\" class=\"col medium-6 small-12 large-6\"  >\n\t\t\t\t<div class=\"col-inner box-shadow-2 box-shadow-5-hover\" style=\"background-color:rgb(255, 255, 255);\" >\n\t\t\t\n\t\t\t\n\n<h2 class=\"thin-font\"><strong>(Recipe) <\/strong>Gnocchi with Spicy cheese and pesto<\/h2>\n<p><img decoding=\"async\" class=\"alignnone size-large wp-image-226414\" src=\"https:\/\/dutchhealthstore.com\/wp-content\/uploads\/2022\/12\/gnocchi-met-pesto-gezond-weekmenu-768x1152.jpg-533x800.webp\" alt=\"\" width=\"533\" height=\"800\" srcset=\"https:\/\/dutchhealthstore.com\/wp-content\/uploads\/2022\/12\/gnocchi-met-pesto-gezond-weekmenu-768x1152.jpg-533x800.webp 533w, https:\/\/dutchhealthstore.com\/wp-content\/uploads\/2022\/12\/gnocchi-met-pesto-gezond-weekmenu-768x1152.jpg-267x400.webp 267w, https:\/\/dutchhealthstore.com\/wp-content\/uploads\/2022\/12\/gnocchi-met-pesto-gezond-weekmenu-768x1152.jpg-510x765.webp 510w, https:\/\/dutchhealthstore.com\/wp-content\/uploads\/2022\/12\/gnocchi-met-pesto-gezond-weekmenu-768x1152.jpg-64x96.webp 64w, https:\/\/dutchhealthstore.com\/wp-content\/uploads\/2022\/12\/gnocchi-met-pesto-gezond-weekmenu-768x1152.jpg.webp 768w\" sizes=\"(max-width: 533px) 100vw, 533px\" \/><\/p>\n<p><strong><span class=\"wprm-recipe-details-label wprm-block-text-bold wprm-recipe-time-label wprm-recipe-prep-time-label\">Prep Time: <\/span><span class=\"wprm-recipe-time wprm-block-text-bold\"><span class=\"wprm-recipe-details wprm-recipe-details-minutes wprm-recipe-prep_time wprm-recipe-prep_time-minutes\">20 minutes<\/span><\/span><\/strong><strong><span class=\"wprm-recipe-time wprm-block-text-bold\"><span class=\"wprm-recipe-details-unit wprm-recipe-details-minutes wprm-recipe-prep_time-unit wprm-recipe-prep_timeunit-minutes\"><br><\/span><\/span><\/strong><strong><span class=\"wprm-recipe-details-label wprm-block-text-bold wprm-recipe-servings-label\">Serves <\/span><span class=\"wprm-recipe-servings wprm-recipe-details wprm-recipe-servings-56149 wprm-recipe-servings-adjustable-disabled wprm-block-text-bold\" data-recipe=\"56149\" aria-label=\"Adjust recipe servings\" data-servings=\"4\" data-original-servings=\"4\">4 <br><\/span><\/strong><\/p>\n<p>Gnocchi is not a pasta, but a mixture of potato, flour and egg. The advantage of gnocchi, apart from being very tasty, is that you cook gnocchi in a few minutes.<br><br>Baking gnocchi can also be done, which is also the tastiest part of this recipe. Baked gnocchi is deliciously crispy on the outside and soft on the inside.<br><br>Combined with the tangy flavor of the Parmigiano Reggiano and spicy pesto, this is a gnocchi recipe to make your mouth water! Lets get started!<\/p>\n\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-1336116327 > .col-inner {\n  padding: 15px 15px 15px 15px;\n}\n<\/style>\n\t<\/div>\n\n\t\n\n\t<div id=\"col-84539293\" class=\"col medium-6 small-12 large-6\"  >\n\t\t\t\t<div class=\"col-inner box-shadow-2 box-shadow-5-hover\" style=\"background-color:rgb(255, 255, 255);\" >\n\t\t\t\n\t\t\t\n\n\t<div id=\"text-2070996686\" class=\"text\">\n\t\t\n\n<div class=\"wprm-recipe-ingredients-container wprm-recipe-42544-ingredients-container wprm-block-text-normal wprm-ingredient-style-regular\" data-recipe=\"42544\" data-servings=\"12\">\n<div class=\"wprm-recipe-ingredients-container wprm-recipe-56149-ingredients-container wprm-block-text-normal wprm-ingredient-style-regular\" data-recipe=\"56149\" data-servings=\"4\">\n<h3 class=\"wprm-recipe-header wprm-recipe-ingredients-header wprm-block-text-bold wprm-align-left wprm-header-decoration-none\">Ingredients<\/h3>\n<div class=\"wprm-recipe-ingredients-container wprm-recipe-59936-ingredients-container wprm-block-text-normal wprm-ingredient-style-regular\" data-recipe=\"59936\" data-servings=\"4\">\n<div class=\"rte-setting\">\n<ul>\n<li>800 grams of gnocchi di patate<\/li>\n<li>1 onion<\/li>\n<li>250 grams of mushrooms<\/li>\n<li>250 grams of cherry tomatoes<\/li>\n<li>200 grams of spinach<\/li>\n<li>100 grams spicy Parmesan Cheese (Such as Parmigiano Reggiano)<\/li>\n<li>100 grams of green pesto<\/li>\n<\/ul>\n<\/div>\n<h3 class=\"wprm-recipe-header wprm-recipe-instructions-header wprm-block-text-bold wprm-align-left wprm-header-decoration-none\">Instructions<\/h3>\n<div class=\"wprm-recipe-instruction-group\">\n<ol>\n<li>Heat a generous splash of olive oil in a frying pan and fry the gnocchi for about 10 minutes until crisp and light brown.<\/li>\n<li>Chop the onion and thinly slice the mushrooms.<\/li>\n<li>Halve the cherry tomatoes.<\/li>\n<li>Heat a dash of oil in a second skillet and fry the onion and mushrooms in it for about 5 minutes.<\/li>\n<li>Then add the cherry tomatoes and spinach.<\/li>\n<li>Fry until the spinach has completely shrunk.<\/li>\n<li>Add the vegetables to the pan with the crispy gnocchi and toss to combine.<\/li>\n<li>Scoop the pesto into the gnocchi vegetable mixture and add half of the grated Parmigiano.<\/li>\n<li>Stir through until the cheese is melted.<\/li>\n<li>Serve the gnocchi with the remaining grated Parmigiano cheese.<\/li>\n<\/ol>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n\t\t\n<style>\n#text-2070996686 {\n  line-height: 1.75;\n}\n<\/style>\n\t<\/div>\n\t\n\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-84539293 > .col-inner {\n  padding: 15px 15px 15px 15px;\n}\n<\/style>\n\t<\/div>\n\n\t\n\n\t<div id=\"col-1561751606\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner text-center\"  >\n\t\t\t\n\t\t\t\n\n\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n<\/div>\n<div class=\"container section-title-container\" ><h3 class=\"section-title section-title-normal\"><b aria-hidden=\"true\"><\/b><span class=\"section-title-main\" >More recipes<\/span><b aria-hidden=\"true\"><\/b><\/h3><\/div>\n\n\n  \n    <div class=\"row large-columns-3 medium-columns-1 small-columns-1 slider row-slider slider-nav-reveal slider-nav-push\"  data-flickity-options='{&quot;imagesLoaded&quot;: true, &quot;groupCells&quot;: &quot;100%&quot;, &quot;dragThreshold&quot; : 5, &quot;cellAlign&quot;: &quot;left&quot;,&quot;wrapAround&quot;: true,&quot;prevNextButtons&quot;: true,&quot;percentPosition&quot;: true,&quot;pageDots&quot;: false, &quot;rightToLeft&quot;: false, &quot;autoPlay&quot; : false}' >\n\n  <div class=\"col post-item\" >\n\t\t\t<div class=\"col-inner\">\n\t\t\t\t<div class=\"box box-normal box-text-bottom box-blog-post has-hover\">\n            \t\t\t\t\t<div class=\"box-image\" >\n  \t\t\t\t\t\t<div class=\"image-cover\" style=\"padding-top:32%;\">\n\t\t\t\t\t\t\t<a href=\"https:\/\/dutchhealthstore.com\/nl\/recipe-healthy-flatbread-with-grilled-vegetables\/\" class=\"plain\" aria-label=\"(Recipe) Healthy flatbread with Grilled Vegetables\">\n\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"800\" height=\"268\" src=\"https:\/\/dutchhealthstore.com\/wp-content\/uploads\/2026\/08\/receptheader-800x268.jpg\" class=\"attachment-medium size-medium wp-post-image\" alt=\"\" srcset=\"https:\/\/dutchhealthstore.com\/wp-content\/uploads\/2026\/08\/receptheader-800x268.jpg 800w, https:\/\/dutchhealthstore.com\/wp-content\/uploads\/2026\/08\/receptheader-768x257.jpg 768w, https:\/\/dutchhealthstore.com\/wp-content\/uploads\/2026\/08\/receptheader-149x50.jpg 149w, https:\/\/dutchhealthstore.com\/wp-content\/uploads\/2026\/08\/receptheader-530x178.jpg 530w, https:\/\/dutchhealthstore.com\/wp-content\/uploads\/2026\/08\/receptheader-64x21.jpg 64w, https:\/\/dutchhealthstore.com\/wp-content\/uploads\/2026\/08\/receptheader.jpg 1390w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t<\/a>\n  \t\t\t\t\t\t\t  \t\t\t\t\t\t\t  \t\t\t\t\t\t<\/div>\n  \t\t\t\t\t\t  \t\t\t\t\t<\/div>\n          \t\t\t\t\t<div class=\"box-text text-center\" >\n\t\t\t\t\t<div class=\"box-text-inner blog-post-inner\">\n\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<h5 class=\"post-title is-large \">\n\t\t\t\t\t\t<a href=\"https:\/\/dutchhealthstore.com\/nl\/recipe-healthy-flatbread-with-grilled-vegetables\/\" class=\"plain\">(Recipe) Healthy flatbread with Grilled Vegetables<\/a>\n\t\t\t\t\t<\/h5>\n\t\t\t\t\t\t\t\t\t\t<div class=\"is-divider\"><\/div>\n\t\t\t\t\t\t\t\t\t\t<p class=\"from_the_blog_excerpt \">\n\t\t\t\t\t\tFresh, colourful and packed with flavour, these healthy flatbreads make a delicious lunch or light [...]\t\t\t\t\t<\/p>\n\t\t\t\t\t                    \n\t\t\t\t\t\n\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"badge absolute top post-date badge-square\">\n\t\t\t\t\t\t\t<div class=\"badge-inner\">\n\t\t\t\t\t\t\t\t<span class=\"post-date-day\">27<\/span><br>\n\t\t\t\t\t\t\t\t<span class=\"post-date-month is-xsmall\">aug<\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div><div class=\"col post-item\" >\n\t\t\t<div class=\"col-inner\">\n\t\t\t\t<div class=\"box box-normal box-text-bottom box-blog-post has-hover\">\n            \t\t\t\t\t<div class=\"box-image\" >\n  \t\t\t\t\t\t<div class=\"image-cover\" style=\"padding-top:32%;\">\n\t\t\t\t\t\t\t<a href=\"https:\/\/dutchhealthstore.com\/nl\/recipe-vegetable-mozzarella-ciabatta-skewers-with-pesto\/\" class=\"plain\" aria-label=\"(Recipe) Vegetable, Mozzarella &amp; Ciabatta Skewers with Pesto\">\n\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"268\" src=\"https:\/\/dutchhealthstore.com\/wp-content\/uploads\/2026\/08\/header-recipe-skew-800x268.jpg\" class=\"attachment-medium size-medium wp-post-image\" alt=\"\" srcset=\"https:\/\/dutchhealthstore.com\/wp-content\/uploads\/2026\/08\/header-recipe-skew-800x268.jpg 800w, https:\/\/dutchhealthstore.com\/wp-content\/uploads\/2026\/08\/header-recipe-skew-768x257.jpg 768w, https:\/\/dutchhealthstore.com\/wp-content\/uploads\/2026\/08\/header-recipe-skew-149x50.jpg 149w, https:\/\/dutchhealthstore.com\/wp-content\/uploads\/2026\/08\/header-recipe-skew-530x178.jpg 530w, https:\/\/dutchhealthstore.com\/wp-content\/uploads\/2026\/08\/header-recipe-skew-64x21.jpg 64w, https:\/\/dutchhealthstore.com\/wp-content\/uploads\/2026\/08\/header-recipe-skew.jpg 1390w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t<\/a>\n  \t\t\t\t\t\t\t  \t\t\t\t\t\t\t  \t\t\t\t\t\t<\/div>\n  \t\t\t\t\t\t  \t\t\t\t\t<\/div>\n          \t\t\t\t\t<div class=\"box-text text-center\" >\n\t\t\t\t\t<div class=\"box-text-inner blog-post-inner\">\n\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<h5 class=\"post-title is-large \">\n\t\t\t\t\t\t<a href=\"https:\/\/dutchhealthstore.com\/nl\/recipe-vegetable-mozzarella-ciabatta-skewers-with-pesto\/\" class=\"plain\">(Recipe) Vegetable, Mozzarella &amp; Ciabatta Skewers with Pesto<\/a>\n\t\t\t\t\t<\/h5>\n\t\t\t\t\t\t\t\t\t\t<div class=\"is-divider\"><\/div>\n\t\t\t\t\t\t\t\t\t\t<p class=\"from_the_blog_excerpt \">\n\t\t\t\t\t\tFresh, colourful and incredibly easy to make, these vegetable skewers combine juicy tomatoes, crunchy vegetables, [...]\t\t\t\t\t<\/p>\n\t\t\t\t\t                    \n\t\t\t\t\t\n\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"badge absolute top post-date badge-square\">\n\t\t\t\t\t\t\t<div class=\"badge-inner\">\n\t\t\t\t\t\t\t\t<span class=\"post-date-day\">14<\/span><br>\n\t\t\t\t\t\t\t\t<span class=\"post-date-month is-xsmall\">aug<\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div><div class=\"col post-item\" >\n\t\t\t<div class=\"col-inner\">\n\t\t\t\t<div class=\"box box-normal box-text-bottom box-blog-post has-hover\">\n            \t\t\t\t\t<div class=\"box-image\" >\n  \t\t\t\t\t\t<div class=\"image-cover\" style=\"padding-top:32%;\">\n\t\t\t\t\t\t\t<a href=\"https:\/\/dutchhealthstore.com\/nl\/recipe-mediterranean-chicken-with-pointed-cabbage\/\" class=\"plain\" aria-label=\"(Recipe) Mediterranean Chicken with Pointed Cabbage\">\n\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"268\" src=\"https:\/\/dutchhealthstore.com\/wp-content\/uploads\/2026\/08\/recept-cabbage-800x268.jpg\" class=\"attachment-medium size-medium wp-post-image\" alt=\"\" srcset=\"https:\/\/dutchhealthstore.com\/wp-content\/uploads\/2026\/08\/recept-cabbage-800x268.jpg 800w, https:\/\/dutchhealthstore.com\/wp-content\/uploads\/2026\/08\/recept-cabbage-768x257.jpg 768w, https:\/\/dutchhealthstore.com\/wp-content\/uploads\/2026\/08\/recept-cabbage-149x50.jpg 149w, https:\/\/dutchhealthstore.com\/wp-content\/uploads\/2026\/08\/recept-cabbage-530x178.jpg 530w, https:\/\/dutchhealthstore.com\/wp-content\/uploads\/2026\/08\/recept-cabbage-64x21.jpg 64w, https:\/\/dutchhealthstore.com\/wp-content\/uploads\/2026\/08\/recept-cabbage.jpg 1390w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t<\/a>\n  \t\t\t\t\t\t\t  \t\t\t\t\t\t\t  \t\t\t\t\t\t<\/div>\n  \t\t\t\t\t\t  \t\t\t\t\t<\/div>\n          \t\t\t\t\t<div class=\"box-text text-center\" >\n\t\t\t\t\t<div class=\"box-text-inner blog-post-inner\">\n\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<h5 class=\"post-title is-large \">\n\t\t\t\t\t\t<a href=\"https:\/\/dutchhealthstore.com\/nl\/recipe-mediterranean-chicken-with-pointed-cabbage\/\" class=\"plain\">(Recipe) Mediterranean Chicken with Pointed Cabbage<\/a>\n\t\t\t\t\t<\/h5>\n\t\t\t\t\t\t\t\t\t\t<div class=\"is-divider\"><\/div>\n\t\t\t\t\t\t\t\t\t\t<p class=\"from_the_blog_excerpt \">\n\t\t\t\t\t\tA simple, wholesome traybake packed with Mediterranean flavours. Tender chicken thighs, sweet roasted vegetables, caramelised [...]\t\t\t\t\t<\/p>\n\t\t\t\t\t                    \n\t\t\t\t\t\n\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"badge absolute top post-date badge-square\">\n\t\t\t\t\t\t\t<div class=\"badge-inner\">\n\t\t\t\t\t\t\t\t<span class=\"post-date-day\">07<\/span><br>\n\t\t\t\t\t\t\t\t<span class=\"post-date-month is-xsmall\">aug<\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div><div class=\"col post-item\" >\n\t\t\t<div class=\"col-inner\">\n\t\t\t\t<div class=\"box box-normal box-text-bottom box-blog-post has-hover\">\n            \t\t\t\t\t<div class=\"box-image\" >\n  \t\t\t\t\t\t<div class=\"image-cover\" style=\"padding-top:32%;\">\n\t\t\t\t\t\t\t<a href=\"https:\/\/dutchhealthstore.com\/nl\/recipe-summer-peach-burrata-salad\/\" class=\"plain\" aria-label=\"(Recipe) Summer peach &amp; Burrata Salad\">\n\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"268\" src=\"https:\/\/dutchhealthstore.com\/wp-content\/uploads\/2026\/07\/receptheader-800x268.png\" class=\"attachment-medium size-medium wp-post-image\" alt=\"\" srcset=\"https:\/\/dutchhealthstore.com\/wp-content\/uploads\/2026\/07\/receptheader-800x268.png 800w, https:\/\/dutchhealthstore.com\/wp-content\/uploads\/2026\/07\/receptheader-768x257.png 768w, https:\/\/dutchhealthstore.com\/wp-content\/uploads\/2026\/07\/receptheader-149x50.png 149w, https:\/\/dutchhealthstore.com\/wp-content\/uploads\/2026\/07\/receptheader-530x178.png 530w, https:\/\/dutchhealthstore.com\/wp-content\/uploads\/2026\/07\/receptheader-64x21.png 64w, https:\/\/dutchhealthstore.com\/wp-content\/uploads\/2026\/07\/receptheader.png 1390w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t<\/a>\n  \t\t\t\t\t\t\t  \t\t\t\t\t\t\t  \t\t\t\t\t\t<\/div>\n  \t\t\t\t\t\t  \t\t\t\t\t<\/div>\n          \t\t\t\t\t<div class=\"box-text text-center\" >\n\t\t\t\t\t<div class=\"box-text-inner blog-post-inner\">\n\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<h5 class=\"post-title is-large \">\n\t\t\t\t\t\t<a href=\"https:\/\/dutchhealthstore.com\/nl\/recipe-summer-peach-burrata-salad\/\" class=\"plain\">(Recipe) Summer peach &amp; Burrata Salad<\/a>\n\t\t\t\t\t<\/h5>\n\t\t\t\t\t\t\t\t\t\t<div class=\"is-divider\"><\/div>\n\t\t\t\t\t\t\t\t\t\t<p class=\"from_the_blog_excerpt \">\n\t\t\t\t\t\tA fresh taste of summer, inspired by long lunches in the French countryside. Juicy peaches, [...]\t\t\t\t\t<\/p>\n\t\t\t\t\t                    \n\t\t\t\t\t\n\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"badge absolute top post-date badge-square\">\n\t\t\t\t\t\t\t<div class=\"badge-inner\">\n\t\t\t\t\t\t\t\t<span class=\"post-date-day\">31<\/span><br>\n\t\t\t\t\t\t\t\t<span class=\"post-date-month is-xsmall\">jul<\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div><div class=\"col post-item\" >\n\t\t\t<div class=\"col-inner\">\n\t\t\t\t<div class=\"box box-normal box-text-bottom box-blog-post has-hover\">\n            \t\t\t\t\t<div class=\"box-image\" >\n  \t\t\t\t\t\t<div class=\"image-cover\" style=\"padding-top:32%;\">\n\t\t\t\t\t\t\t<a href=\"https:\/\/dutchhealthstore.com\/nl\/recipe-italian-vegetable-stew-with-cauliflower-rice\/\" class=\"plain\" aria-label=\"(Recipe) Italian Vegetable Stew with Cauliflower Rice\">\n\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"268\" src=\"https:\/\/dutchhealthstore.com\/wp-content\/uploads\/2025\/07\/header-recipe2-800x268.jpg\" class=\"attachment-medium size-medium wp-post-image\" alt=\"\" srcset=\"https:\/\/dutchhealthstore.com\/wp-content\/uploads\/2025\/07\/header-recipe2-800x268.jpg 800w, https:\/\/dutchhealthstore.com\/wp-content\/uploads\/2025\/07\/header-recipe2-768x257.jpg 768w, https:\/\/dutchhealthstore.com\/wp-content\/uploads\/2025\/07\/header-recipe2-149x50.jpg 149w, https:\/\/dutchhealthstore.com\/wp-content\/uploads\/2025\/07\/header-recipe2-530x178.jpg 530w, https:\/\/dutchhealthstore.com\/wp-content\/uploads\/2025\/07\/header-recipe2-64x21.jpg 64w, https:\/\/dutchhealthstore.com\/wp-content\/uploads\/2025\/07\/header-recipe2.jpg 1390w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t<\/a>\n  \t\t\t\t\t\t\t  \t\t\t\t\t\t\t  \t\t\t\t\t\t<\/div>\n  \t\t\t\t\t\t  \t\t\t\t\t<\/div>\n          \t\t\t\t\t<div class=\"box-text text-center\" >\n\t\t\t\t\t<div class=\"box-text-inner blog-post-inner\">\n\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<h5 class=\"post-title is-large \">\n\t\t\t\t\t\t<a href=\"https:\/\/dutchhealthstore.com\/nl\/recipe-italian-vegetable-stew-with-cauliflower-rice\/\" class=\"plain\">(Recipe) Italian Vegetable Stew with Cauliflower Rice<\/a>\n\t\t\t\t\t<\/h5>\n\t\t\t\t\t\t\t\t\t\t<div class=\"is-divider\"><\/div>\n\t\t\t\t\t\t\t\t\t\t<p class=\"from_the_blog_excerpt \">\n\t\t\t\t\t\tLooking for a warm, hearty dish that's both nourishing and low in carbs? This Mediterranean-inspired [...]\t\t\t\t\t<\/p>\n\t\t\t\t\t                    \n\t\t\t\t\t\n\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"badge absolute top post-date badge-square\">\n\t\t\t\t\t\t\t<div class=\"badge-inner\">\n\t\t\t\t\t\t\t\t<span class=\"post-date-day\">24<\/span><br>\n\t\t\t\t\t\t\t\t<span class=\"post-date-month is-xsmall\">jul<\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div><div class=\"col post-item\" >\n\t\t\t<div class=\"col-inner\">\n\t\t\t\t<div class=\"box box-normal box-text-bottom box-blog-post has-hover\">\n            \t\t\t\t\t<div class=\"box-image\" >\n  \t\t\t\t\t\t<div class=\"image-cover\" style=\"padding-top:32%;\">\n\t\t\t\t\t\t\t<a href=\"https:\/\/dutchhealthstore.com\/nl\/recipe-frozen-mint-lemonade\/\" class=\"plain\" aria-label=\"(Recipe) Frozen Mint Lemonade\">\n\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"268\" src=\"https:\/\/dutchhealthstore.com\/wp-content\/uploads\/2024\/07\/recipe-02-800x268.jpg\" class=\"attachment-medium size-medium wp-post-image\" alt=\"\" srcset=\"https:\/\/dutchhealthstore.com\/wp-content\/uploads\/2024\/07\/recipe-02-800x268.jpg 800w, https:\/\/dutchhealthstore.com\/wp-content\/uploads\/2024\/07\/recipe-02-768x257.jpg 768w, https:\/\/dutchhealthstore.com\/wp-content\/uploads\/2024\/07\/recipe-02-530x178.jpg 530w, https:\/\/dutchhealthstore.com\/wp-content\/uploads\/2024\/07\/recipe-02-64x21.jpg 64w, https:\/\/dutchhealthstore.com\/wp-content\/uploads\/2024\/07\/recipe-02.jpg 1390w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t<\/a>\n  \t\t\t\t\t\t\t  \t\t\t\t\t\t\t  \t\t\t\t\t\t<\/div>\n  \t\t\t\t\t\t  \t\t\t\t\t<\/div>\n          \t\t\t\t\t<div class=\"box-text text-center\" >\n\t\t\t\t\t<div class=\"box-text-inner blog-post-inner\">\n\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<h5 class=\"post-title is-large \">\n\t\t\t\t\t\t<a href=\"https:\/\/dutchhealthstore.com\/nl\/recipe-frozen-mint-lemonade\/\" class=\"plain\">(Recipe) Frozen Mint Lemonade<\/a>\n\t\t\t\t\t<\/h5>\n\t\t\t\t\t\t\t\t\t\t<div class=\"is-divider\"><\/div>\n\t\t\t\t\t\t\t\t\t\t<p class=\"from_the_blog_excerpt \">\n\t\t\t\t\t\tAs the summer heats up, keeping yourself hydrated is crucial for maintaining healthy, glowing skin [...]\t\t\t\t\t<\/p>\n\t\t\t\t\t                    \n\t\t\t\t\t\n\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"badge absolute top post-date badge-square\">\n\t\t\t\t\t\t\t<div class=\"badge-inner\">\n\t\t\t\t\t\t\t\t<span class=\"post-date-day\">17<\/span><br>\n\t\t\t\t\t\t\t\t<span class=\"post-date-month is-xsmall\">jul<\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div><div class=\"col post-item\" >\n\t\t\t<div class=\"col-inner\">\n\t\t\t\t<div class=\"box box-normal box-text-bottom box-blog-post has-hover\">\n            \t\t\t\t\t<div class=\"box-image\" >\n  \t\t\t\t\t\t<div class=\"image-cover\" style=\"padding-top:32%;\">\n\t\t\t\t\t\t\t<a href=\"https:\/\/dutchhealthstore.com\/nl\/recipe-cold-cucumber-soup\/\" class=\"plain\" aria-label=\"(Recipe) Cold Cucumber Soup\">\n\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"268\" src=\"https:\/\/dutchhealthstore.com\/wp-content\/uploads\/2024\/06\/recipe-cucumber-soup-800x268.jpg\" class=\"attachment-medium size-medium wp-post-image\" alt=\"\" srcset=\"https:\/\/dutchhealthstore.com\/wp-content\/uploads\/2024\/06\/recipe-cucumber-soup-800x268.jpg 800w, https:\/\/dutchhealthstore.com\/wp-content\/uploads\/2024\/06\/recipe-cucumber-soup-768x257.jpg 768w, https:\/\/dutchhealthstore.com\/wp-content\/uploads\/2024\/06\/recipe-cucumber-soup-530x178.jpg 530w, https:\/\/dutchhealthstore.com\/wp-content\/uploads\/2024\/06\/recipe-cucumber-soup-64x21.jpg 64w, https:\/\/dutchhealthstore.com\/wp-content\/uploads\/2024\/06\/recipe-cucumber-soup.jpg 1390w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t<\/a>\n  \t\t\t\t\t\t\t  \t\t\t\t\t\t\t  \t\t\t\t\t\t<\/div>\n  \t\t\t\t\t\t  \t\t\t\t\t<\/div>\n          \t\t\t\t\t<div class=\"box-text text-center\" >\n\t\t\t\t\t<div class=\"box-text-inner blog-post-inner\">\n\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<h5 class=\"post-title is-large \">\n\t\t\t\t\t\t<a href=\"https:\/\/dutchhealthstore.com\/nl\/recipe-cold-cucumber-soup\/\" class=\"plain\">(Recipe) Cold Cucumber Soup<\/a>\n\t\t\t\t\t<\/h5>\n\t\t\t\t\t\t\t\t\t\t<div class=\"is-divider\"><\/div>\n\t\t\t\t\t\t\t\t\t\t<p class=\"from_the_blog_excerpt \">\n\t\t\t\t\t\tEven with the rainy weather in June here in the Netherlands, a refreshing dish can [...]\t\t\t\t\t<\/p>\n\t\t\t\t\t                    \n\t\t\t\t\t\n\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"badge absolute top post-date badge-square\">\n\t\t\t\t\t\t\t<div class=\"badge-inner\">\n\t\t\t\t\t\t\t\t<span class=\"post-date-day\">09<\/span><br>\n\t\t\t\t\t\t\t\t<span class=\"post-date-month is-xsmall\">jul<\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div><div class=\"col post-item\" >\n\t\t\t<div class=\"col-inner\">\n\t\t\t\t<div class=\"box box-normal box-text-bottom box-blog-post has-hover\">\n            \t\t\t\t\t<div class=\"box-image\" >\n  \t\t\t\t\t\t<div class=\"image-cover\" style=\"padding-top:32%;\">\n\t\t\t\t\t\t\t<a href=\"https:\/\/dutchhealthstore.com\/nl\/recipe-creamy-greek-frozen-yogurt\/\" class=\"plain\" aria-label=\"(Recipe) Creamy Greek Frozen Yogurt\">\n\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"268\" src=\"https:\/\/dutchhealthstore.com\/wp-content\/uploads\/2026\/07\/receptijs-800x268.jpg\" class=\"attachment-medium size-medium wp-post-image\" alt=\"\" srcset=\"https:\/\/dutchhealthstore.com\/wp-content\/uploads\/2026\/07\/receptijs-800x268.jpg 800w, https:\/\/dutchhealthstore.com\/wp-content\/uploads\/2026\/07\/receptijs-768x257.jpg 768w, https:\/\/dutchhealthstore.com\/wp-content\/uploads\/2026\/07\/receptijs-149x50.jpg 149w, https:\/\/dutchhealthstore.com\/wp-content\/uploads\/2026\/07\/receptijs-530x178.jpg 530w, https:\/\/dutchhealthstore.com\/wp-content\/uploads\/2026\/07\/receptijs-64x21.jpg 64w, https:\/\/dutchhealthstore.com\/wp-content\/uploads\/2026\/07\/receptijs.jpg 1390w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t<\/a>\n  \t\t\t\t\t\t\t  \t\t\t\t\t\t\t  \t\t\t\t\t\t<\/div>\n  \t\t\t\t\t\t  \t\t\t\t\t<\/div>\n          \t\t\t\t\t<div class=\"box-text text-center\" >\n\t\t\t\t\t<div class=\"box-text-inner blog-post-inner\">\n\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<h5 class=\"post-title is-large \">\n\t\t\t\t\t\t<a href=\"https:\/\/dutchhealthstore.com\/nl\/recipe-creamy-greek-frozen-yogurt\/\" class=\"plain\">(Recipe) Creamy Greek Frozen Yogurt<\/a>\n\t\t\t\t\t<\/h5>\n\t\t\t\t\t\t\t\t\t\t<div class=\"is-divider\"><\/div>\n\t\t\t\t\t\t\t\t\t\t<p class=\"from_the_blog_excerpt \">\n\t\t\t\t\t\tLooking for a healthier frozen treat this summer? This creamy Greek Frozen Yogurt is rich [...]\t\t\t\t\t<\/p>\n\t\t\t\t\t                    \n\t\t\t\t\t\n\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"badge absolute top post-date badge-square\">\n\t\t\t\t\t\t\t<div class=\"badge-inner\">\n\t\t\t\t\t\t\t\t<span class=\"post-date-day\">03<\/span><br>\n\t\t\t\t\t\t\t\t<span class=\"post-date-month is-xsmall\">jul<\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div><\/div>\n\n\n\t\t<\/div>\n\n\t\t\n<style>\n#section_915945346 {\n  padding-top: 59px;\n  padding-bottom: 59px;\n  min-height: 300px;\n  background-color: rgb(240, 240, 240);\n}\n#section_915945346 .section-bg-overlay {\n  background-color: rgba(255, 255, 255, 0.965);\n}\n<\/style>\n\t<\/section>\n\t\n","protected":false},"excerpt":{"rendered":"<p>Crispy gnocchi with spicy cheese and spicy pesto.<\/p>\n","protected":false},"author":7912,"featured_media":226410,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5286],"tags":[],"class_list":["post-226408","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-recipes"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.1 (Yoast SEO v28.1) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>(Recipe) Gnocchi with spicy cheese &amp; pesto<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dutchhealthstore.com\/nl\/recipe-gnocchi-met-pesto\/\" \/>\n<meta property=\"og:locale\" content=\"nl_NL\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"(Recipe) Gnocchi with spicy cheese &amp; pesto\" \/>\n<meta property=\"og:description\" content=\"Crispy gnocchi with spicy cheese and spicy pesto.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dutchhealthstore.com\/nl\/recipe-gnocchi-met-pesto\/\" \/>\n<meta property=\"og:site_name\" content=\"Dutch Health Store\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.instagram.com\/dutchhealthstore\/\" \/>\n<meta property=\"article:published_time\" content=\"2022-12-02T08:45:31+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dutchhealthstore.com\/wp-content\/uploads\/2022\/12\/recipe-gnocchi.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"400\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Melissa\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@melissastruik@live.nl\" \/>\n<meta name=\"twitter:label1\" content=\"Geschreven door\" \/>\n\t<meta name=\"twitter:data1\" content=\"Melissa\" \/>\n\t<meta name=\"twitter:label2\" content=\"Geschatte leestijd\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/dutchhealthstore.com\\\/nl\\\/recipe-gnocchi-met-pesto\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dutchhealthstore.com\\\/nl\\\/recipe-gnocchi-met-pesto\\\/\"},\"author\":{\"name\":\"Melissa\",\"@id\":\"https:\\\/\\\/dutchhealthstore.com\\\/nl\\\/#\\\/schema\\\/person\\\/fc8338a651298850abd3add7442f50d7\"},\"headline\":\"(Recipe) Gnocchi with spicy cheese &#038; pesto\",\"datePublished\":\"2022-12-02T08:45:31+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/dutchhealthstore.com\\\/nl\\\/recipe-gnocchi-met-pesto\\\/\"},\"wordCount\":334,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/dutchhealthstore.com\\\/nl\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/dutchhealthstore.com\\\/nl\\\/recipe-gnocchi-met-pesto\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dutchhealthstore.com\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/recipe-gnocchi.jpg\",\"articleSection\":[\"Recipes\"],\"inLanguage\":\"nl-NL\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/dutchhealthstore.com\\\/nl\\\/recipe-gnocchi-met-pesto\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/dutchhealthstore.com\\\/nl\\\/recipe-gnocchi-met-pesto\\\/\",\"url\":\"https:\\\/\\\/dutchhealthstore.com\\\/nl\\\/recipe-gnocchi-met-pesto\\\/\",\"name\":\"(Recipe) Gnocchi with spicy cheese & pesto\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dutchhealthstore.com\\\/nl\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/dutchhealthstore.com\\\/nl\\\/recipe-gnocchi-met-pesto\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/dutchhealthstore.com\\\/nl\\\/recipe-gnocchi-met-pesto\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dutchhealthstore.com\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/recipe-gnocchi.jpg\",\"datePublished\":\"2022-12-02T08:45:31+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/dutchhealthstore.com\\\/nl\\\/recipe-gnocchi-met-pesto\\\/#breadcrumb\"},\"inLanguage\":\"nl-NL\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/dutchhealthstore.com\\\/nl\\\/recipe-gnocchi-met-pesto\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"nl-NL\",\"@id\":\"https:\\\/\\\/dutchhealthstore.com\\\/nl\\\/recipe-gnocchi-met-pesto\\\/#primaryimage\",\"url\":\"https:\\\/\\\/dutchhealthstore.com\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/recipe-gnocchi.jpg\",\"contentUrl\":\"https:\\\/\\\/dutchhealthstore.com\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/recipe-gnocchi.jpg\",\"width\":1200,\"height\":400},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/dutchhealthstore.com\\\/nl\\\/recipe-gnocchi-met-pesto\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/dutchhealthstore.com\\\/nl\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"(Recipe) Gnocchi with spicy cheese &#038; pesto\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/dutchhealthstore.com\\\/nl\\\/#website\",\"url\":\"https:\\\/\\\/dutchhealthstore.com\\\/nl\\\/\",\"name\":\"Dutch Health Store\",\"description\":\"Enhance Your Beauty with Organic &amp; Natural Skincare\",\"publisher\":{\"@id\":\"https:\\\/\\\/dutchhealthstore.com\\\/nl\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/dutchhealthstore.com\\\/nl\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"nl-NL\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/dutchhealthstore.com\\\/nl\\\/#organization\",\"name\":\"Dutch Health Store\",\"url\":\"https:\\\/\\\/dutchhealthstore.com\\\/nl\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"nl-NL\",\"@id\":\"https:\\\/\\\/dutchhealthstore.com\\\/nl\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/dutchhealthstore.com\\\/wp-content\\\/uploads\\\/2020\\\/08\\\/logo-dutchhealthstore-jpg-e1599484957574.jpg\",\"contentUrl\":\"https:\\\/\\\/dutchhealthstore.com\\\/wp-content\\\/uploads\\\/2020\\\/08\\\/logo-dutchhealthstore-jpg-e1599484957574.jpg\",\"width\":400,\"height\":62,\"caption\":\"Dutch Health Store\"},\"image\":{\"@id\":\"https:\\\/\\\/dutchhealthstore.com\\\/nl\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.instagram.com\\\/dutchhealthstore\\\/\",\"https:\\\/\\\/www.facebook.com\\\/dutchhealthstore\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/dutchhealthstore.com\\\/nl\\\/#\\\/schema\\\/person\\\/fc8338a651298850abd3add7442f50d7\",\"name\":\"Melissa\",\"sameAs\":[\"https:\\\/\\\/x.com\\\/melissastruik@live.nl\"],\"url\":\"https:\\\/\\\/dutchhealthstore.com\\\/nl\\\/author\\\/melissa\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"(Recipe) Gnocchi with spicy cheese & pesto","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dutchhealthstore.com\/nl\/recipe-gnocchi-met-pesto\/","og_locale":"nl_NL","og_type":"article","og_title":"(Recipe) Gnocchi with spicy cheese & pesto","og_description":"Crispy gnocchi with spicy cheese and spicy pesto.","og_url":"https:\/\/dutchhealthstore.com\/nl\/recipe-gnocchi-met-pesto\/","og_site_name":"Dutch Health Store","article_publisher":"https:\/\/www.instagram.com\/dutchhealthstore\/","article_published_time":"2022-12-02T08:45:31+00:00","og_image":[{"width":1200,"height":400,"url":"https:\/\/dutchhealthstore.com\/wp-content\/uploads\/2022\/12\/recipe-gnocchi.jpg","type":"image\/jpeg"}],"author":"Melissa","twitter_card":"summary_large_image","twitter_creator":"@melissastruik@live.nl","twitter_misc":{"Geschreven door":"Melissa","Geschatte leestijd":"2 minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/dutchhealthstore.com\/nl\/recipe-gnocchi-met-pesto\/#article","isPartOf":{"@id":"https:\/\/dutchhealthstore.com\/nl\/recipe-gnocchi-met-pesto\/"},"author":{"name":"Melissa","@id":"https:\/\/dutchhealthstore.com\/nl\/#\/schema\/person\/fc8338a651298850abd3add7442f50d7"},"headline":"(Recipe) Gnocchi with spicy cheese &#038; pesto","datePublished":"2022-12-02T08:45:31+00:00","mainEntityOfPage":{"@id":"https:\/\/dutchhealthstore.com\/nl\/recipe-gnocchi-met-pesto\/"},"wordCount":334,"commentCount":0,"publisher":{"@id":"https:\/\/dutchhealthstore.com\/nl\/#organization"},"image":{"@id":"https:\/\/dutchhealthstore.com\/nl\/recipe-gnocchi-met-pesto\/#primaryimage"},"thumbnailUrl":"https:\/\/dutchhealthstore.com\/wp-content\/uploads\/2022\/12\/recipe-gnocchi.jpg","articleSection":["Recipes"],"inLanguage":"nl-NL","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dutchhealthstore.com\/nl\/recipe-gnocchi-met-pesto\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/dutchhealthstore.com\/nl\/recipe-gnocchi-met-pesto\/","url":"https:\/\/dutchhealthstore.com\/nl\/recipe-gnocchi-met-pesto\/","name":"(Recipe) Gnocchi with spicy cheese & pesto","isPartOf":{"@id":"https:\/\/dutchhealthstore.com\/nl\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dutchhealthstore.com\/nl\/recipe-gnocchi-met-pesto\/#primaryimage"},"image":{"@id":"https:\/\/dutchhealthstore.com\/nl\/recipe-gnocchi-met-pesto\/#primaryimage"},"thumbnailUrl":"https:\/\/dutchhealthstore.com\/wp-content\/uploads\/2022\/12\/recipe-gnocchi.jpg","datePublished":"2022-12-02T08:45:31+00:00","breadcrumb":{"@id":"https:\/\/dutchhealthstore.com\/nl\/recipe-gnocchi-met-pesto\/#breadcrumb"},"inLanguage":"nl-NL","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dutchhealthstore.com\/nl\/recipe-gnocchi-met-pesto\/"]}]},{"@type":"ImageObject","inLanguage":"nl-NL","@id":"https:\/\/dutchhealthstore.com\/nl\/recipe-gnocchi-met-pesto\/#primaryimage","url":"https:\/\/dutchhealthstore.com\/wp-content\/uploads\/2022\/12\/recipe-gnocchi.jpg","contentUrl":"https:\/\/dutchhealthstore.com\/wp-content\/uploads\/2022\/12\/recipe-gnocchi.jpg","width":1200,"height":400},{"@type":"BreadcrumbList","@id":"https:\/\/dutchhealthstore.com\/nl\/recipe-gnocchi-met-pesto\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/dutchhealthstore.com\/nl\/"},{"@type":"ListItem","position":2,"name":"(Recipe) Gnocchi with spicy cheese &#038; pesto"}]},{"@type":"WebSite","@id":"https:\/\/dutchhealthstore.com\/nl\/#website","url":"https:\/\/dutchhealthstore.com\/nl\/","name":"Dutch Health Store","description":"Enhance Your Beauty with Organic &amp; Natural Skincare","publisher":{"@id":"https:\/\/dutchhealthstore.com\/nl\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dutchhealthstore.com\/nl\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"nl-NL"},{"@type":"Organization","@id":"https:\/\/dutchhealthstore.com\/nl\/#organization","name":"Dutch Health Store","url":"https:\/\/dutchhealthstore.com\/nl\/","logo":{"@type":"ImageObject","inLanguage":"nl-NL","@id":"https:\/\/dutchhealthstore.com\/nl\/#\/schema\/logo\/image\/","url":"https:\/\/dutchhealthstore.com\/wp-content\/uploads\/2020\/08\/logo-dutchhealthstore-jpg-e1599484957574.jpg","contentUrl":"https:\/\/dutchhealthstore.com\/wp-content\/uploads\/2020\/08\/logo-dutchhealthstore-jpg-e1599484957574.jpg","width":400,"height":62,"caption":"Dutch Health Store"},"image":{"@id":"https:\/\/dutchhealthstore.com\/nl\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.instagram.com\/dutchhealthstore\/","https:\/\/www.facebook.com\/dutchhealthstore"]},{"@type":"Person","@id":"https:\/\/dutchhealthstore.com\/nl\/#\/schema\/person\/fc8338a651298850abd3add7442f50d7","name":"Melissa","sameAs":["https:\/\/x.com\/melissastruik@live.nl"],"url":"https:\/\/dutchhealthstore.com\/nl\/author\/melissa\/"}]}},"_links":{"self":[{"href":"https:\/\/dutchhealthstore.com\/nl\/wp-json\/wp\/v2\/posts\/226408","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dutchhealthstore.com\/nl\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dutchhealthstore.com\/nl\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dutchhealthstore.com\/nl\/wp-json\/wp\/v2\/users\/7912"}],"replies":[{"embeddable":true,"href":"https:\/\/dutchhealthstore.com\/nl\/wp-json\/wp\/v2\/comments?post=226408"}],"version-history":[{"count":0,"href":"https:\/\/dutchhealthstore.com\/nl\/wp-json\/wp\/v2\/posts\/226408\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dutchhealthstore.com\/nl\/wp-json\/wp\/v2\/media\/226410"}],"wp:attachment":[{"href":"https:\/\/dutchhealthstore.com\/nl\/wp-json\/wp\/v2\/media?parent=226408"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dutchhealthstore.com\/nl\/wp-json\/wp\/v2\/categories?post=226408"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dutchhealthstore.com\/nl\/wp-json\/wp\/v2\/tags?post=226408"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}