{"id":102595,"date":"2020-05-23T02:30:51","date_gmt":"2020-05-23T02:30:51","guid":{"rendered":"https:\/\/dutchhealthstore.com\/?p=102595"},"modified":"2022-02-07T09:18:39","modified_gmt":"2022-02-07T09:18:39","slug":"recipe-irish-soda-bread","status":"publish","type":"post","link":"https:\/\/dutchhealthstore.com\/fr\/recipe-irish-soda-bread\/","title":{"rendered":"(Recipe) Irish Soda Bread"},"content":{"rendered":"\n\n\t<section class=\"section\" id=\"section_1007009244\">\n\t\t<div class=\"section-bg fill\" >\n\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"1080\" height=\"1080\" src=\"https:\/\/dutchhealthstore.com\/wp-content\/uploads\/2020\/05\/IMG_7890-irish-soda-bread.jpg\" class=\"bg attachment- size-\" alt=\"\" \/>\t\t\t\t\t\t<div class=\"section-bg-overlay absolute fill\"><\/div>\n\t\t\t\n\t<div class=\"is-border\"\n\t\tstyle=\"border-color:rgb(235, 235, 235);border-width:1px 0px 0px 0px;\">\n\t<\/div>\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n\n<div class=\"row row-large align-middle align-center\"  id=\"row-234466699\">\n\n\n\t<div id=\"col-1023197595\" class=\"col medium-7 small-12 large-7\"  >\n\t\t\t\t<div class=\"col-inner text-center\"  >\n\t\t\t\n\t\t\t\n\n<h2 style=\"text-align: left;\"><strong>Irish Soda Bread with wild garlic pesto<\/strong><\/h2>\n<p>&nbsp;<\/p>\n<h4 style=\"text-align: left;\">You can\u2019t beat the smell of freshly baked bread going through the house, and it\u2019s such a rewarding thing to learn how to make. The great thing about this easy to make recipe is that you can whack it straight in the oven without having to wait hours for the dough to rise.<\/h4>\n<h4 style=\"text-align: left;\"><span style=\"font-size: 150%;\"><strong>Bonus!<\/strong><\/span><\/h4>\n<p style=\"text-align: left;\">&nbsp;<\/p>\n<div class=\"recipe-detail time\" style=\"text-align: left;\"><strong><span class=\"detail_desc\">COOKS IN:&nbsp; &nbsp; <\/span>70 MINUTES<\/strong><\/div>\n<div class=\"recipe-detail difficulty not-too-tricky\" style=\"text-align: left;\"><strong><span class=\"detail_desc\">DIFFICULTY: <\/span>EASY<\/strong><\/div>\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-650397227\" class=\"col medium-5 small-12 large-5\"  >\n\t\t\t\t<div class=\"col-inner box-shadow-2 box-shadow-5-hover\" style=\"background-color:rgb(255, 255, 255);\" >\n\t\t\t\n\t\t\t\n\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_492796179\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img decoding=\"async\" width=\"800\" height=\"800\" src=\"https:\/\/dutchhealthstore.com\/wp-content\/uploads\/2020\/05\/IMG_7890-irish-soda-bread-800x800.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/dutchhealthstore.com\/wp-content\/uploads\/2020\/05\/IMG_7890-irish-soda-bread-800x800.jpg 800w, https:\/\/dutchhealthstore.com\/wp-content\/uploads\/2020\/05\/IMG_7890-irish-soda-bread-100x100.jpg 100w, https:\/\/dutchhealthstore.com\/wp-content\/uploads\/2020\/05\/IMG_7890-irish-soda-bread-510x510.jpg 510w, https:\/\/dutchhealthstore.com\/wp-content\/uploads\/2020\/05\/IMG_7890-irish-soda-bread-400x400.jpg 400w, https:\/\/dutchhealthstore.com\/wp-content\/uploads\/2020\/05\/IMG_7890-irish-soda-bread-280x280.jpg 280w, https:\/\/dutchhealthstore.com\/wp-content\/uploads\/2020\/05\/IMG_7890-irish-soda-bread-768x768.jpg 768w, https:\/\/dutchhealthstore.com\/wp-content\/uploads\/2020\/05\/IMG_7890-irish-soda-bread-150x150.jpg 150w, https:\/\/dutchhealthstore.com\/wp-content\/uploads\/2020\/05\/IMG_7890-irish-soda-bread-32x32.jpg 32w, https:\/\/dutchhealthstore.com\/wp-content\/uploads\/2020\/05\/IMG_7890-irish-soda-bread.jpg 1080w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_492796179 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\n\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-650397227 > .col-inner {\n  padding: 15px 15px 15px 15px;\n}\n<\/style>\n\t<\/div>\n\n\t\n\n<\/div>\n\n\t\t<\/div>\n\n\t\t\n<style>\n#section_1007009244 {\n  padding-top: 59px;\n  padding-bottom: 59px;\n  min-height: 300px;\n  background-color: rgb(228, 228, 228);\n}\n#section_1007009244 .section-bg-overlay {\n  background-color: rgba(255, 255, 255, 0.88);\n}\n<\/style>\n\t<\/section>\n\t\n<div class=\"row\"  id=\"row-1225488834\">\n\n\n\t<div id=\"col-345798790\" class=\"col medium-6 small-12 large-6\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n<h2>Method **<\/h2>\n<ol>\n<li>Preheat the oven to 180-200 degrees<\/li>\n<li>Mix the dry ingredients in a bowl and then rub in the butter<\/li>\n<li>Pour in the milk and yoghurt and mix quickly together<\/li>\n<li>Bring the dough together with your fingertips, don\u2019t knead, be gentle!<\/li>\n<li>Shape it into a circular but flat shape<\/li>\n<img decoding=\"async\" class=\"alignright  wp-image-102663\" src=\"https:\/\/dutchhealthstore.com\/wp-content\/uploads\/2020\/05\/additional.png\" alt=\"\" width=\"224\" height=\"100\" srcset=\"https:\/\/dutchhealthstore.com\/wp-content\/uploads\/2020\/05\/additional.png 617w, https:\/\/dutchhealthstore.com\/wp-content\/uploads\/2020\/05\/additional-510x226.png 510w\" sizes=\"(max-width: 224px) 100vw, 224px\" \/><li>Draw a cross in the centre with a knife<\/li>\n<li>Bake for 30-35 minutes.<\/li>\n<\/ol>\n<h4><em>Additional option **<\/em><\/h4>\n<ul>\n<li>2 big handfuls of wild garlic\/ramson leaves<\/li>\n<li>75g of pine nuts or walnuts or hazel nuts<\/li>\n<li>2 tbsp nutritional yeast<\/li>\n<li>3 tbsp olive oil<\/li>\n<li>Salt &amp; pepper<\/li>\n<\/ul>\n<p><strong>Wash the wild garlic<\/strong><br><strong>Add all ingredients to a food processor and blitz!<\/strong><\/p>\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-358095362\" class=\"col medium-6 small-12 large-6\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n<h2>Ingredients<\/h2>\n<ul>\n<li>250g plain white flour<\/li>\n<li>250g wholemeal flour<\/li>\n<li>100g oats<\/li>\n<li>1tsp bicarbonate of soda<\/li>\n<li>1tsp salt<\/li>\n<li>25g butter<\/li>\n<li>300ml milk\/plant milk<\/li>\n<li>200g yoghurt \u2013 hazelnut is best!<\/li>\n<\/ul>\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n<\/div>\n<div class=\"row\"  id=\"row-370601720\">\n\n\n<\/div>\n\n  \n    <div class=\"row large-columns-3 medium-columns-1 small-columns-1 slider row-slider slider-nav-reveal slider-nav-push\"  data-flickity-options='{&quot;imagesLoaded&quot;: true, &quot;groupCells&quot;: &quot;100%&quot;, &quot;dragThreshold&quot; : 5, &quot;cellAlign&quot;: &quot;left&quot;,&quot;wrapAround&quot;: true,&quot;prevNextButtons&quot;: true,&quot;percentPosition&quot;: true,&quot;pageDots&quot;: false, &quot;rightToLeft&quot;: false, &quot;autoPlay&quot; : false}' >\n\n  <div class=\"col post-item\" >\n\t\t\t<div class=\"col-inner\">\n\t\t\t\t<div class=\"box box-normal box-text-bottom box-blog-post has-hover\">\n            \t\t\t\t\t<div class=\"box-image\" >\n  \t\t\t\t\t\t<div class=\"image-cover\" style=\"padding-top:56.25%;\">\n\t\t\t\t\t\t\t<a href=\"https:\/\/dutchhealthstore.com\/fr\/recipe-vitamin-c-immunity-smoothie\/\" class=\"plain\" aria-label=\"(Recipe) Vitamin C Immunity Smoothie\">\n\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"254\" src=\"https:\/\/dutchhealthstore.com\/wp-content\/uploads\/2023\/03\/recipe-smoothie-800x254.jpg\" class=\"attachment-medium size-medium wp-post-image\" alt=\"Vitamin C Immunity Smoothie\" srcset=\"https:\/\/dutchhealthstore.com\/wp-content\/uploads\/2023\/03\/recipe-smoothie-800x254.jpg 800w, https:\/\/dutchhealthstore.com\/wp-content\/uploads\/2023\/03\/recipe-smoothie-768x244.jpg 768w, https:\/\/dutchhealthstore.com\/wp-content\/uploads\/2023\/03\/recipe-smoothie-510x162.jpg 510w, https:\/\/dutchhealthstore.com\/wp-content\/uploads\/2023\/03\/recipe-smoothie-64x20.jpg 64w, https:\/\/dutchhealthstore.com\/wp-content\/uploads\/2023\/03\/recipe-smoothie.jpg 1200w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t<\/a>\n  \t\t\t\t\t\t\t  \t\t\t\t\t\t\t  \t\t\t\t\t\t<\/div>\n  \t\t\t\t\t\t  \t\t\t\t\t<\/div>\n          \t\t\t\t\t<div class=\"box-text text-center\" >\n\t\t\t\t\t<div class=\"box-text-inner blog-post-inner\">\n\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<h5 class=\"post-title is-large \">\n\t\t\t\t\t\t<a href=\"https:\/\/dutchhealthstore.com\/fr\/recipe-vitamin-c-immunity-smoothie\/\" class=\"plain\">(Recipe) Vitamin C Immunity Smoothie<\/a>\n\t\t\t\t\t<\/h5>\n\t\t\t\t\t\t\t\t\t\t<div class=\"is-divider\"><\/div>\n\t\t\t\t\t\t\t\t\t\t<p class=\"from_the_blog_excerpt \">\n\t\t\t\t\t\tMade with fresh oranges, banana, mango, ginger and honey, this Vitamin C smoothie is bright, [...]\t\t\t\t\t<\/p>\n\t\t\t\t\t                    \n\t\t\t\t\t\n\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"badge absolute top post-date badge-square\">\n\t\t\t\t\t\t\t<div class=\"badge-inner\">\n\t\t\t\t\t\t\t\t<span class=\"post-date-day\">01<\/span><br>\n\t\t\t\t\t\t\t\t<span class=\"post-date-month is-xsmall\">Mai<\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div><div class=\"col post-item\" >\n\t\t\t<div class=\"col-inner\">\n\t\t\t\t<div class=\"box box-normal box-text-bottom box-blog-post has-hover\">\n            \t\t\t\t\t<div class=\"box-image\" >\n  \t\t\t\t\t\t<div class=\"image-cover\" style=\"padding-top:56.25%;\">\n\t\t\t\t\t\t\t<a href=\"https:\/\/dutchhealthstore.com\/fr\/recipe-panzanella-with-green-asparagus\/\" class=\"plain\" aria-label=\"(Recipe) Panzanella with Green Asparagus\">\n\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"268\" src=\"https:\/\/dutchhealthstore.com\/wp-content\/uploads\/2025\/04\/recipe-asp-800x268.jpg\" class=\"attachment-medium size-medium wp-post-image\" alt=\"\" srcset=\"https:\/\/dutchhealthstore.com\/wp-content\/uploads\/2025\/04\/recipe-asp-800x268.jpg 800w, https:\/\/dutchhealthstore.com\/wp-content\/uploads\/2025\/04\/recipe-asp-768x258.jpg 768w, https:\/\/dutchhealthstore.com\/wp-content\/uploads\/2025\/04\/recipe-asp-149x50.jpg 149w, https:\/\/dutchhealthstore.com\/wp-content\/uploads\/2025\/04\/recipe-asp-530x178.jpg 530w, https:\/\/dutchhealthstore.com\/wp-content\/uploads\/2025\/04\/recipe-asp-64x21.jpg 64w, https:\/\/dutchhealthstore.com\/wp-content\/uploads\/2025\/04\/recipe-asp.jpg 1020w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t<\/a>\n  \t\t\t\t\t\t\t  \t\t\t\t\t\t\t  \t\t\t\t\t\t<\/div>\n  \t\t\t\t\t\t  \t\t\t\t\t<\/div>\n          \t\t\t\t\t<div class=\"box-text text-center\" >\n\t\t\t\t\t<div class=\"box-text-inner blog-post-inner\">\n\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<h5 class=\"post-title is-large \">\n\t\t\t\t\t\t<a href=\"https:\/\/dutchhealthstore.com\/fr\/recipe-panzanella-with-green-asparagus\/\" class=\"plain\">(Recipe) Panzanella with Green Asparagus<\/a>\n\t\t\t\t\t<\/h5>\n\t\t\t\t\t\t\t\t\t\t<div class=\"is-divider\"><\/div>\n\t\t\t\t\t\t\t\t\t\t<p class=\"from_the_blog_excerpt \">\n\t\t\t\t\t\tSpring is in the air, and there's no better way to celebrate than with a [...]\t\t\t\t\t<\/p>\n\t\t\t\t\t                    \n\t\t\t\t\t\n\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"badge absolute top post-date badge-square\">\n\t\t\t\t\t\t\t<div class=\"badge-inner\">\n\t\t\t\t\t\t\t\t<span class=\"post-date-day\">17<\/span><br>\n\t\t\t\t\t\t\t\t<span class=\"post-date-month is-xsmall\">Avr<\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div><div class=\"col post-item\" >\n\t\t\t<div class=\"col-inner\">\n\t\t\t\t<div class=\"box box-normal box-text-bottom box-blog-post has-hover\">\n            \t\t\t\t\t<div class=\"box-image\" >\n  \t\t\t\t\t\t<div class=\"image-cover\" style=\"padding-top:56.25%;\">\n\t\t\t\t\t\t\t<a href=\"https:\/\/dutchhealthstore.com\/fr\/recipe-easter-spring-bread-with-spinach-and-peppers\/\" class=\"plain\" aria-label=\"(Recipe) Easter spring bread with spinach and peppers\">\n\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"270\" src=\"https:\/\/dutchhealthstore.com\/wp-content\/uploads\/2026\/04\/recipehead-800x270.jpg\" class=\"attachment-medium size-medium wp-post-image\" alt=\"\" srcset=\"https:\/\/dutchhealthstore.com\/wp-content\/uploads\/2026\/04\/recipehead-800x270.jpg 800w, https:\/\/dutchhealthstore.com\/wp-content\/uploads\/2026\/04\/recipehead-768x259.jpg 768w, https:\/\/dutchhealthstore.com\/wp-content\/uploads\/2026\/04\/recipehead-148x50.jpg 148w, https:\/\/dutchhealthstore.com\/wp-content\/uploads\/2026\/04\/recipehead-530x179.jpg 530w, https:\/\/dutchhealthstore.com\/wp-content\/uploads\/2026\/04\/recipehead-64x22.jpg 64w, https:\/\/dutchhealthstore.com\/wp-content\/uploads\/2026\/04\/recipehead.jpg 1400w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t<\/a>\n  \t\t\t\t\t\t\t  \t\t\t\t\t\t\t  \t\t\t\t\t\t<\/div>\n  \t\t\t\t\t\t  \t\t\t\t\t<\/div>\n          \t\t\t\t\t<div class=\"box-text text-center\" >\n\t\t\t\t\t<div class=\"box-text-inner blog-post-inner\">\n\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<h5 class=\"post-title is-large \">\n\t\t\t\t\t\t<a href=\"https:\/\/dutchhealthstore.com\/fr\/recipe-easter-spring-bread-with-spinach-and-peppers\/\" class=\"plain\">(Recipe) Easter spring bread with spinach and peppers<\/a>\n\t\t\t\t\t<\/h5>\n\t\t\t\t\t\t\t\t\t\t<div class=\"is-divider\"><\/div>\n\t\t\t\t\t\t\t\t\t\t<p class=\"from_the_blog_excerpt \">\n\t\t\t\t\t\tEaster is just around the corner \u2014 a time to slow down, enjoy good company, [...]\t\t\t\t\t<\/p>\n\t\t\t\t\t                    \n\t\t\t\t\t\n\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"badge absolute top post-date badge-square\">\n\t\t\t\t\t\t\t<div class=\"badge-inner\">\n\t\t\t\t\t\t\t\t<span class=\"post-date-day\">03<\/span><br>\n\t\t\t\t\t\t\t\t<span class=\"post-date-month is-xsmall\">Avr<\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div><div class=\"col post-item\" >\n\t\t\t<div class=\"col-inner\">\n\t\t\t\t<div class=\"box box-normal box-text-bottom box-blog-post has-hover\">\n            \t\t\t\t\t<div class=\"box-image\" >\n  \t\t\t\t\t\t<div class=\"image-cover\" style=\"padding-top:56.25%;\">\n\t\t\t\t\t\t\t<a href=\"https:\/\/dutchhealthstore.com\/fr\/recipe-apple-oat-cookies-with-dark-chocolate\/\" class=\"plain\" aria-label=\"(Recipe) Apple Oat Cookies with Dark Chocolate\">\n\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"267\" src=\"https:\/\/dutchhealthstore.com\/wp-content\/uploads\/2026\/03\/recept4-800x267.png\" class=\"attachment-medium size-medium wp-post-image\" alt=\"\" srcset=\"https:\/\/dutchhealthstore.com\/wp-content\/uploads\/2026\/03\/recept4-800x267.png 800w, https:\/\/dutchhealthstore.com\/wp-content\/uploads\/2026\/03\/recept4-768x256.png 768w, https:\/\/dutchhealthstore.com\/wp-content\/uploads\/2026\/03\/recept4-150x50.png 150w, https:\/\/dutchhealthstore.com\/wp-content\/uploads\/2026\/03\/recept4-530x177.png 530w, https:\/\/dutchhealthstore.com\/wp-content\/uploads\/2026\/03\/recept4-64x21.png 64w, https:\/\/dutchhealthstore.com\/wp-content\/uploads\/2026\/03\/recept4.png 1200w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t<\/a>\n  \t\t\t\t\t\t\t  \t\t\t\t\t\t\t  \t\t\t\t\t\t<\/div>\n  \t\t\t\t\t\t  \t\t\t\t\t<\/div>\n          \t\t\t\t\t<div class=\"box-text text-center\" >\n\t\t\t\t\t<div class=\"box-text-inner blog-post-inner\">\n\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<h5 class=\"post-title is-large \">\n\t\t\t\t\t\t<a href=\"https:\/\/dutchhealthstore.com\/fr\/recipe-apple-oat-cookies-with-dark-chocolate\/\" class=\"plain\">(Recipe) Apple Oat Cookies with Dark Chocolate<\/a>\n\t\t\t\t\t<\/h5>\n\t\t\t\t\t\t\t\t\t\t<div class=\"is-divider\"><\/div>\n\t\t\t\t\t\t\t\t\t\t<p class=\"from_the_blog_excerpt \">\n\t\t\t\t\t\tLooking for a wholesome treat that feels indulgent without the guilt? These apple oat cookies [...]\t\t\t\t\t<\/p>\n\t\t\t\t\t                    \n\t\t\t\t\t\n\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"badge absolute top post-date badge-square\">\n\t\t\t\t\t\t\t<div class=\"badge-inner\">\n\t\t\t\t\t\t\t\t<span class=\"post-date-day\">27<\/span><br>\n\t\t\t\t\t\t\t\t<span class=\"post-date-month is-xsmall\">Mar<\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div><div class=\"col post-item\" >\n\t\t\t<div class=\"col-inner\">\n\t\t\t\t<div class=\"box box-normal box-text-bottom box-blog-post has-hover\">\n            \t\t\t\t\t<div class=\"box-image\" >\n  \t\t\t\t\t\t<div class=\"image-cover\" style=\"padding-top:56.25%;\">\n\t\t\t\t\t\t\t<a href=\"https:\/\/dutchhealthstore.com\/fr\/recipe-spring-dumplings-with-pak-choi-minced-filling\/\" class=\"plain\" aria-label=\"(Recipe) Spring dumplings with pak Choi &amp; Minced filling\">\n\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"268\" src=\"https:\/\/dutchhealthstore.com\/wp-content\/uploads\/2025\/04\/recipe-2-800x268.jpg\" class=\"attachment-medium size-medium wp-post-image\" alt=\"\" srcset=\"https:\/\/dutchhealthstore.com\/wp-content\/uploads\/2025\/04\/recipe-2-800x268.jpg 800w, https:\/\/dutchhealthstore.com\/wp-content\/uploads\/2025\/04\/recipe-2-768x257.jpg 768w, https:\/\/dutchhealthstore.com\/wp-content\/uploads\/2025\/04\/recipe-2-149x50.jpg 149w, https:\/\/dutchhealthstore.com\/wp-content\/uploads\/2025\/04\/recipe-2-530x178.jpg 530w, https:\/\/dutchhealthstore.com\/wp-content\/uploads\/2025\/04\/recipe-2-64x21.jpg 64w, https:\/\/dutchhealthstore.com\/wp-content\/uploads\/2025\/04\/recipe-2.jpg 1390w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t<\/a>\n  \t\t\t\t\t\t\t  \t\t\t\t\t\t\t  \t\t\t\t\t\t<\/div>\n  \t\t\t\t\t\t  \t\t\t\t\t<\/div>\n          \t\t\t\t\t<div class=\"box-text text-center\" >\n\t\t\t\t\t<div class=\"box-text-inner blog-post-inner\">\n\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<h5 class=\"post-title is-large \">\n\t\t\t\t\t\t<a href=\"https:\/\/dutchhealthstore.com\/fr\/recipe-spring-dumplings-with-pak-choi-minced-filling\/\" class=\"plain\">(Recipe) Spring dumplings with pak Choi &amp; Minced filling<\/a>\n\t\t\t\t\t<\/h5>\n\t\t\t\t\t\t\t\t\t\t<div class=\"is-divider\"><\/div>\n\t\t\t\t\t\t\t\t\t\t<p class=\"from_the_blog_excerpt \">\n\t\t\t\t\t\tWelcome the fresh flavors of spring with these crisp, golden dumplings filled with tender pak [...]\t\t\t\t\t<\/p>\n\t\t\t\t\t                    \n\t\t\t\t\t\n\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"badge absolute top post-date badge-square\">\n\t\t\t\t\t\t\t<div class=\"badge-inner\">\n\t\t\t\t\t\t\t\t<span class=\"post-date-day\">20<\/span><br>\n\t\t\t\t\t\t\t\t<span class=\"post-date-month is-xsmall\">Mar<\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div><div class=\"col post-item\" >\n\t\t\t<div class=\"col-inner\">\n\t\t\t\t<div class=\"box box-normal box-text-bottom box-blog-post has-hover\">\n            \t\t\t\t\t<div class=\"box-image\" >\n  \t\t\t\t\t\t<div class=\"image-cover\" style=\"padding-top:56.25%;\">\n\t\t\t\t\t\t\t<a href=\"https:\/\/dutchhealthstore.com\/fr\/recipe-sweet-potato-waffles-with-spinach-cheese\/\" class=\"plain\" aria-label=\"(Recipe) Sweet potato waffles with Spinach &amp; Cheese\">\n\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"267\" src=\"https:\/\/dutchhealthstore.com\/wp-content\/uploads\/2025\/02\/Recipe-header-spinach-800x267.jpg\" class=\"attachment-medium size-medium wp-post-image\" alt=\"\" srcset=\"https:\/\/dutchhealthstore.com\/wp-content\/uploads\/2025\/02\/Recipe-header-spinach-800x267.jpg 800w, https:\/\/dutchhealthstore.com\/wp-content\/uploads\/2025\/02\/Recipe-header-spinach-768x256.jpg 768w, https:\/\/dutchhealthstore.com\/wp-content\/uploads\/2025\/02\/Recipe-header-spinach-150x50.jpg 150w, https:\/\/dutchhealthstore.com\/wp-content\/uploads\/2025\/02\/Recipe-header-spinach-530x177.jpg 530w, https:\/\/dutchhealthstore.com\/wp-content\/uploads\/2025\/02\/Recipe-header-spinach-64x21.jpg 64w, https:\/\/dutchhealthstore.com\/wp-content\/uploads\/2025\/02\/Recipe-header-spinach.jpg 1200w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t<\/a>\n  \t\t\t\t\t\t\t  \t\t\t\t\t\t\t  \t\t\t\t\t\t<\/div>\n  \t\t\t\t\t\t  \t\t\t\t\t<\/div>\n          \t\t\t\t\t<div class=\"box-text text-center\" >\n\t\t\t\t\t<div class=\"box-text-inner blog-post-inner\">\n\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<h5 class=\"post-title is-large \">\n\t\t\t\t\t\t<a href=\"https:\/\/dutchhealthstore.com\/fr\/recipe-sweet-potato-waffles-with-spinach-cheese\/\" class=\"plain\">(Recipe) Sweet potato waffles with Spinach &amp; Cheese<\/a>\n\t\t\t\t\t<\/h5>\n\t\t\t\t\t\t\t\t\t\t<div class=\"is-divider\"><\/div>\n\t\t\t\t\t\t\t\t\t\t<p class=\"from_the_blog_excerpt \">\n\t\t\t\t\t\tLooking for a nutritious and savory twist on traditional waffles? These sweet potato waffles combine [...]\t\t\t\t\t<\/p>\n\t\t\t\t\t                    \n\t\t\t\t\t\n\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"badge absolute top post-date badge-square\">\n\t\t\t\t\t\t\t<div class=\"badge-inner\">\n\t\t\t\t\t\t\t\t<span class=\"post-date-day\">13<\/span><br>\n\t\t\t\t\t\t\t\t<span class=\"post-date-month is-xsmall\">Mar<\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div><div class=\"col post-item\" >\n\t\t\t<div class=\"col-inner\">\n\t\t\t\t<div class=\"box box-normal box-text-bottom box-blog-post has-hover\">\n            \t\t\t\t\t<div class=\"box-image\" >\n  \t\t\t\t\t\t<div class=\"image-cover\" style=\"padding-top:56.25%;\">\n\t\t\t\t\t\t\t<a href=\"https:\/\/dutchhealthstore.com\/fr\/recipe-spring-roll-salad\/\" class=\"plain\" aria-label=\"(Recipe) Spring Roll Salad\">\n\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"268\" src=\"https:\/\/dutchhealthstore.com\/wp-content\/uploads\/2025\/05\/recipe-header-2-800x268.jpg\" class=\"attachment-medium size-medium wp-post-image\" alt=\"\" srcset=\"https:\/\/dutchhealthstore.com\/wp-content\/uploads\/2025\/05\/recipe-header-2-800x268.jpg 800w, https:\/\/dutchhealthstore.com\/wp-content\/uploads\/2025\/05\/recipe-header-2-768x257.jpg 768w, https:\/\/dutchhealthstore.com\/wp-content\/uploads\/2025\/05\/recipe-header-2-149x50.jpg 149w, https:\/\/dutchhealthstore.com\/wp-content\/uploads\/2025\/05\/recipe-header-2-530x178.jpg 530w, https:\/\/dutchhealthstore.com\/wp-content\/uploads\/2025\/05\/recipe-header-2-64x21.jpg 64w, https:\/\/dutchhealthstore.com\/wp-content\/uploads\/2025\/05\/recipe-header-2.jpg 1390w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t<\/a>\n  \t\t\t\t\t\t\t  \t\t\t\t\t\t\t  \t\t\t\t\t\t<\/div>\n  \t\t\t\t\t\t  \t\t\t\t\t<\/div>\n          \t\t\t\t\t<div class=\"box-text text-center\" >\n\t\t\t\t\t<div class=\"box-text-inner blog-post-inner\">\n\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<h5 class=\"post-title is-large \">\n\t\t\t\t\t\t<a href=\"https:\/\/dutchhealthstore.com\/fr\/recipe-spring-roll-salad\/\" class=\"plain\">(Recipe) Spring Roll Salad<\/a>\n\t\t\t\t\t<\/h5>\n\t\t\t\t\t\t\t\t\t\t<div class=\"is-divider\"><\/div>\n\t\t\t\t\t\t\t\t\t\t<p class=\"from_the_blog_excerpt \">\n\t\t\t\t\t\tThis Healthy Spring Roll Salad brings together all the bright flavors and satisfying crunch of [...]\t\t\t\t\t<\/p>\n\t\t\t\t\t                    \n\t\t\t\t\t\n\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"badge absolute top post-date badge-square\">\n\t\t\t\t\t\t\t<div class=\"badge-inner\">\n\t\t\t\t\t\t\t\t<span class=\"post-date-day\">27<\/span><br>\n\t\t\t\t\t\t\t\t<span class=\"post-date-month is-xsmall\">F\u00e9v<\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div><div class=\"col post-item\" >\n\t\t\t<div class=\"col-inner\">\n\t\t\t\t<div class=\"box box-normal box-text-bottom box-blog-post has-hover\">\n            \t\t\t\t\t<div class=\"box-image\" >\n  \t\t\t\t\t\t<div class=\"image-cover\" style=\"padding-top:56.25%;\">\n\t\t\t\t\t\t\t<a href=\"https:\/\/dutchhealthstore.com\/fr\/recipe-sauerkraut-tortilla-with-carrot-crispy-bacon\/\" class=\"plain\" aria-label=\"(Recipe) Sauerkraut Tortilla with Carrot &amp; Crispy Bacon\">\n\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"267\" src=\"https:\/\/dutchhealthstore.com\/wp-content\/uploads\/2026\/02\/sauerkrauttortilla-800x267.jpg\" class=\"attachment-medium size-medium wp-post-image\" alt=\"\" srcset=\"https:\/\/dutchhealthstore.com\/wp-content\/uploads\/2026\/02\/sauerkrauttortilla-800x267.jpg 800w, https:\/\/dutchhealthstore.com\/wp-content\/uploads\/2026\/02\/sauerkrauttortilla-768x256.jpg 768w, https:\/\/dutchhealthstore.com\/wp-content\/uploads\/2026\/02\/sauerkrauttortilla-150x50.jpg 150w, https:\/\/dutchhealthstore.com\/wp-content\/uploads\/2026\/02\/sauerkrauttortilla-530x177.jpg 530w, https:\/\/dutchhealthstore.com\/wp-content\/uploads\/2026\/02\/sauerkrauttortilla-64x21.jpg 64w, https:\/\/dutchhealthstore.com\/wp-content\/uploads\/2026\/02\/sauerkrauttortilla.jpg 1200w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t<\/a>\n  \t\t\t\t\t\t\t  \t\t\t\t\t\t\t  \t\t\t\t\t\t<\/div>\n  \t\t\t\t\t\t  \t\t\t\t\t<\/div>\n          \t\t\t\t\t<div class=\"box-text text-center\" >\n\t\t\t\t\t<div class=\"box-text-inner blog-post-inner\">\n\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<h5 class=\"post-title is-large \">\n\t\t\t\t\t\t<a href=\"https:\/\/dutchhealthstore.com\/fr\/recipe-sauerkraut-tortilla-with-carrot-crispy-bacon\/\" class=\"plain\">(Recipe) Sauerkraut Tortilla with Carrot &amp; Crispy Bacon<\/a>\n\t\t\t\t\t<\/h5>\n\t\t\t\t\t\t\t\t\t\t<div class=\"is-divider\"><\/div>\n\t\t\t\t\t\t\t\t\t\t<p class=\"from_the_blog_excerpt \">\n\t\t\t\t\t\tIf you\u2019re looking for something hearty yet fresh, this sauerkraut tortilla is a beautiful in-between [...]\t\t\t\t\t<\/p>\n\t\t\t\t\t                    \n\t\t\t\t\t\n\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"badge absolute top post-date badge-square\">\n\t\t\t\t\t\t\t<div class=\"badge-inner\">\n\t\t\t\t\t\t\t\t<span class=\"post-date-day\">20<\/span><br>\n\t\t\t\t\t\t\t\t<span class=\"post-date-month is-xsmall\">F\u00e9v<\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div><\/div>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":7912,"featured_media":102601,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5286],"tags":[],"class_list":["post-102595","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-recipes"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.5 (Yoast SEO v26.5) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>(Recipe) Irish Soda Bread<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dutchhealthstore.com\/fr\/recipe-irish-soda-bread\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"(Recipe) Irish Soda Bread\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dutchhealthstore.com\/fr\/recipe-irish-soda-bread\/\" \/>\n<meta property=\"og:site_name\" content=\"Dutch Health Store\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.instagram.com\/dutchhealthstore\/\" \/>\n<meta property=\"article:published_time\" content=\"2020-05-23T02:30:51+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-02-07T09:18:39+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dutchhealthstore.com\/wp-content\/uploads\/2020\/05\/recipe-irish-soda-bread-dutch-health-store.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1390\" \/>\n\t<meta property=\"og:image:height\" content=\"466\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Melissa\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@melissastruik@live.nl\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Melissa\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/dutchhealthstore.com\/fr\/recipe-irish-soda-bread\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/dutchhealthstore.com\/fr\/recipe-irish-soda-bread\/\"},\"author\":{\"name\":\"Melissa\",\"@id\":\"https:\/\/dutchhealthstore.com\/fr\/#\/schema\/person\/fc8338a651298850abd3add7442f50d7\"},\"headline\":\"(Recipe) Irish Soda Bread\",\"datePublished\":\"2020-05-23T02:30:51+00:00\",\"dateModified\":\"2022-02-07T09:18:39+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/dutchhealthstore.com\/fr\/recipe-irish-soda-bread\/\"},\"wordCount\":292,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/dutchhealthstore.com\/fr\/#organization\"},\"image\":{\"@id\":\"https:\/\/dutchhealthstore.com\/fr\/recipe-irish-soda-bread\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dutchhealthstore.com\/wp-content\/uploads\/2020\/05\/recipe-irish-soda-bread-dutch-health-store.jpg\",\"articleSection\":[\"Recipes\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/dutchhealthstore.com\/fr\/recipe-irish-soda-bread\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dutchhealthstore.com\/fr\/recipe-irish-soda-bread\/\",\"url\":\"https:\/\/dutchhealthstore.com\/fr\/recipe-irish-soda-bread\/\",\"name\":\"(Recipe) Irish Soda Bread\",\"isPartOf\":{\"@id\":\"https:\/\/dutchhealthstore.com\/fr\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/dutchhealthstore.com\/fr\/recipe-irish-soda-bread\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/dutchhealthstore.com\/fr\/recipe-irish-soda-bread\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dutchhealthstore.com\/wp-content\/uploads\/2020\/05\/recipe-irish-soda-bread-dutch-health-store.jpg\",\"datePublished\":\"2020-05-23T02:30:51+00:00\",\"dateModified\":\"2022-02-07T09:18:39+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/dutchhealthstore.com\/fr\/recipe-irish-soda-bread\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dutchhealthstore.com\/fr\/recipe-irish-soda-bread\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dutchhealthstore.com\/fr\/recipe-irish-soda-bread\/#primaryimage\",\"url\":\"https:\/\/dutchhealthstore.com\/wp-content\/uploads\/2020\/05\/recipe-irish-soda-bread-dutch-health-store.jpg\",\"contentUrl\":\"https:\/\/dutchhealthstore.com\/wp-content\/uploads\/2020\/05\/recipe-irish-soda-bread-dutch-health-store.jpg\",\"width\":1390,\"height\":466},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dutchhealthstore.com\/fr\/recipe-irish-soda-bread\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/dutchhealthstore.com\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"(Recipe) Irish Soda Bread\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dutchhealthstore.com\/fr\/#website\",\"url\":\"https:\/\/dutchhealthstore.com\/fr\/\",\"name\":\"Dutch Health Store\",\"description\":\"Enhance Your Beauty with Organic &amp; Natural Skincare\",\"publisher\":{\"@id\":\"https:\/\/dutchhealthstore.com\/fr\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dutchhealthstore.com\/fr\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/dutchhealthstore.com\/fr\/#organization\",\"name\":\"Dutch Health Store\",\"url\":\"https:\/\/dutchhealthstore.com\/fr\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dutchhealthstore.com\/fr\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dutchhealthstore.com\/wp-content\/uploads\/2020\/08\/logo-dutchhealthstore-jpg-e1599484957574.jpg\",\"contentUrl\":\"https:\/\/dutchhealthstore.com\/wp-content\/uploads\/2020\/08\/logo-dutchhealthstore-jpg-e1599484957574.jpg\",\"width\":400,\"height\":62,\"caption\":\"Dutch Health Store\"},\"image\":{\"@id\":\"https:\/\/dutchhealthstore.com\/fr\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.instagram.com\/dutchhealthstore\/\",\"https:\/\/www.facebook.com\/dutchhealthstore\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/dutchhealthstore.com\/fr\/#\/schema\/person\/fc8338a651298850abd3add7442f50d7\",\"name\":\"Melissa\",\"sameAs\":[\"https:\/\/x.com\/melissastruik@live.nl\"],\"url\":\"https:\/\/dutchhealthstore.com\/fr\/author\/melissa\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"(Recipe) Irish Soda Bread","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dutchhealthstore.com\/fr\/recipe-irish-soda-bread\/","og_locale":"fr_FR","og_type":"article","og_title":"(Recipe) Irish Soda Bread","og_url":"https:\/\/dutchhealthstore.com\/fr\/recipe-irish-soda-bread\/","og_site_name":"Dutch Health Store","article_publisher":"https:\/\/www.instagram.com\/dutchhealthstore\/","article_published_time":"2020-05-23T02:30:51+00:00","article_modified_time":"2022-02-07T09:18:39+00:00","og_image":[{"width":1390,"height":466,"url":"https:\/\/dutchhealthstore.com\/wp-content\/uploads\/2020\/05\/recipe-irish-soda-bread-dutch-health-store.jpg","type":"image\/jpeg"}],"author":"Melissa","twitter_card":"summary_large_image","twitter_creator":"@melissastruik@live.nl","twitter_misc":{"\u00c9crit par":"Melissa","Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/dutchhealthstore.com\/fr\/recipe-irish-soda-bread\/#article","isPartOf":{"@id":"https:\/\/dutchhealthstore.com\/fr\/recipe-irish-soda-bread\/"},"author":{"name":"Melissa","@id":"https:\/\/dutchhealthstore.com\/fr\/#\/schema\/person\/fc8338a651298850abd3add7442f50d7"},"headline":"(Recipe) Irish Soda Bread","datePublished":"2020-05-23T02:30:51+00:00","dateModified":"2022-02-07T09:18:39+00:00","mainEntityOfPage":{"@id":"https:\/\/dutchhealthstore.com\/fr\/recipe-irish-soda-bread\/"},"wordCount":292,"commentCount":0,"publisher":{"@id":"https:\/\/dutchhealthstore.com\/fr\/#organization"},"image":{"@id":"https:\/\/dutchhealthstore.com\/fr\/recipe-irish-soda-bread\/#primaryimage"},"thumbnailUrl":"https:\/\/dutchhealthstore.com\/wp-content\/uploads\/2020\/05\/recipe-irish-soda-bread-dutch-health-store.jpg","articleSection":["Recipes"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dutchhealthstore.com\/fr\/recipe-irish-soda-bread\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/dutchhealthstore.com\/fr\/recipe-irish-soda-bread\/","url":"https:\/\/dutchhealthstore.com\/fr\/recipe-irish-soda-bread\/","name":"(Recipe) Irish Soda Bread","isPartOf":{"@id":"https:\/\/dutchhealthstore.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dutchhealthstore.com\/fr\/recipe-irish-soda-bread\/#primaryimage"},"image":{"@id":"https:\/\/dutchhealthstore.com\/fr\/recipe-irish-soda-bread\/#primaryimage"},"thumbnailUrl":"https:\/\/dutchhealthstore.com\/wp-content\/uploads\/2020\/05\/recipe-irish-soda-bread-dutch-health-store.jpg","datePublished":"2020-05-23T02:30:51+00:00","dateModified":"2022-02-07T09:18:39+00:00","breadcrumb":{"@id":"https:\/\/dutchhealthstore.com\/fr\/recipe-irish-soda-bread\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dutchhealthstore.com\/fr\/recipe-irish-soda-bread\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dutchhealthstore.com\/fr\/recipe-irish-soda-bread\/#primaryimage","url":"https:\/\/dutchhealthstore.com\/wp-content\/uploads\/2020\/05\/recipe-irish-soda-bread-dutch-health-store.jpg","contentUrl":"https:\/\/dutchhealthstore.com\/wp-content\/uploads\/2020\/05\/recipe-irish-soda-bread-dutch-health-store.jpg","width":1390,"height":466},{"@type":"BreadcrumbList","@id":"https:\/\/dutchhealthstore.com\/fr\/recipe-irish-soda-bread\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/dutchhealthstore.com\/fr\/"},{"@type":"ListItem","position":2,"name":"(Recipe) Irish Soda Bread"}]},{"@type":"WebSite","@id":"https:\/\/dutchhealthstore.com\/fr\/#website","url":"https:\/\/dutchhealthstore.com\/fr\/","name":"Dutch Health Store","description":"Enhance Your Beauty with Organic &amp; Natural Skincare","publisher":{"@id":"https:\/\/dutchhealthstore.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dutchhealthstore.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/dutchhealthstore.com\/fr\/#organization","name":"Dutch Health Store","url":"https:\/\/dutchhealthstore.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dutchhealthstore.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/dutchhealthstore.com\/wp-content\/uploads\/2020\/08\/logo-dutchhealthstore-jpg-e1599484957574.jpg","contentUrl":"https:\/\/dutchhealthstore.com\/wp-content\/uploads\/2020\/08\/logo-dutchhealthstore-jpg-e1599484957574.jpg","width":400,"height":62,"caption":"Dutch Health Store"},"image":{"@id":"https:\/\/dutchhealthstore.com\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.instagram.com\/dutchhealthstore\/","https:\/\/www.facebook.com\/dutchhealthstore"]},{"@type":"Person","@id":"https:\/\/dutchhealthstore.com\/fr\/#\/schema\/person\/fc8338a651298850abd3add7442f50d7","name":"Melissa","sameAs":["https:\/\/x.com\/melissastruik@live.nl"],"url":"https:\/\/dutchhealthstore.com\/fr\/author\/melissa\/"}]}},"_links":{"self":[{"href":"https:\/\/dutchhealthstore.com\/fr\/wp-json\/wp\/v2\/posts\/102595","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dutchhealthstore.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dutchhealthstore.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dutchhealthstore.com\/fr\/wp-json\/wp\/v2\/users\/7912"}],"replies":[{"embeddable":true,"href":"https:\/\/dutchhealthstore.com\/fr\/wp-json\/wp\/v2\/comments?post=102595"}],"version-history":[{"count":0,"href":"https:\/\/dutchhealthstore.com\/fr\/wp-json\/wp\/v2\/posts\/102595\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dutchhealthstore.com\/fr\/wp-json\/wp\/v2\/media\/102601"}],"wp:attachment":[{"href":"https:\/\/dutchhealthstore.com\/fr\/wp-json\/wp\/v2\/media?parent=102595"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dutchhealthstore.com\/fr\/wp-json\/wp\/v2\/categories?post=102595"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dutchhealthstore.com\/fr\/wp-json\/wp\/v2\/tags?post=102595"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}