{"id":388096,"date":"2026-08-13T14:54:21","date_gmt":"2026-08-13T12:54:21","guid":{"rendered":"https:\/\/dutchhealthstore.com\/product\/pineapple-sugar-scrub-bar-brightening\/"},"modified":"2026-08-13T14:54:21","modified_gmt":"2026-08-13T12:54:21","slug":"pineapple-sugar-scrub-bar-brightening","status":"publish","type":"product","link":"https:\/\/dutchhealthstore.com\/de\/product\/pineapple-sugar-scrub-bar-brightening\/","title":{"rendered":"Pineapple Sugar Scrub Bar \u2013 Brightening"},"content":{"rendered":"<p>Kristallzucker und Longsheng-Reispuder polieren sanft abgestorbene Hautzellen weg, w\u00e4hrend Sheabutter, Reiskleie\u00f6l und Vitamin E die frische Haut darunter hydratisieren. Ein Bar, zwei Jobs. <\/p>\n<p>Hergestellt mit demselben Longsheng-Reiswasser, das sich durch Vioris gesamte Haarpflege-Linie zieht \u2013 es liefert die Vitamine B und E, Aminos\u00e4uren und Antioxidantien, um die Haut zu n\u00e4hren, w\u00e4hrend der Zucker das Peeling \u00fcbernimmt.<\/p>\n<p><strong>Duft:<\/strong> Leuchtend, tropische Ananas \u2013 s\u00fc\u00df und belebend.<\/p>\n<p><strong>So f\u00fchlt es sich an:<\/strong> Feine K\u00f6rnchen, die sich beim Peelen aufl\u00f6sen \u2013 nie kratzig oder hart. Nach dem Absp\u00fclen f\u00fchlt sich die Haut glatt, strahlend und hydratisiert an, ohne fettigen Film. <\/p>\n<p>Jeder Bar reicht f\u00fcr ca. 50+ Anwendungen \u2013 je nachdem, wie stark Sie pro Anwendung exfolieren.<\/p>\n<p><strong>Gr\u00f6\u00dfe: 4,23 oz \/ 120 g<\/strong><\/p>\n<p><strong><em>Sulfatfrei \u00b7 Parabenfrei \u00b7 Phthalatfrei \u00b7 Vegan \u00b7 Tierversuchsfrei \u00b7 Plastikfrei<\/em><\/strong><\/p>\n<h2><strong>Nat\u00fcrliche \/ biologische Inhaltsstoffe <\/strong><\/h2>\n<p>Sodium Cocoyl Isethionate, Behentrimonium Methosulfate, Zucker, Longsheng Reiswasser, Kakaobutter, Sodium Lactate, Glycerin, Duftstoffe*, Cetyl Alcohol, Sheabutter, Butylene Glycol (pflanzlich), Stearic Acid, Jojoba\u00f6l, Vitamin B8, Vitamin B5, Reiskleie\u00f6l, Hydrolysiertes Reisprotein, Brokkolisamen\u00f6l, Bambusextrakt, Vitamin E, Kurkuma Gelbpulver, Aloe Vera<\/p>\n<p>*Pflanzlich und nat\u00fcrlich vorkommend, saubere Inhaltsstoffe.<\/p>\n<p class=\"PDq2pG_selectionAnchorContainer\" data-start=\"66\" data-end=\"94\"><strong data-start=\"66\" data-end=\"94\">ERKL\u00c4RUNG DER INHALTSSTOFFE<\/strong><\/p>\n<ul data-start=\"96\" data-end=\"1022\" data-is-last-node=\"\" data-is-only-node=\"\">\n<li data-section-id=\"1ktsby4\" data-start=\"96\" data-end=\"147\"><strong data-start=\"98\" data-end=\"117\">Longsheng-Reis:<\/strong> Erneuert, repariert, verj\u00fcngt.<\/li>\n<li data-section-id=\"1y048h1\" data-start=\"148\" data-end=\"201\"><strong data-start=\"150\" data-end=\"167\">Kakaobutter:<\/strong> Macht geschmeidig, pflegt, spendet Feuchtigkeit.<\/li>\n<li data-section-id=\"xsdaxt\" data-start=\"202\" data-end=\"245\"><strong data-start=\"204\" data-end=\"220\">Sheabutter:<\/strong> Pflegt, spendet Feuchtigkeit.<\/li>\n<li data-section-id=\"rnnpbf\" data-start=\"246\" data-end=\"328\"><strong data-start=\"248\" data-end=\"292\">Reiskeim\u00f6l &#038; Hydrolysiertes Reisprotein:<\/strong> St\u00e4rkt, verleiht Volumen und Glanz.<\/li>\n<li data-section-id=\"pwg10w\" data-start=\"329\" data-end=\"403\"><strong data-start=\"331\" data-end=\"356\">Alaskische Gletschertonerde:<\/strong> Mineralstoffreiche Tonerde mit entgiftenden Eigenschaften.<\/li>\n<li data-section-id=\"1wehfbe\" data-start=\"404\" data-end=\"461\"><strong data-start=\"406\" data-end=\"420\">Aloe Vera:<\/strong> Erneuert, repariert, pflegt, verleiht Glanz.<\/li>\n<li data-section-id=\"1t8aa8x\" data-start=\"462\" data-end=\"516\"><strong data-start=\"464\" data-end=\"475\">Bambus:<\/strong> Erneuert, repariert, pflegt, verleiht Glanz.<\/li>\n<li data-section-id=\"sk430k\" data-start=\"517\" data-end=\"582\"><strong data-start=\"519\" data-end=\"549\">Natriumcocoylisethionat:<\/strong> Milder Reiniger auf Kokosnussbasis.<\/li>\n<li data-section-id=\"x08ll3\" data-start=\"583\" data-end=\"658\"><strong data-start=\"585\" data-end=\"617\">Behentrimoniummethosulfat:<\/strong> Sulfatfreie Sp\u00fclung auf pflanzlicher Basis.<\/li>\n<li data-section-id=\"bdz7ay\" data-start=\"659\" data-end=\"711\"><strong data-start=\"661\" data-end=\"687\">Kakaosamen- &#038; Kleie\u00f6l:<\/strong> N\u00e4hrt und hydratisiert.<\/li>\n<li data-section-id=\"1u2hs9u\" data-start=\"712\" data-end=\"761\"><strong data-start=\"714\" data-end=\"732\">Cetylalkohol:<\/strong> Fettalkohol auf pflanzlicher Basis.<\/li>\n<li data-section-id=\"1mlvy5a\" data-start=\"762\" data-end=\"807\"><strong data-start=\"764\" data-end=\"781\">Stearins\u00e4ure:<\/strong> Fetts\u00e4ure auf pflanzlicher Basis.<\/li>\n<li data-section-id=\"yznr39\" data-start=\"808\" data-end=\"886\"><strong data-start=\"810\" data-end=\"829\">Natriumlactat:<\/strong> Feuchtigkeitsspender aus fermentiertem Mais- und R\u00fcbenzucker.<\/li>\n<li data-section-id=\"yivxh5\" data-start=\"887\" data-end=\"953\"><strong data-start=\"889\" data-end=\"908\">Natriumpalmat:<\/strong> RSPO-zertifizierter Seifeninhaltsstoff auf Palm\u00f6lbasis.<\/li>\n<li data-section-id=\"vpti3i\" data-start=\"954\" data-end=\"1022\" data-is-last-node=\"\"><strong data-start=\"956\" data-end=\"975\">Natriumcocoat:<\/strong> Reinigender Seifeninhaltsstoff aus Kokos\u00f6l.<\/li>\n<\/ul>\n\n\t<section class=\"section\" id=\"section_524330405\">\n\t\t<div class=\"section-bg fill\" >\n\t\t\t\t\t\t\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n\n<div class=\"row\"  id=\"row-1873466674\">\n\n\n\t<div id=\"col-47777170\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n<h3><span style=\"font-size: 100%;\">Erfahren Sie mehr \u00fcber Viori<\/span><\/h3>\n<div class=\"is-divider divider clearfix\" style=\"max-width:3000px;height:1px;\"><\/div>\n\n<p>Im Jahr 2019 machten sich die Gr\u00fcnder von Viori auf den Weg in ein abgelegenes Dorf, das in den Reisterrassen-Bergen von Longsheng liegt. Dort stie\u00dfen sie auf den Stamm der Red Yao, eine Gemeinschaft, die diese Berge seit Jahrhunderten ihr Zuhause nennt. <\/p>\n<p>Etwas stach sofort ins Auge. Jede Frau im Dorf hatte auffallend langes, tiefschwarzes Haar, ohne eine einzige wei\u00dfe Str\u00e4hne, selbst bei Frauen, die bereits weit \u00fcber achtzig Jahre alt waren. Neugierig fragten sie die Frauen nach ihrem Geheimnis.  <\/p>\n<p>Eine der Frauen l\u00e4chelte und f\u00fchrte sie zu einer kleinen Holzh\u00fctte in der N\u00e4he. Drinnen stand auf dem Boden eine Sch\u00fcssel, die mit einer milchig-wei\u00dfen Fl\u00fcssigkeit gef\u00fcllt war. Sie begann zu erkl\u00e4ren. Von klein auf bereiteten die Frauen des Stammes den Reis nach der Ernte auf den Bergfeldern auf eine besondere Weise zu. Sie lie\u00dfen den Reis \u00fcber mehrere Tage fermentieren und verwendeten die daraus resultierende Fl\u00fcssigkeit, sobald sie fertig war, um ihr Haar zu waschen. Ein einfaches Ritual, das \u00fcber Generationen weitergegeben wurde und der Schl\u00fcssel zu ihrem bemerkenswerten Haar ist.     <\/p>\n<p>Dieser Moment wurde zum Fundament von Viori.<\/p>\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-458836991\" class=\"col medium-4 small-12 large-4\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_1139870215\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"400\" height=\"600\" src=\"https:\/\/dutchhealthstore.com\/wp-content\/uploads\/2026\/06\/ChatGPT_Image_Mar_18_2026_11_40.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/dutchhealthstore.com\/wp-content\/uploads\/2026\/06\/ChatGPT_Image_Mar_18_2026_11_40.jpg 400w, https:\/\/dutchhealthstore.com\/wp-content\/uploads\/2026\/06\/ChatGPT_Image_Mar_18_2026_11_40-267x400.jpg 267w, https:\/\/dutchhealthstore.com\/wp-content\/uploads\/2026\/06\/ChatGPT_Image_Mar_18_2026_11_40-33x50.jpg 33w, https:\/\/dutchhealthstore.com\/wp-content\/uploads\/2026\/06\/ChatGPT_Image_Mar_18_2026_11_40-64x96.jpg 64w\" sizes=\"(max-width: 400px) 100vw, 400px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_1139870215 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-399853865\" class=\"col medium-8 small-12 large-8\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n<div class=\"accordion\">\n\n\t<div id=\"accordion-968435841\" class=\"accordion-item\">\n\t\t<a id=\"accordion-968435841-label\" class=\"accordion-title plain\" href=\"#accordion-item-wie-verwende-ich-die-shampoo--und-conditioner-bars?\" aria-expanded=\"false\" aria-controls=\"accordion-968435841-content\">\n\t\t\t<button class=\"toggle\" aria-label=\"Umschalten\"><i class=\"icon-angle-down\" aria-hidden=\"true\"><\/i><\/button>\n\t\t\t<span>Wie verwende ich die Shampoo- und Conditioner-Bars?<\/span>\n\t\t<\/a>\n\t\t<div id=\"accordion-968435841-content\" class=\"accordion-inner\" aria-labelledby=\"accordion-968435841-label\">\n\t\t\t\n\n<p>Die erste Umstellung auf Shampoo- und Conditioner-Bars kann ein wenig gew\u00f6hnungsbed\u00fcrftig sein, aber sobald Sie sich daran gew\u00f6hnt haben, werden Sie sich fragen, wie Sie jemals etwas anderes verwenden konnten. Wir haben ein paar Videos zusammengestellt, um Sie durch alles Wissenswerte zu f\u00fchren: <\/p>\n<p><a href=\"https:\/\/www.youtube.com\/watch?v=ZC7rBBjs2p0\">Tutorial f\u00fcr Shampoo-Bars<\/a><\/p>\n<p><a href=\"https:\/\/youtu.be\/wAkPA2meS0g\">Tutorial f\u00fcr Conditioner-Bars<\/a><\/p>\n<p><a href=\"https:\/\/youtu.be\/ss6Fkzl8Lkg\">Tutorial f\u00fcr Bambushalter<\/a><\/p>\n\n\t\t<\/div>\n\t<\/div>\n\t\n\t<div id=\"accordion-1283185169\" class=\"accordion-item\">\n\t\t<a id=\"accordion-1283185169-label\" class=\"accordion-title plain\" href=\"#accordion-item-empfehlungen-f\u00fcr-die-reise\" aria-expanded=\"false\" aria-controls=\"accordion-1283185169-content\">\n\t\t\t<button class=\"toggle\" aria-label=\"Umschalten\"><i class=\"icon-angle-down\" aria-hidden=\"true\"><\/i><\/button>\n\t\t\t<span>Empfehlungen f\u00fcr die Reise<\/span>\n\t\t<\/a>\n\t\t<div id=\"accordion-1283185169-content\" class=\"accordion-inner\" aria-labelledby=\"accordion-1283185169-label\">\n\t\t\t\n\n<p>Das Reisen mit Ihren Bars ist einfacher, als Sie vielleicht denken. Hier sind ein paar einfache M\u00f6glichkeiten, sie unterwegs sicher aufzubewahren: <\/p>\n<ul>\n<li>Lassen Sie die Deckel auf Ihren Bambushaltern einrasten und wickeln Sie ein Haargummi, ein Gummiband oder ein St\u00fcck Schnur darum, damit alles an seinem Platz bleibt.<\/li>\n<li>Seifens\u00e4ckchen aus Netzgewebe funktionieren hervorragend; achten Sie nur darauf, sie in einer anderen Tasche oder einem Beh\u00e4lter zu verstauen, falls die Bars noch etwas feucht sind.<\/li>\n<li>Ein kleiner Glas- oder Tupperware-Beh\u00e4lter erf\u00fcllt den Zweck perfekt.<\/li>\n<li>Ein wiederverwendbarer Silikonbeutel ist eine leichte und umweltfreundliche Option.<\/li>\n<li>Ein Blechbeh\u00e4lter sch\u00fctzt sie und sorgt f\u00fcr ein ordentliches Aussehen in Ihrer Tasche.<\/li>\n<\/ul>\n\n\t\t<\/div>\n\t<\/div>\n\t\n\t<div id=\"accordion-3030687011\" class=\"accordion-item\">\n\t\t<a id=\"accordion-3030687011-label\" class=\"accordion-title plain\" href=\"#accordion-item-wirken-die-produkte-wie-die-verwendung-von-reiswasser?\" aria-expanded=\"false\" aria-controls=\"accordion-3030687011-content\">\n\t\t\t<button class=\"toggle\" aria-label=\"Umschalten\"><i class=\"icon-angle-down\" aria-hidden=\"true\"><\/i><\/button>\n\t\t\t<span>Wirken die Produkte wie die Verwendung von Reiswasser?<\/span>\n\t\t<\/a>\n\t\t<div id=\"accordion-3030687011-content\" class=\"accordion-inner\" aria-labelledby=\"accordion-3030687011-label\">\n\t\t\t\n\n<p class=\"font-claude-response-body break-words whitespace-normal\">Unsere Produkte enthalten eine sorgf\u00e4ltig abgestimmte Konzentration an Longsheng-Reiswasser. Die Verwendung von Reiswasser in zu hoher Konzentration oder zu h\u00e4ufig kann den nat\u00fcrlichen pH-Wert Ihres Haares und Ihrer Kopfhaut st\u00f6ren. Deshalb haben wir unsere Produkte unter Ber\u00fccksichtigung dieses Aspekts formuliert. In Kombination mit den anderen n\u00e4hrstoffreichen Inhaltsstoffen in jedem Bar erzielen Sie Ergebnisse, die mit einer speziellen Reiswasser-Sp\u00fclung vergleichbar sind, ohne das Risiko, das Gleichgewicht Ihrer Kopfhaut zu beeintr\u00e4chtigen.  <\/p>\n<p class=\"font-claude-response-body break-words whitespace-normal\">Unsere Produkte sind darauf ausgelegt, Feuchtigkeit zu spenden, zu st\u00e4rken, das Nachwachsen zu f\u00f6rdern, Volumen zu verleihen, den nat\u00fcrlichen Glanz zu steigern, Sch\u00e4den zu reparieren sowie Irritationen und Trockenheit der Kopfhaut zu reduzieren \u2013 und das alles in einer pH-neutralen Formel, die sanft genug f\u00fcr den t\u00e4glichen Gebrauch ist.<\/p>\n\n\t\t<\/div>\n\t<\/div>\n\t\n\t<div id=\"accordion-3696911653\" class=\"accordion-item\">\n\t\t<a id=\"accordion-3696911653-label\" class=\"accordion-title plain\" href=\"#accordion-item-was-sind-die-vorteile-von-longsheng-reiswasser?\" aria-expanded=\"false\" aria-controls=\"accordion-3696911653-content\">\n\t\t\t<button class=\"toggle\" aria-label=\"Umschalten\"><i class=\"icon-angle-down\" aria-hidden=\"true\"><\/i><\/button>\n\t\t\t<span>Was sind die Vorteile von Longsheng-Reiswasser?<\/span>\n\t\t<\/a>\n\t\t<div id=\"accordion-3696911653-content\" class=\"accordion-inner\" aria-labelledby=\"accordion-3696911653-label\">\n\t\t\t\n\n<p>Unabh\u00e4ngige Forschung hat gezeigt, dass Reisprotein das Haar gl\u00e4tten, den Glanz verst\u00e4rken, die Widerstandsf\u00e4higkeit erh\u00f6hen und ein l\u00e4ngeres Haarwachstum unterst\u00fctzen kann.<\/p>\n\n\t\t<\/div>\n\t<\/div>\n\t\n\t<div id=\"accordion-2497366284\" class=\"accordion-item\">\n\t\t<a id=\"accordion-2497366284-label\" class=\"accordion-title plain\" href=\"#accordion-item-hinterlassen-diese-r\u00fcckst\u00e4nde-oder-beschweren-sie-mein-haar?\" aria-expanded=\"false\" aria-controls=\"accordion-2497366284-content\">\n\t\t\t<button class=\"toggle\" aria-label=\"Umschalten\"><i class=\"icon-angle-down\" aria-hidden=\"true\"><\/i><\/button>\n\t\t\t<span>Hinterlassen diese R\u00fcckst\u00e4nde oder beschweren sie mein Haar?<\/span>\n\t\t<\/a>\n\t\t<div id=\"accordion-2497366284-content\" class=\"accordion-inner\" aria-labelledby=\"accordion-2497366284-label\">\n\t\t\t\n\n<p>Viele unserer Kunden sagen, dass eines ihrer Lieblingsdinge an unseren Bars das leichte Gef\u00fchl ist, ohne Schwere oder R\u00fcckst\u00e4nde nach dem Waschen.<\/p>\n\n\t\t<\/div>\n\t<\/div>\n\t\n\t<div id=\"accordion-1222249955\" class=\"accordion-item\">\n\t\t<a id=\"accordion-1222249955-label\" class=\"accordion-title plain\" href=\"#accordion-item-funktionieren-ihre-produkte-bei..\" aria-expanded=\"false\" aria-controls=\"accordion-1222249955-content\">\n\t\t\t<button class=\"toggle\" aria-label=\"Umschalten\"><i class=\"icon-angle-down\" aria-hidden=\"true\"><\/i><\/button>\n\t\t\t<span>Funktionieren Ihre Produkte bei..<\/span>\n\t\t<\/a>\n\t\t<div id=\"accordion-1222249955-content\" class=\"accordion-inner\" aria-labelledby=\"accordion-1222249955-label\">\n\t\t\t\n\n<p><strong>Farbbehandeltes Haar<\/strong><br\/>Alle unsere Produkte sind so formuliert, dass sie mit farbbehandeltem Haar kompatibel sind, und wir haben viel positives Feedback von Kunden erhalten, die sie im Rahmen ihrer Farbausbesserungs-Routine verwenden. Unsere Produkte sind parabenfrei und werden aus rein nat\u00fcrlichen Inhaltsstoffen hergestellt, wodurch sie mild und sanft zum Haar sind. <\/p>\n<p>Dennoch k\u00f6nnen die Ergebnisse je nach Art der verwendeten Farbe variieren. Toner, semi-permanente T\u00f6nungen und Drogerie-Colorationen enthalten oft Schwermetalle und Chemikalien, die unvorhersehbar mit anderen Produkten reagieren k\u00f6nnen. F\u00fcr beste Ergebnisse empfehlen wir die Verwendung einer permanenten Haarfarbe, da diese in die Schuppenschicht des Haares eindringt und sich dort fester verankert. Da festes Shampoo eine gewisse Reibung ben\u00f6tigt, um Schaum zu erzeugen, kann dies die Schuppenschicht leicht \u00f6ffnen, was dazu f\u00fchren kann, dass die Farbe verblasst, wenn sie nicht vollst\u00e4ndig eingedrungen ist. Um Ihre Farbe zu sch\u00fctzen, empfehlen wir, den Schaum zuerst in der Handfl\u00e4che zu erzeugen und ihn mit den H\u00e4nden aufzutragen, anstatt den Bar direkt auf dem Haar zu reiben. Wie bei jedem Haarpflegeprodukt erfolgt die Anwendung auf eigene Gefahr. Viori ist nicht verantwortlich f\u00fcr Farbver\u00e4nderungen oder unerw\u00fcnschte Ergebnisse bei farbbehandeltem Haar.      <\/p>\n<p><strong>Alle Haarfarben<\/strong><br\/>Unsere Produkte funktionieren gut bei allen Haarfarben, egal ob Sie hellblondes, rotes, braunes oder schwarzes Haar haben. Wir haben auch Kunden mit grauem oder wei\u00dfem Haar, die unsere Bars verwenden, um ihr Haar zu st\u00e4rken, zu n\u00e4hren und aufzuhellen, wobei einige sogar berichten, dass sie mit der Zeit weniger graue Haare haben. <\/p>\n<p><strong>Haartyp 3 und 4<\/strong><br\/>Wir hatten viele Kunden mit Haartyp 3 und Haartyp 4, die unsere Produkte ausprobiert haben und sie lieben. Bei allen Variationen dieser Haartypen haben wir bisher durchweg positive Ergebnisse gesehen. <\/p>\n<p><strong>Feines oder d\u00fcnnes Haar<\/strong><br\/>Alle unsere Produkte funktionieren gut bei feinem oder d\u00fcnnem Haar. Wenn Ihre Kopfhaut eher fettig ist, empfehlen wir Citrus Yao. Bei trockener Kopfhaut sind Hidden Waterfall, Terrace Garden oder Native Essence hervorragende Optionen.  <\/p>\n\n\t\t<\/div>\n\t<\/div>\n\t\n\n<\/div>\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n<\/div>\n\n\t\t<\/div>\n\n\t\t\n<style>\n#section_524330405 {\n  padding-top: 30px;\n  padding-bottom: 30px;\n}\n<\/style>\n\t<\/section>\n\t\n","protected":false},"excerpt":{"rendered":"<p>Ein Zuckerpeeling-Bar mit Reiswasser, der in einem Schritt exfoliert und Feuchtigkeit spendet \u2013 ganz ohne das \u00fcbliche Absp\u00fcl-Chaos.<\/p>\n","protected":false},"featured_media":386660,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[1032,1110,515,1210,1910,20907,21011,1048,511,6472,22645],"product_tag":[],"class_list":["post-388096","product","type-product","status-publish","has-post-thumbnail","product_cat-kategorien","product_cat-korperpeeling","product_cat-korperpflege-de","product_cat-marken","product_cat-neue-produkte","product_cat-new-additions-skincare-de","product_cat-peelings-peelingsalben","product_cat-kollektion","product_cat-produkte","product_cat-soaps-de-2","product_cat-viori","pa_brand-viori","pa_gtin-22884","pa_size-120-g-de","first","instock","taxable","shipping-taxable","purchasable","product-type-simple"],"bundled_by":[],"bundle_stock_status":"instock","bundle_stock_quantity":3,"bundle_virtual":false,"bundle_layout":"","bundle_add_to_cart_form_location":"","bundle_editable_in_cart":false,"bundle_sold_individually_context":"","bundle_item_grouping":"","bundle_min_size":"","bundle_max_size":"","bundle_price":[],"bundled_items":[],"bundle_sell_ids":[],"group_of_quantity":0,"min_quantity":0,"max_quantity":"","exclude_order_quantity_value_rules":"no","exclude_category_quantity_rules":"no","combine_variations":"no","yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.1 (Yoast SEO v28.1) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Pineapple Sugar Scrub Bar \u2013 Brightening - Voiri<\/title>\n<meta name=\"description\" content=\"Ein Zuckerpeeling-Bar mit Reiswasser, der in einem Schritt exfoliert und Feuchtigkeit spendet \u2013 ganz ohne das \u00fcbliche Absp\u00fcl-Chaos.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dutchhealthstore.com\/de\/product\/pineapple-sugar-scrub-bar-brightening\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Pineapple Sugar Scrub Bar \u2013 Brightening - Dutch Health Store\" \/>\n<meta property=\"og:description\" content=\"Ein Zuckerpeeling-Bar mit Reiswasser, der in einem Schritt exfoliert und Feuchtigkeit spendet \u2013 ganz ohne das \u00fcbliche Absp\u00fcl-Chaos.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dutchhealthstore.com\/de\/product\/pineapple-sugar-scrub-bar-brightening\/\" \/>\n<meta property=\"og:site_name\" content=\"Dutch Health Store\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.instagram.com\/dutchhealthstore\/\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dutchhealthstore.com\/wp-content\/uploads\/2026\/08\/Untitled-design-2026-08-05T113143.769.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"530\" \/>\n\t<meta property=\"og:image:height\" content=\"530\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Preis\" \/>\n\t<meta name=\"twitter:data1\" content=\"&euro;15,95\" \/>\n\t<meta name=\"twitter:label2\" content=\"Verf\u00fcgbarkeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"Auf Lager\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/dutchhealthstore.com\\\/de\\\/product\\\/pineapple-sugar-scrub-bar-brightening\\\/\",\"url\":\"https:\\\/\\\/dutchhealthstore.com\\\/de\\\/product\\\/pineapple-sugar-scrub-bar-brightening\\\/\",\"name\":\"Pineapple Sugar Scrub Bar \u2013 Brightening - Voiri\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dutchhealthstore.com\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/dutchhealthstore.com\\\/de\\\/product\\\/pineapple-sugar-scrub-bar-brightening\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/dutchhealthstore.com\\\/de\\\/product\\\/pineapple-sugar-scrub-bar-brightening\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dutchhealthstore.com\\\/wp-content\\\/uploads\\\/2026\\\/08\\\/Untitled-design-2026-08-05T113143.769.jpg\",\"datePublished\":\"2026-08-13T12:54:21+00:00\",\"description\":\"Ein Zuckerpeeling-Bar mit Reiswasser, der in einem Schritt exfoliert und Feuchtigkeit spendet \u2013 ganz ohne das \u00fcbliche Absp\u00fcl-Chaos.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/dutchhealthstore.com\\\/de\\\/product\\\/pineapple-sugar-scrub-bar-brightening\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/dutchhealthstore.com\\\/de\\\/product\\\/pineapple-sugar-scrub-bar-brightening\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/dutchhealthstore.com\\\/de\\\/product\\\/pineapple-sugar-scrub-bar-brightening\\\/#primaryimage\",\"url\":\"https:\\\/\\\/dutchhealthstore.com\\\/wp-content\\\/uploads\\\/2026\\\/08\\\/Untitled-design-2026-08-05T113143.769.jpg\",\"contentUrl\":\"https:\\\/\\\/dutchhealthstore.com\\\/wp-content\\\/uploads\\\/2026\\\/08\\\/Untitled-design-2026-08-05T113143.769.jpg\",\"width\":530,\"height\":530,\"caption\":\"viori-ananas-peeling\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/dutchhealthstore.com\\\/de\\\/product\\\/pineapple-sugar-scrub-bar-brightening\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/dutchhealthstore.com\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/dutchhealthstore.com\\\/de\\\/shop-2\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Pineapple Sugar Scrub Bar \u2013 Brightening\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/dutchhealthstore.com\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/dutchhealthstore.com\\\/de\\\/\",\"name\":\"Dutch Health Store\",\"description\":\"Enhance Your Beauty with Organic &amp; Natural Skincare\",\"publisher\":{\"@id\":\"https:\\\/\\\/dutchhealthstore.com\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/dutchhealthstore.com\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/dutchhealthstore.com\\\/de\\\/#organization\",\"name\":\"Dutch Health Store\",\"url\":\"https:\\\/\\\/dutchhealthstore.com\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/dutchhealthstore.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/dutchhealthstore.com\\\/wp-content\\\/uploads\\\/2020\\\/08\\\/logo-dutchhealthstore-jpg-e1599484957574.jpg\",\"contentUrl\":\"https:\\\/\\\/dutchhealthstore.com\\\/wp-content\\\/uploads\\\/2020\\\/08\\\/logo-dutchhealthstore-jpg-e1599484957574.jpg\",\"width\":400,\"height\":62,\"caption\":\"Dutch Health Store\"},\"image\":{\"@id\":\"https:\\\/\\\/dutchhealthstore.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.instagram.com\\\/dutchhealthstore\\\/\",\"https:\\\/\\\/www.facebook.com\\\/dutchhealthstore\"]}]}<\/script>\n<meta property=\"product:brand\" content=\"Viori\" \/>\n<meta property=\"product:price:amount\" content=\"15.95\" \/>\n<meta property=\"product:price:currency\" content=\"EUR\" \/>\n<meta property=\"og:availability\" content=\"instock\" \/>\n<meta property=\"product:availability\" content=\"instock\" \/>\n<meta property=\"product:retailer_item_id\" content=\"EB-PA-120W\" \/>\n<meta property=\"product:condition\" content=\"new\" \/>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Pineapple Sugar Scrub Bar \u2013 Brightening - Voiri","description":"Ein Zuckerpeeling-Bar mit Reiswasser, der in einem Schritt exfoliert und Feuchtigkeit spendet \u2013 ganz ohne das \u00fcbliche Absp\u00fcl-Chaos.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dutchhealthstore.com\/de\/product\/pineapple-sugar-scrub-bar-brightening\/","og_locale":"de_DE","og_type":"article","og_title":"Pineapple Sugar Scrub Bar \u2013 Brightening - Dutch Health Store","og_description":"Ein Zuckerpeeling-Bar mit Reiswasser, der in einem Schritt exfoliert und Feuchtigkeit spendet \u2013 ganz ohne das \u00fcbliche Absp\u00fcl-Chaos.","og_url":"https:\/\/dutchhealthstore.com\/de\/product\/pineapple-sugar-scrub-bar-brightening\/","og_site_name":"Dutch Health Store","article_publisher":"https:\/\/www.instagram.com\/dutchhealthstore\/","og_image":[{"width":530,"height":530,"url":"https:\/\/dutchhealthstore.com\/wp-content\/uploads\/2026\/08\/Untitled-design-2026-08-05T113143.769.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Preis":"&euro;15,95","Verf\u00fcgbarkeit":"Auf Lager"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/dutchhealthstore.com\/de\/product\/pineapple-sugar-scrub-bar-brightening\/","url":"https:\/\/dutchhealthstore.com\/de\/product\/pineapple-sugar-scrub-bar-brightening\/","name":"Pineapple Sugar Scrub Bar \u2013 Brightening - Voiri","isPartOf":{"@id":"https:\/\/dutchhealthstore.com\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dutchhealthstore.com\/de\/product\/pineapple-sugar-scrub-bar-brightening\/#primaryimage"},"image":{"@id":"https:\/\/dutchhealthstore.com\/de\/product\/pineapple-sugar-scrub-bar-brightening\/#primaryimage"},"thumbnailUrl":"https:\/\/dutchhealthstore.com\/wp-content\/uploads\/2026\/08\/Untitled-design-2026-08-05T113143.769.jpg","datePublished":"2026-08-13T12:54:21+00:00","description":"Ein Zuckerpeeling-Bar mit Reiswasser, der in einem Schritt exfoliert und Feuchtigkeit spendet \u2013 ganz ohne das \u00fcbliche Absp\u00fcl-Chaos.","breadcrumb":{"@id":"https:\/\/dutchhealthstore.com\/de\/product\/pineapple-sugar-scrub-bar-brightening\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dutchhealthstore.com\/de\/product\/pineapple-sugar-scrub-bar-brightening\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/dutchhealthstore.com\/de\/product\/pineapple-sugar-scrub-bar-brightening\/#primaryimage","url":"https:\/\/dutchhealthstore.com\/wp-content\/uploads\/2026\/08\/Untitled-design-2026-08-05T113143.769.jpg","contentUrl":"https:\/\/dutchhealthstore.com\/wp-content\/uploads\/2026\/08\/Untitled-design-2026-08-05T113143.769.jpg","width":530,"height":530,"caption":"viori-ananas-peeling"},{"@type":"BreadcrumbList","@id":"https:\/\/dutchhealthstore.com\/de\/product\/pineapple-sugar-scrub-bar-brightening\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/dutchhealthstore.com\/de\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/dutchhealthstore.com\/de\/shop-2\/"},{"@type":"ListItem","position":3,"name":"Pineapple Sugar Scrub Bar \u2013 Brightening"}]},{"@type":"WebSite","@id":"https:\/\/dutchhealthstore.com\/de\/#website","url":"https:\/\/dutchhealthstore.com\/de\/","name":"Dutch Health Store","description":"Enhance Your Beauty with Organic &amp; Natural Skincare","publisher":{"@id":"https:\/\/dutchhealthstore.com\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dutchhealthstore.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/dutchhealthstore.com\/de\/#organization","name":"Dutch Health Store","url":"https:\/\/dutchhealthstore.com\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/dutchhealthstore.com\/de\/#\/schema\/logo\/image\/","url":"https:\/\/dutchhealthstore.com\/wp-content\/uploads\/2020\/08\/logo-dutchhealthstore-jpg-e1599484957574.jpg","contentUrl":"https:\/\/dutchhealthstore.com\/wp-content\/uploads\/2020\/08\/logo-dutchhealthstore-jpg-e1599484957574.jpg","width":400,"height":62,"caption":"Dutch Health Store"},"image":{"@id":"https:\/\/dutchhealthstore.com\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.instagram.com\/dutchhealthstore\/","https:\/\/www.facebook.com\/dutchhealthstore"]}]},"product_brand":"Viori","product_price_amount":"15.95","product_price_currency":"EUR","og_availability":"instock","product_availability":"instock","product_retailer_item_id":"EB-PA-120W","product_condition":"new"},"_links":{"self":[{"href":"https:\/\/dutchhealthstore.com\/de\/wp-json\/wp\/v2\/product\/388096","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dutchhealthstore.com\/de\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/dutchhealthstore.com\/de\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/dutchhealthstore.com\/de\/wp-json\/wp\/v2\/comments?post=388096"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dutchhealthstore.com\/de\/wp-json\/wp\/v2\/media\/386660"}],"wp:attachment":[{"href":"https:\/\/dutchhealthstore.com\/de\/wp-json\/wp\/v2\/media?parent=388096"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/dutchhealthstore.com\/de\/wp-json\/wp\/v2\/product_brand?post=388096"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/dutchhealthstore.com\/de\/wp-json\/wp\/v2\/product_cat?post=388096"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/dutchhealthstore.com\/de\/wp-json\/wp\/v2\/product_tag?post=388096"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}