{"id":388093,"date":"2026-08-13T14:56:00","date_gmt":"2026-08-13T12:56:00","guid":{"rendered":"https:\/\/dutchhealthstore.com\/product\/limited-liliko%ca%bbi-lychee-sugar-scrub-bar\/"},"modified":"2026-08-15T13:56:37","modified_gmt":"2026-08-15T11:56:37","slug":"limited-liliko%ca%bbi-lychee-sugar-scrub-bar","status":"publish","type":"product","link":"https:\/\/dutchhealthstore.com\/de\/product\/limited-liliko%ca%bbi-lychee-sugar-scrub-bar\/","title":{"rendered":"LIMITED Liliko\u02bbi Lychee Sugar Scrub Bar"},"content":{"rendered":"<p>Feine Zuckerkristalle, pflegende \u00d6le und traditionelles Longsheng-Reiswasser entfernen Unebenheiten und mildern das Erscheinungsbild fahler, unebener Haut. Bei jeder Anwendung f\u00fchlt sich die Haut weicher, hydratisierter und sichtbar strahlender an. <\/p>\n<p>Inspiriert von Aloha \u02bb\u0100ina und mit Blick auf Nachhaltigkeit gefertigt: plastikfrei, verantwortungsvoll hergestellt und f\u00fcr den t\u00e4glichen Gebrauch konzipiert, ohne der Natur etwas abzuverlangen.<\/p>\n<p>Der Duft von Liliko\u02bbi Lychee ist s\u00fc\u00df und erfrischend \u2013 saftige Passionsfrucht und Litschi f\u00fcr ein helles, belebendes Finish. Jede Anwendung f\u00fchlt sich an wie ein Ausbruch von Inselenergie: frisch, verspielt, voller Leben. <\/p>\n<p>Einfach, effektiv und reisefreundlich bringt er einen Hauch der Inseln in Ihr t\u00e4gliches Ritual.<\/p>\n<p>F\u00fcr trockene, strukturierte Haut<\/p>\n<p><em>Peelend \u00b7 Erweichend \u00b7 Feuchtigkeitsspendend \u00b7 Tropischer Duft<\/em><\/p>\n<p><strong>Gr\u00f6\u00dfe: 4,23 oz \/ 120 g<\/strong><\/p>\n<h3>Wie benutzt man<\/h3>\n<p><a href=\"https:\/\/dutchhealthstore.com\/wp-content\/uploads\/2026\/08\/Untitled-design-2026-08-05T102932.801.jpg\"><img decoding=\"async\" class=\"alignnone size-full wp-image-386599\" src=\"https:\/\/dutchhealthstore.com\/wp-content\/uploads\/2026\/08\/Untitled-design-2026-08-05T102932.801.jpg\" alt=\"viori-liliko-lychee-peeling-anwendung\" width=\"200\" height=\"200\" srcset=\"https:\/\/dutchhealthstore.com\/wp-content\/uploads\/2026\/08\/Untitled-design-2026-08-05T102932.801.jpg 200w, https:\/\/dutchhealthstore.com\/wp-content\/uploads\/2026\/08\/Untitled-design-2026-08-05T102932.801-50x50.jpg 50w, https:\/\/dutchhealthstore.com\/wp-content\/uploads\/2026\/08\/Untitled-design-2026-08-05T102932.801-100x100.jpg 100w, https:\/\/dutchhealthstore.com\/wp-content\/uploads\/2026\/08\/Untitled-design-2026-08-05T102932.801-64x64.jpg 64w\" sizes=\"(max-width: 200px) 100vw, 200px\" \/><\/a><\/p>\n<h2><strong>Nat\u00fcrliche \/ biologische Inhaltsstoffe <\/strong><\/h2>\n<p>Sodium Cocoyl Isethionate, Behentrimonium Methosulfate, Zucker, Longsheng Reiswasser, Kakaobutter, Sodium Lactate, Glycerin, Duftstoffe*, Cetyl Alcohol, Sheabutter, Butylene Glycol (pflanzlich), Stearic Acid, Jojoba\u00f6l, Vitamin B8, Vitamin B5, Reiskleie\u00f6l, Hydrolysiertes Reisprotein, Brokkolisamen\u00f6l, Bambusextrakt, Vitamin E, Kurkuma Gelbpulver, Aloe Vera<\/p>\n<p>*Pflanzlich und nat\u00fcrlich vorkommend, saubere Inhaltsstoffe.<\/p>\n<h3 class=\"ff-heading fs-heading-5-base\">ERKL\u00c4RUNG DER INHALTSSTOFFE<\/h3>\n<div class=\"accordion__label-icons\"><\/div>\n<div id=\"accordion-content-accordion_9bHzDq\" class=\"accordion__content fs-body-100 rte non-page-rte measure\" aria-hidden=\"false\">\n<p><strong>Longsheng-Reis:<\/strong> erneuert, verj\u00fcngt, repariert.<\/p>\n<p><strong>Kakaobutter:<\/strong> pflegt, macht weich, spendet Feuchtigkeit.<\/p>\n<p><strong>Sheabutter:<\/strong> pflegt, spendet Feuchtigkeit.<\/p>\n<p><strong>Reiskleie\u00f6l &#038; Hydrolyzed Rice Protein: <\/strong>erh\u00f6ht Volumen und Glanz, st\u00e4rkt.<\/p>\n<p><strong>Alaskan Glacial Clay: <\/strong>Mineralreiche Erde mit entgiftenden Eigenschaften.<\/p>\n<p><strong>Aloe Vera:<\/strong> erneuert, verj\u00fcngt, repariert, pflegt, gl\u00e4ttet, erh\u00f6ht den Glanz.<\/p>\n<p><strong>Bambus: <\/strong>erneuert, verj\u00fcngt, repariert, pflegt, gl\u00e4ttet, erh\u00f6ht den Glanz.<\/p>\n<p><strong>Sodium Cocoyl Isethionate<\/strong>: ein nat\u00fcrliches Reinigungsmittel aus Kokosnuss.<\/p>\n<p><strong>Behentrimonium Methosulfate:<\/strong> ein sulfatfreier Conditioner aus pflanzlicher Quelle, gewonnen aus der Raps-Pflanze.<\/p>\n<p><strong>Cacao Seed &#038; Bran Oil:<\/strong> N\u00e4hrt und spendet der Haut Feuchtigkeit (&#038; dem Fell bei Haustieren).<\/p>\n<p><strong>Cetyl Alcohol:<\/strong> Fettalkohol aus pflanzlicher Quelle.<\/p>\n<p><strong>Stearic Acid:<\/strong> Fettalkohol aus pflanzlicher Quelle.<\/p>\n<p><strong>Sodium Lactate: <\/strong>gewonnen aus der nat\u00fcrlichen Fermentation von Zuckern aus Mais und R\u00fcben.<\/p>\n<p><strong>Sodium Palmate:<\/strong> das Natriumsalz der Palmitins\u00e4ure (RSPO).<\/p>\n<p><strong>Sodium Cocoate: <\/strong>eine Mischung aus Fetts\u00e4uresalzen (S\u00e4uresalzen) von Kokos\u00f6l, die in einigen Seifen verwendet wird.<\/p>\n<\/div>\n<p>&nbsp;<\/p>\n<p><em><strong>Sulfatfrei \u00b7 Parabenfrei \u00b7 Phthalatfrei \u00b7 Vegan \u00b7 Tierversuchsfrei \u00b7 Plastikfrei <\/strong><\/em><\/p>\n\n\t<section class=\"section\" id=\"section_1054927307\">\n\t\t<div class=\"section-bg fill\" >\n\t\t\t\t\t\t\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n\n<div class=\"row\"  id=\"row-1361058880\">\n\n\n\t<div id=\"col-1222200295\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n<h3><span style=\"font-size: 100%;\">Erfahren Sie mehr \u00fcber Viori<\/span><\/h3>\n<div class=\"is-divider divider clearfix\" style=\"max-width:3000px;height:1px;\"><\/div>\n\n<p>Im Jahr 2019 machten sich die Gr\u00fcnder von Viori auf den Weg in ein abgelegenes Dorf, das in den Reisterrassen-Bergen von Longsheng liegt. Dort stie\u00dfen sie auf den Stamm der Red Yao, eine Gemeinschaft, die diese Berge seit Jahrhunderten ihr Zuhause nennt. <\/p>\n<p>Etwas stach sofort ins Auge. Jede Frau im Dorf hatte auffallend langes, tiefschwarzes Haar, ohne eine einzige wei\u00dfe Str\u00e4hne, selbst bei Frauen, die bereits weit \u00fcber achtzig Jahre alt waren. Neugierig fragten sie die Frauen nach ihrem Geheimnis.  <\/p>\n<p>Eine der Frauen l\u00e4chelte und f\u00fchrte sie zu einer kleinen Holzh\u00fctte in der N\u00e4he. Drinnen stand auf dem Boden eine Sch\u00fcssel, die mit einer milchig-wei\u00dfen Fl\u00fcssigkeit gef\u00fcllt war. Sie begann zu erkl\u00e4ren. Von klein auf bereiteten die Frauen des Stammes den Reis nach der Ernte auf den Bergfeldern auf eine besondere Weise zu. Sie lie\u00dfen den Reis \u00fcber mehrere Tage fermentieren und verwendeten die daraus resultierende Fl\u00fcssigkeit, sobald sie fertig war, um ihr Haar zu waschen. Ein einfaches Ritual, das \u00fcber Generationen weitergegeben wurde und der Schl\u00fcssel zu ihrem bemerkenswerten Haar ist.     <\/p>\n<p>Dieser Moment wurde zum Fundament von Viori.<\/p>\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-1402122293\" class=\"col medium-4 small-12 large-4\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_251324697\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"400\" height=\"600\" src=\"https:\/\/dutchhealthstore.com\/wp-content\/uploads\/2026\/06\/ChatGPT_Image_Mar_18_2026_11_40.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/dutchhealthstore.com\/wp-content\/uploads\/2026\/06\/ChatGPT_Image_Mar_18_2026_11_40.jpg 400w, https:\/\/dutchhealthstore.com\/wp-content\/uploads\/2026\/06\/ChatGPT_Image_Mar_18_2026_11_40-267x400.jpg 267w, https:\/\/dutchhealthstore.com\/wp-content\/uploads\/2026\/06\/ChatGPT_Image_Mar_18_2026_11_40-33x50.jpg 33w, https:\/\/dutchhealthstore.com\/wp-content\/uploads\/2026\/06\/ChatGPT_Image_Mar_18_2026_11_40-64x96.jpg 64w\" sizes=\"(max-width: 400px) 100vw, 400px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_251324697 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-988629830\" class=\"col medium-8 small-12 large-8\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n<div class=\"accordion\">\n\n\t<div id=\"accordion-3577453461\" class=\"accordion-item\">\n\t\t<a id=\"accordion-3577453461-label\" class=\"accordion-title plain\" href=\"#accordion-item-wie-verwende-ich-die-shampoo--und-conditioner-bars?\" aria-expanded=\"false\" aria-controls=\"accordion-3577453461-content\">\n\t\t\t<button class=\"toggle\" aria-label=\"Umschalten\"><i class=\"icon-angle-down\" aria-hidden=\"true\"><\/i><\/button>\n\t\t\t<span>Wie verwende ich die Shampoo- und Conditioner-Bars?<\/span>\n\t\t<\/a>\n\t\t<div id=\"accordion-3577453461-content\" class=\"accordion-inner\" aria-labelledby=\"accordion-3577453461-label\">\n\t\t\t\n\n<p>Die erste Umstellung auf Shampoo- und Conditioner-Bars kann ein wenig gew\u00f6hnungsbed\u00fcrftig sein, aber sobald Sie sich daran gew\u00f6hnt haben, werden Sie sich fragen, wie Sie jemals etwas anderes verwenden konnten. Wir haben ein paar Videos zusammengestellt, um Sie durch alles Wissenswerte zu f\u00fchren: <\/p>\n<p><a href=\"https:\/\/www.youtube.com\/watch?v=ZC7rBBjs2p0\">Tutorial f\u00fcr Shampoo-Bars<\/a><\/p>\n<p><a href=\"https:\/\/youtu.be\/wAkPA2meS0g\">Tutorial f\u00fcr Conditioner-Bars<\/a><\/p>\n<p><a href=\"https:\/\/youtu.be\/ss6Fkzl8Lkg\">Tutorial f\u00fcr Bambushalter<\/a><\/p>\n\n\t\t<\/div>\n\t<\/div>\n\t\n\t<div id=\"accordion-1226580906\" class=\"accordion-item\">\n\t\t<a id=\"accordion-1226580906-label\" class=\"accordion-title plain\" href=\"#accordion-item-empfehlungen-f\u00fcr-die-reise\" aria-expanded=\"false\" aria-controls=\"accordion-1226580906-content\">\n\t\t\t<button class=\"toggle\" aria-label=\"Umschalten\"><i class=\"icon-angle-down\" aria-hidden=\"true\"><\/i><\/button>\n\t\t\t<span>Empfehlungen f\u00fcr die Reise<\/span>\n\t\t<\/a>\n\t\t<div id=\"accordion-1226580906-content\" class=\"accordion-inner\" aria-labelledby=\"accordion-1226580906-label\">\n\t\t\t\n\n<p>Das Reisen mit Ihren Bars ist einfacher, als Sie vielleicht denken. Hier sind ein paar einfache M\u00f6glichkeiten, sie unterwegs sicher aufzubewahren: <\/p>\n<ul>\n<li>Lassen Sie die Deckel auf Ihren Bambushaltern einrasten und wickeln Sie ein Haargummi, ein Gummiband oder ein St\u00fcck Schnur darum, damit alles an seinem Platz bleibt.<\/li>\n<li>Seifens\u00e4ckchen aus Netzgewebe funktionieren hervorragend; achten Sie nur darauf, sie in einer anderen Tasche oder einem Beh\u00e4lter zu verstauen, falls die Bars noch etwas feucht sind.<\/li>\n<li>Ein kleiner Glas- oder Tupperware-Beh\u00e4lter erf\u00fcllt den Zweck perfekt.<\/li>\n<li>Ein wiederverwendbarer Silikonbeutel ist eine leichte und umweltfreundliche Option.<\/li>\n<li>Ein Blechbeh\u00e4lter sch\u00fctzt sie und sorgt f\u00fcr ein ordentliches Aussehen in Ihrer Tasche.<\/li>\n<\/ul>\n\n\t\t<\/div>\n\t<\/div>\n\t\n\t<div id=\"accordion-1595490794\" class=\"accordion-item\">\n\t\t<a id=\"accordion-1595490794-label\" class=\"accordion-title plain\" href=\"#accordion-item-wirken-die-produkte-wie-die-verwendung-von-reiswasser?\" aria-expanded=\"false\" aria-controls=\"accordion-1595490794-content\">\n\t\t\t<button class=\"toggle\" aria-label=\"Umschalten\"><i class=\"icon-angle-down\" aria-hidden=\"true\"><\/i><\/button>\n\t\t\t<span>Wirken die Produkte wie die Verwendung von Reiswasser?<\/span>\n\t\t<\/a>\n\t\t<div id=\"accordion-1595490794-content\" class=\"accordion-inner\" aria-labelledby=\"accordion-1595490794-label\">\n\t\t\t\n\n<p class=\"font-claude-response-body break-words whitespace-normal\">Unsere Produkte enthalten eine sorgf\u00e4ltig abgestimmte Konzentration an Longsheng-Reiswasser. Die Verwendung von Reiswasser in zu hoher Konzentration oder zu h\u00e4ufig kann den nat\u00fcrlichen pH-Wert Ihres Haares und Ihrer Kopfhaut st\u00f6ren. Deshalb haben wir unsere Produkte unter Ber\u00fccksichtigung dieses Aspekts formuliert. In Kombination mit den anderen n\u00e4hrstoffreichen Inhaltsstoffen in jedem Bar erzielen Sie Ergebnisse, die mit einer speziellen Reiswasser-Sp\u00fclung vergleichbar sind, ohne das Risiko, das Gleichgewicht Ihrer Kopfhaut zu beeintr\u00e4chtigen.  <\/p>\n<p class=\"font-claude-response-body break-words whitespace-normal\">Unsere Produkte sind darauf ausgelegt, Feuchtigkeit zu spenden, zu st\u00e4rken, das Nachwachsen zu f\u00f6rdern, Volumen zu verleihen, den nat\u00fcrlichen Glanz zu steigern, Sch\u00e4den zu reparieren sowie Irritationen und Trockenheit der Kopfhaut zu reduzieren \u2013 und das alles in einer pH-neutralen Formel, die sanft genug f\u00fcr den t\u00e4glichen Gebrauch ist.<\/p>\n\n\t\t<\/div>\n\t<\/div>\n\t\n\t<div id=\"accordion-1212254281\" class=\"accordion-item\">\n\t\t<a id=\"accordion-1212254281-label\" class=\"accordion-title plain\" href=\"#accordion-item-was-sind-die-vorteile-von-longsheng-reiswasser?\" aria-expanded=\"false\" aria-controls=\"accordion-1212254281-content\">\n\t\t\t<button class=\"toggle\" aria-label=\"Umschalten\"><i class=\"icon-angle-down\" aria-hidden=\"true\"><\/i><\/button>\n\t\t\t<span>Was sind die Vorteile von Longsheng-Reiswasser?<\/span>\n\t\t<\/a>\n\t\t<div id=\"accordion-1212254281-content\" class=\"accordion-inner\" aria-labelledby=\"accordion-1212254281-label\">\n\t\t\t\n\n<p>Unabh\u00e4ngige Forschung hat gezeigt, dass Reisprotein das Haar gl\u00e4tten, den Glanz verst\u00e4rken, die Widerstandsf\u00e4higkeit erh\u00f6hen und ein l\u00e4ngeres Haarwachstum unterst\u00fctzen kann.<\/p>\n\n\t\t<\/div>\n\t<\/div>\n\t\n\t<div id=\"accordion-2704406140\" class=\"accordion-item\">\n\t\t<a id=\"accordion-2704406140-label\" class=\"accordion-title plain\" href=\"#accordion-item-hinterlassen-diese-r\u00fcckst\u00e4nde-oder-beschweren-sie-mein-haar?\" aria-expanded=\"false\" aria-controls=\"accordion-2704406140-content\">\n\t\t\t<button class=\"toggle\" aria-label=\"Umschalten\"><i class=\"icon-angle-down\" aria-hidden=\"true\"><\/i><\/button>\n\t\t\t<span>Hinterlassen diese R\u00fcckst\u00e4nde oder beschweren sie mein Haar?<\/span>\n\t\t<\/a>\n\t\t<div id=\"accordion-2704406140-content\" class=\"accordion-inner\" aria-labelledby=\"accordion-2704406140-label\">\n\t\t\t\n\n<p>Viele unserer Kunden sagen, dass eines ihrer Lieblingsdinge an unseren Bars das leichte Gef\u00fchl ist, ohne Schwere oder R\u00fcckst\u00e4nde nach dem Waschen.<\/p>\n\n\t\t<\/div>\n\t<\/div>\n\t\n\t<div id=\"accordion-1885827754\" class=\"accordion-item\">\n\t\t<a id=\"accordion-1885827754-label\" class=\"accordion-title plain\" href=\"#accordion-item-funktionieren-ihre-produkte-bei..\" aria-expanded=\"false\" aria-controls=\"accordion-1885827754-content\">\n\t\t\t<button class=\"toggle\" aria-label=\"Umschalten\"><i class=\"icon-angle-down\" aria-hidden=\"true\"><\/i><\/button>\n\t\t\t<span>Funktionieren Ihre Produkte bei..<\/span>\n\t\t<\/a>\n\t\t<div id=\"accordion-1885827754-content\" class=\"accordion-inner\" aria-labelledby=\"accordion-1885827754-label\">\n\t\t\t\n\n<p><strong>Farbbehandeltes Haar<\/strong><br\/>Alle unsere Produkte sind so formuliert, dass sie mit farbbehandeltem Haar kompatibel sind, und wir haben viel positives Feedback von Kunden erhalten, die sie im Rahmen ihrer Farbausbesserungs-Routine verwenden. Unsere Produkte sind parabenfrei und werden aus rein nat\u00fcrlichen Inhaltsstoffen hergestellt, wodurch sie mild und sanft zum Haar sind. <\/p>\n<p>Dennoch k\u00f6nnen die Ergebnisse je nach Art der verwendeten Farbe variieren. Toner, semi-permanente T\u00f6nungen und Drogerie-Colorationen enthalten oft Schwermetalle und Chemikalien, die unvorhersehbar mit anderen Produkten reagieren k\u00f6nnen. F\u00fcr beste Ergebnisse empfehlen wir die Verwendung einer permanenten Haarfarbe, da diese in die Schuppenschicht des Haares eindringt und sich dort fester verankert. Da festes Shampoo eine gewisse Reibung ben\u00f6tigt, um Schaum zu erzeugen, kann dies die Schuppenschicht leicht \u00f6ffnen, was dazu f\u00fchren kann, dass die Farbe verblasst, wenn sie nicht vollst\u00e4ndig eingedrungen ist. Um Ihre Farbe zu sch\u00fctzen, empfehlen wir, den Schaum zuerst in der Handfl\u00e4che zu erzeugen und ihn mit den H\u00e4nden aufzutragen, anstatt den Bar direkt auf dem Haar zu reiben. Wie bei jedem Haarpflegeprodukt erfolgt die Anwendung auf eigene Gefahr. Viori ist nicht verantwortlich f\u00fcr Farbver\u00e4nderungen oder unerw\u00fcnschte Ergebnisse bei farbbehandeltem Haar.      <\/p>\n<p><strong>Alle Haarfarben<\/strong><br\/>Unsere Produkte funktionieren gut bei allen Haarfarben, egal ob Sie hellblondes, rotes, braunes oder schwarzes Haar haben. Wir haben auch Kunden mit grauem oder wei\u00dfem Haar, die unsere Bars verwenden, um ihr Haar zu st\u00e4rken, zu n\u00e4hren und aufzuhellen, wobei einige sogar berichten, dass sie mit der Zeit weniger graue Haare haben. <\/p>\n<p><strong>Haartyp 3 und 4<\/strong><br\/>Wir hatten viele Kunden mit Haartyp 3 und Haartyp 4, die unsere Produkte ausprobiert haben und sie lieben. Bei allen Variationen dieser Haartypen haben wir bisher durchweg positive Ergebnisse gesehen. <\/p>\n<p><strong>Feines oder d\u00fcnnes Haar<\/strong><br\/>Alle unsere Produkte funktionieren gut bei feinem oder d\u00fcnnem Haar. Wenn Ihre Kopfhaut eher fettig ist, empfehlen wir Citrus Yao. Bei trockener Kopfhaut sind Hidden Waterfall, Terrace Garden oder Native Essence hervorragende Optionen.  <\/p>\n\n\t\t<\/div>\n\t<\/div>\n\t\n\n<\/div>\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n<\/div>\n\n\t\t<\/div>\n\n\t\t\n<style>\n#section_1054927307 {\n  padding-top: 30px;\n  padding-bottom: 30px;\n}\n<\/style>\n\t<\/section>\n\t\n","protected":false},"excerpt":{"rendered":"<p>Eine helle, tropische Peeling-Behandlung, entwickelt, um zu gl\u00e4tten, zu erfrischen und zu beleben.<\/p>\n","protected":false},"featured_media":386581,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[1032,1110,515,1210,1910,20907,21011,1048,511,6472,22645],"product_tag":[],"class_list":["post-388093","product","type-product","status-publish","has-post-thumbnail","product_cat-kategorien","product_cat-korperpeeling","product_cat-korperpflege-de","product_cat-marken","product_cat-neue-produkte","product_cat-new-additions-skincare-de","product_cat-peelings-peelingsalben","product_cat-kollektion","product_cat-produkte","product_cat-soaps-de-2","product_cat-viori","pa_brand-viori","pa_gtin-22881","pa_size-120-g-de","first","instock","taxable","shipping-taxable","purchasable","product-type-simple"],"bundled_by":[],"bundle_stock_status":"instock","bundle_stock_quantity":2,"bundle_virtual":false,"bundle_layout":"","bundle_add_to_cart_form_location":"","bundle_editable_in_cart":false,"bundle_sold_individually_context":"","bundle_item_grouping":"","bundle_min_size":"","bundle_max_size":"","bundle_price":[],"bundled_items":[],"bundle_sell_ids":[],"group_of_quantity":0,"min_quantity":0,"max_quantity":"","exclude_order_quantity_value_rules":"no","exclude_category_quantity_rules":"no","combine_variations":"no","yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.1 (Yoast SEO v28.1) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>LIMITED Liliko\u02bbi Lychee Sugar Scrub Bar - Viori<\/title>\n<meta name=\"description\" content=\"Eine helle, tropische Peeling-Behandlung, entwickelt, um zu gl\u00e4tten, zu erfrischen und zu beleben.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dutchhealthstore.com\/de\/product\/limited-liliko%ca%bbi-lychee-sugar-scrub-bar\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"LIMITED Liliko\u02bbi Lychee Sugar Scrub Bar - Dutch Health Store\" \/>\n<meta property=\"og:description\" content=\"Eine helle, tropische Peeling-Behandlung, entwickelt, um zu gl\u00e4tten, zu erfrischen und zu beleben.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dutchhealthstore.com\/de\/product\/limited-liliko%ca%bbi-lychee-sugar-scrub-bar\/\" \/>\n<meta property=\"og:site_name\" content=\"Dutch Health Store\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.instagram.com\/dutchhealthstore\/\" \/>\n<meta property=\"article:modified_time\" content=\"2026-08-15T11:56:37+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dutchhealthstore.com\/wp-content\/uploads\/2026\/08\/Untitled-design-2026-08-05T102337.730.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"530\" \/>\n\t<meta property=\"og:image:height\" content=\"530\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Preis\" \/>\n\t<meta name=\"twitter:data1\" content=\"&euro;15,95\" \/>\n\t<meta name=\"twitter:label2\" content=\"Verf\u00fcgbarkeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"Auf Lager\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/dutchhealthstore.com\\\/de\\\/product\\\/limited-liliko%ca%bbi-lychee-sugar-scrub-bar\\\/\",\"url\":\"https:\\\/\\\/dutchhealthstore.com\\\/de\\\/product\\\/limited-liliko%ca%bbi-lychee-sugar-scrub-bar\\\/\",\"name\":\"LIMITED Liliko\u02bbi Lychee Sugar Scrub Bar - Viori\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dutchhealthstore.com\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/dutchhealthstore.com\\\/de\\\/product\\\/limited-liliko%ca%bbi-lychee-sugar-scrub-bar\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/dutchhealthstore.com\\\/de\\\/product\\\/limited-liliko%ca%bbi-lychee-sugar-scrub-bar\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dutchhealthstore.com\\\/wp-content\\\/uploads\\\/2026\\\/08\\\/Untitled-design-2026-08-05T102337.730.jpg\",\"datePublished\":\"2026-08-13T12:56:00+00:00\",\"dateModified\":\"2026-08-15T11:56:37+00:00\",\"description\":\"Eine helle, tropische Peeling-Behandlung, entwickelt, um zu gl\u00e4tten, zu erfrischen und zu beleben.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/dutchhealthstore.com\\\/de\\\/product\\\/limited-liliko%ca%bbi-lychee-sugar-scrub-bar\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/dutchhealthstore.com\\\/de\\\/product\\\/limited-liliko%ca%bbi-lychee-sugar-scrub-bar\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/dutchhealthstore.com\\\/de\\\/product\\\/limited-liliko%ca%bbi-lychee-sugar-scrub-bar\\\/#primaryimage\",\"url\":\"https:\\\/\\\/dutchhealthstore.com\\\/wp-content\\\/uploads\\\/2026\\\/08\\\/Untitled-design-2026-08-05T102337.730.jpg\",\"contentUrl\":\"https:\\\/\\\/dutchhealthstore.com\\\/wp-content\\\/uploads\\\/2026\\\/08\\\/Untitled-design-2026-08-05T102337.730.jpg\",\"width\":530,\"height\":530,\"caption\":\"viori-liliko-lychee-peeling\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/dutchhealthstore.com\\\/de\\\/product\\\/limited-liliko%ca%bbi-lychee-sugar-scrub-bar\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/dutchhealthstore.com\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/dutchhealthstore.com\\\/de\\\/shop-2\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"LIMITED Liliko\u02bbi Lychee Sugar Scrub Bar\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/dutchhealthstore.com\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/dutchhealthstore.com\\\/de\\\/\",\"name\":\"Dutch Health Store\",\"description\":\"Enhance Your Beauty with Organic &amp; Natural Skincare\",\"publisher\":{\"@id\":\"https:\\\/\\\/dutchhealthstore.com\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/dutchhealthstore.com\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/dutchhealthstore.com\\\/de\\\/#organization\",\"name\":\"Dutch Health Store\",\"url\":\"https:\\\/\\\/dutchhealthstore.com\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/dutchhealthstore.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/dutchhealthstore.com\\\/wp-content\\\/uploads\\\/2020\\\/08\\\/logo-dutchhealthstore-jpg-e1599484957574.jpg\",\"contentUrl\":\"https:\\\/\\\/dutchhealthstore.com\\\/wp-content\\\/uploads\\\/2020\\\/08\\\/logo-dutchhealthstore-jpg-e1599484957574.jpg\",\"width\":400,\"height\":62,\"caption\":\"Dutch Health Store\"},\"image\":{\"@id\":\"https:\\\/\\\/dutchhealthstore.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.instagram.com\\\/dutchhealthstore\\\/\",\"https:\\\/\\\/www.facebook.com\\\/dutchhealthstore\"]}]}<\/script>\n<meta property=\"product:brand\" content=\"Viori\" \/>\n<meta property=\"product:price:amount\" content=\"15.95\" \/>\n<meta property=\"product:price:currency\" content=\"EUR\" \/>\n<meta property=\"og:availability\" content=\"instock\" \/>\n<meta property=\"product:availability\" content=\"instock\" \/>\n<meta property=\"product:retailer_item_id\" content=\"EB-LL-120W\" \/>\n<meta property=\"product:condition\" content=\"new\" \/>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"LIMITED Liliko\u02bbi Lychee Sugar Scrub Bar - Viori","description":"Eine helle, tropische Peeling-Behandlung, entwickelt, um zu gl\u00e4tten, zu erfrischen und zu beleben.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dutchhealthstore.com\/de\/product\/limited-liliko%ca%bbi-lychee-sugar-scrub-bar\/","og_locale":"de_DE","og_type":"article","og_title":"LIMITED Liliko\u02bbi Lychee Sugar Scrub Bar - Dutch Health Store","og_description":"Eine helle, tropische Peeling-Behandlung, entwickelt, um zu gl\u00e4tten, zu erfrischen und zu beleben.","og_url":"https:\/\/dutchhealthstore.com\/de\/product\/limited-liliko%ca%bbi-lychee-sugar-scrub-bar\/","og_site_name":"Dutch Health Store","article_publisher":"https:\/\/www.instagram.com\/dutchhealthstore\/","article_modified_time":"2026-08-15T11:56:37+00:00","og_image":[{"width":530,"height":530,"url":"https:\/\/dutchhealthstore.com\/wp-content\/uploads\/2026\/08\/Untitled-design-2026-08-05T102337.730.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Preis":"&euro;15,95","Verf\u00fcgbarkeit":"Auf Lager"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/dutchhealthstore.com\/de\/product\/limited-liliko%ca%bbi-lychee-sugar-scrub-bar\/","url":"https:\/\/dutchhealthstore.com\/de\/product\/limited-liliko%ca%bbi-lychee-sugar-scrub-bar\/","name":"LIMITED Liliko\u02bbi Lychee Sugar Scrub Bar - Viori","isPartOf":{"@id":"https:\/\/dutchhealthstore.com\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dutchhealthstore.com\/de\/product\/limited-liliko%ca%bbi-lychee-sugar-scrub-bar\/#primaryimage"},"image":{"@id":"https:\/\/dutchhealthstore.com\/de\/product\/limited-liliko%ca%bbi-lychee-sugar-scrub-bar\/#primaryimage"},"thumbnailUrl":"https:\/\/dutchhealthstore.com\/wp-content\/uploads\/2026\/08\/Untitled-design-2026-08-05T102337.730.jpg","datePublished":"2026-08-13T12:56:00+00:00","dateModified":"2026-08-15T11:56:37+00:00","description":"Eine helle, tropische Peeling-Behandlung, entwickelt, um zu gl\u00e4tten, zu erfrischen und zu beleben.","breadcrumb":{"@id":"https:\/\/dutchhealthstore.com\/de\/product\/limited-liliko%ca%bbi-lychee-sugar-scrub-bar\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dutchhealthstore.com\/de\/product\/limited-liliko%ca%bbi-lychee-sugar-scrub-bar\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/dutchhealthstore.com\/de\/product\/limited-liliko%ca%bbi-lychee-sugar-scrub-bar\/#primaryimage","url":"https:\/\/dutchhealthstore.com\/wp-content\/uploads\/2026\/08\/Untitled-design-2026-08-05T102337.730.jpg","contentUrl":"https:\/\/dutchhealthstore.com\/wp-content\/uploads\/2026\/08\/Untitled-design-2026-08-05T102337.730.jpg","width":530,"height":530,"caption":"viori-liliko-lychee-peeling"},{"@type":"BreadcrumbList","@id":"https:\/\/dutchhealthstore.com\/de\/product\/limited-liliko%ca%bbi-lychee-sugar-scrub-bar\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/dutchhealthstore.com\/de\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/dutchhealthstore.com\/de\/shop-2\/"},{"@type":"ListItem","position":3,"name":"LIMITED Liliko\u02bbi Lychee Sugar Scrub Bar"}]},{"@type":"WebSite","@id":"https:\/\/dutchhealthstore.com\/de\/#website","url":"https:\/\/dutchhealthstore.com\/de\/","name":"Dutch Health Store","description":"Enhance Your Beauty with Organic &amp; Natural Skincare","publisher":{"@id":"https:\/\/dutchhealthstore.com\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dutchhealthstore.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/dutchhealthstore.com\/de\/#organization","name":"Dutch Health Store","url":"https:\/\/dutchhealthstore.com\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/dutchhealthstore.com\/de\/#\/schema\/logo\/image\/","url":"https:\/\/dutchhealthstore.com\/wp-content\/uploads\/2020\/08\/logo-dutchhealthstore-jpg-e1599484957574.jpg","contentUrl":"https:\/\/dutchhealthstore.com\/wp-content\/uploads\/2020\/08\/logo-dutchhealthstore-jpg-e1599484957574.jpg","width":400,"height":62,"caption":"Dutch Health Store"},"image":{"@id":"https:\/\/dutchhealthstore.com\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.instagram.com\/dutchhealthstore\/","https:\/\/www.facebook.com\/dutchhealthstore"]}]},"product_brand":"Viori","product_price_amount":"15.95","product_price_currency":"EUR","og_availability":"instock","product_availability":"instock","product_retailer_item_id":"EB-LL-120W","product_condition":"new"},"_links":{"self":[{"href":"https:\/\/dutchhealthstore.com\/de\/wp-json\/wp\/v2\/product\/388093","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dutchhealthstore.com\/de\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/dutchhealthstore.com\/de\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/dutchhealthstore.com\/de\/wp-json\/wp\/v2\/comments?post=388093"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dutchhealthstore.com\/de\/wp-json\/wp\/v2\/media\/386581"}],"wp:attachment":[{"href":"https:\/\/dutchhealthstore.com\/de\/wp-json\/wp\/v2\/media?parent=388093"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/dutchhealthstore.com\/de\/wp-json\/wp\/v2\/product_brand?post=388093"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/dutchhealthstore.com\/de\/wp-json\/wp\/v2\/product_cat?post=388093"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/dutchhealthstore.com\/de\/wp-json\/wp\/v2\/product_tag?post=388093"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}